{"id":108722,"date":"2026-05-12T01:47:51","date_gmt":"2026-05-11T23:47:51","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/gastgeber\/gasthof-buschmann-2\/"},"modified":"2026-05-12T01:47:51","modified_gmt":"2026-05-11T23:47:51","slug":"gasthof-buschmann-2","status":"publish","type":"host","link":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/gasthof-buschmann-2\/","title":{"rendered":"Gasthof Buschmann"},"content":{"rendered":"<p>Der Gasthof Buschmann, seit 1868 in Familienbesitz, liegt am idyllischen Ortsrand von Hamminkeln-Ringenberg und stellt mit seiner Historie und zugleich modernen Ausstattung ein attraktives Ziel f\u00fcr Reisende und Erholungssuchende dar. Das Haus bietet komfortable Zimmer, ideal f\u00fcr Gesch\u00e4ftsreisen oder Wochenendtrips. Besonders hervorzuheben sind die verschiedenen Gastr\u00e4ume wie die Alte Dorfgastst\u00e4tte, das Bistro-Restaurant und der gro\u00dfz\u00fcgige Festsaal, die perfekte Rahmenbedingungen f\u00fcr Veranstaltungen jeder Art bieten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Gasthof Buschmann, seit 1868 in Familienbesitz, liegt am idyllischen Ortsrand von Hamminkeln-Ringenberg und stellt mit seiner Historie und zugleich modernen Ausstattung ein attraktives Ziel f\u00fcr Reisende und Erholungssuchende dar. Das Haus bietet komfortable Zimmer, ideal f\u00fcr Gesch\u00e4ftsreisen oder Wochenendtrips. Besonders hervorzuheben sind die verschiedenen Gastr\u00e4ume wie die Alte Dorfgastst\u00e4tte, das Bistro-Restaurant und der gro\u00dfz\u00fcgige [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":103769,"template":"","accommodation_types":[134],"class_list":["post-108722","host","type-host","status-publish","has-post-thumbnail","hentry","accommodation_type-gasthof"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gasthof Buschmann - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/gasthof-buschmann-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gasthof Buschmann - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Der Gasthof Buschmann, seit 1868 in Familienbesitz, liegt am idyllischen Ortsrand von Hamminkeln-Ringenberg und stellt mit seiner Historie und zugleich modernen Ausstattung ein attraktives Ziel f\u00fcr Reisende und Erholungssuchende dar. Das Haus bietet komfortable Zimmer, ideal f\u00fcr Gesch\u00e4ftsreisen oder Wochenendtrips. Besonders hervorzuheben sind die verschiedenen Gastr\u00e4ume wie die Alte Dorfgastst\u00e4tte, das Bistro-Restaurant und der gro\u00dfz\u00fcgige [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/03\/gasthof-buschmann.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/gasthof-buschmann-2\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/gasthof-buschmann-2\/\",\"name\":\"Gasthof Buschmann - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-05-11T23:47:51+00:00\",\"dateModified\":\"2026-05-11T23:47:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/gasthof-buschmann-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/gasthof-buschmann-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/gasthof-buschmann-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gastgeber\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gasthof Buschmann\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gasthof Buschmann - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/gasthof-buschmann-2\/","og_locale":"en_US","og_type":"article","og_title":"Gasthof Buschmann - Stadt. Land. Niederrhein","og_description":"Der Gasthof Buschmann, seit 1868 in Familienbesitz, liegt am idyllischen Ortsrand von Hamminkeln-Ringenberg und stellt mit seiner Historie und zugleich modernen Ausstattung ein attraktives Ziel f\u00fcr Reisende und Erholungssuchende dar. Das Haus bietet komfortable Zimmer, ideal f\u00fcr Gesch\u00e4ftsreisen oder Wochenendtrips. Besonders hervorzuheben sind die verschiedenen Gastr\u00e4ume wie die Alte Dorfgastst\u00e4tte, das Bistro-Restaurant und der gro\u00dfz\u00fcgige [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":960,"height":720,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/03\/gasthof-buschmann.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/gasthof-buschmann-2\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/gasthof-buschmann-2\/","name":"Gasthof Buschmann - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-05-11T23:47:51+00:00","dateModified":"2026-05-11T23:47:51+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/gasthof-buschmann-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/gasthof-buschmann-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/gasthof-buschmann-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Gastgeber","item":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/"},{"@type":"ListItem","position":3,"name":"Gasthof Buschmann"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/108722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/host"}],"version-history":[{"count":2,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/108722\/revisions"}],"predecessor-version":[{"id":123719,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/108722\/revisions\/123719"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/103769"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=108722"}],"wp:term":[{"taxonomy":"accommodation_type","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/accommodation_types?post=108722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}