{"id":108733,"date":"2026-05-12T01:47:58","date_gmt":"2026-05-11T23:47:58","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/gastgeber\/ferienwohnung-krummensteg-2\/"},"modified":"2026-05-12T01:47:58","modified_gmt":"2026-05-11T23:47:58","slug":"ferienwohnung-krummensteg-2","status":"publish","type":"host","link":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-krummensteg-2\/","title":{"rendered":"Ferienwohnung Krummensteg"},"content":{"rendered":"<p>Die Ferienwohnung Krummensteg bietet auf 85 m\u00b2 im ersten Obergeschoss komfortablen Raum f\u00fcr bis zu vier Personen. \u00dcber eine Au\u00dfen-Wendeltreppe gelangt man zur gro\u00dfz\u00fcgigen S\u00fcd-Dachterrasse, die im Sommer Sonnenstunden verspricht. Ein separates Schlafzimmer mit flexibler Anordnung von Boxspringbetten sowie eine Galerie mit weiteren Betten sorgen f\u00fcr erholsamen Schlaf. Das Tageslichtbad ist modern ausgestattet und die voll ausgestattete K\u00fcche l\u00e4dt zum Kochen ein. Im Wohnzimmer bieten Schlafsofas und ein moderner Entertainment-Bereich Raum zur Entspannung. Haustiere sind nach Absprache willkommen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Ferienwohnung Krummensteg bietet auf 85 m\u00b2 im ersten Obergeschoss komfortablen Raum f\u00fcr bis zu vier Personen. \u00dcber eine Au\u00dfen-Wendeltreppe gelangt man zur gro\u00dfz\u00fcgigen S\u00fcd-Dachterrasse, die im Sommer Sonnenstunden verspricht. Ein separates Schlafzimmer mit flexibler Anordnung von Boxspringbetten sowie eine Galerie mit weiteren Betten sorgen f\u00fcr erholsamen Schlaf. Das Tageslichtbad ist modern ausgestattet und die [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":103551,"template":"","accommodation_types":[138],"class_list":["post-108733","host","type-host","status-publish","has-post-thumbnail","hentry","accommodation_type-ferienwohnung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ferienwohnung Krummensteg - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-krummensteg-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferienwohnung Krummensteg - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Die Ferienwohnung Krummensteg bietet auf 85 m\u00b2 im ersten Obergeschoss komfortablen Raum f\u00fcr bis zu vier Personen. \u00dcber eine Au\u00dfen-Wendeltreppe gelangt man zur gro\u00dfz\u00fcgigen S\u00fcd-Dachterrasse, die im Sommer Sonnenstunden verspricht. Ein separates Schlafzimmer mit flexibler Anordnung von Boxspringbetten sowie eine Galerie mit weiteren Betten sorgen f\u00fcr erholsamen Schlaf. Das Tageslichtbad ist modern ausgestattet und die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/03\/wohnbereich.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-krummensteg-2\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-krummensteg-2\/\",\"name\":\"Ferienwohnung Krummensteg - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-05-11T23:47:58+00:00\",\"dateModified\":\"2026-05-11T23:47:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-krummensteg-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-krummensteg-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-krummensteg-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gastgeber\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ferienwohnung Krummensteg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ferienwohnung Krummensteg - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-krummensteg-2\/","og_locale":"en_US","og_type":"article","og_title":"Ferienwohnung Krummensteg - Stadt. Land. Niederrhein","og_description":"Die Ferienwohnung Krummensteg bietet auf 85 m\u00b2 im ersten Obergeschoss komfortablen Raum f\u00fcr bis zu vier Personen. \u00dcber eine Au\u00dfen-Wendeltreppe gelangt man zur gro\u00dfz\u00fcgigen S\u00fcd-Dachterrasse, die im Sommer Sonnenstunden verspricht. Ein separates Schlafzimmer mit flexibler Anordnung von Boxspringbetten sowie eine Galerie mit weiteren Betten sorgen f\u00fcr erholsamen Schlaf. Das Tageslichtbad ist modern ausgestattet und die [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2048,"height":1536,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/03\/wohnbereich.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-krummensteg-2\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-krummensteg-2\/","name":"Ferienwohnung Krummensteg - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-05-11T23:47:58+00:00","dateModified":"2026-05-11T23:47:58+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-krummensteg-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-krummensteg-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-krummensteg-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Gastgeber","item":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/"},{"@type":"ListItem","position":3,"name":"Ferienwohnung Krummensteg"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/108733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/host"}],"version-history":[{"count":2,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/108733\/revisions"}],"predecessor-version":[{"id":123728,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/108733\/revisions\/123728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/103551"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=108733"}],"wp:term":[{"taxonomy":"accommodation_type","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/accommodation_types?post=108733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}