{"id":124608,"date":"2026-05-12T01:49:40","date_gmt":"2026-05-11T23:49:40","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/gastgeber\/ferienwohnungen-gaestehaus-bauernhof-ermen-2\/"},"modified":"2026-05-12T01:49:40","modified_gmt":"2026-05-11T23:49:40","slug":"ferienwohnungen-gaestehaus-bauernhof-ermen-2","status":"publish","type":"host","link":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnungen-gaestehaus-bauernhof-ermen-2\/","title":{"rendered":"Ferienwohnungen &#8220;G\u00e4stehaus Bauernhof Ermen&#8221;"},"content":{"rendered":"<p>Der ehemalige Bauernhof befindet sich in idyllischer l\u00e4ndlicher Lage und bietet eine bequeme Verkehrsanbindung. Die Ferienwohnungen sind modern ausgestattet und erm\u00f6glichen dank voll ausgestatteter K\u00fcchen ein hohes Ma\u00df an Unabh\u00e4ngigkeit. Besonders hervorzuheben sind die zwei Maisonettewohnungen, die \u00fcber jeweils zwei Etagen, zwei Schlafzimmer und Balkone verf\u00fcgen und Platz f\u00fcr bis zu vier Personen bieten. Ein reichhaltiges Fr\u00fchst\u00fcck kann optional bestellt werden und Leihfahrr\u00e4der stehen bereit. Die Umgebung lockt mit zahlreichen Aktivit\u00e4ten und Sehensw\u00fcrdigkeiten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der ehemalige Bauernhof befindet sich in idyllischer l\u00e4ndlicher Lage und bietet eine bequeme Verkehrsanbindung. Die Ferienwohnungen sind modern ausgestattet und erm\u00f6glichen dank voll ausgestatteter K\u00fcchen ein hohes Ma\u00df an Unabh\u00e4ngigkeit. Besonders hervorzuheben sind die zwei Maisonettewohnungen, die \u00fcber jeweils zwei Etagen, zwei Schlafzimmer und Balkone verf\u00fcgen und Platz f\u00fcr bis zu vier Personen bieten. Ein [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":103957,"template":"","accommodation_types":[138],"class_list":["post-124608","host","type-host","status-publish","has-post-thumbnail","hentry","accommodation_type-ferienwohnung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ferienwohnungen &quot;G\u00e4stehaus Bauernhof Ermen&quot; - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnungen-gaestehaus-bauernhof-ermen-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferienwohnungen &quot;G\u00e4stehaus Bauernhof Ermen&quot; - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Der ehemalige Bauernhof befindet sich in idyllischer l\u00e4ndlicher Lage und bietet eine bequeme Verkehrsanbindung. Die Ferienwohnungen sind modern ausgestattet und erm\u00f6glichen dank voll ausgestatteter K\u00fcchen ein hohes Ma\u00df an Unabh\u00e4ngigkeit. Besonders hervorzuheben sind die zwei Maisonettewohnungen, die \u00fcber jeweils zwei Etagen, zwei Schlafzimmer und Balkone verf\u00fcgen und Platz f\u00fcr bis zu vier Personen bieten. Ein [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/03\/ferienwohnungen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnungen-gaestehaus-bauernhof-ermen-2\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnungen-gaestehaus-bauernhof-ermen-2\/\",\"name\":\"Ferienwohnungen \\\"G\u00e4stehaus Bauernhof Ermen\\\" - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-05-11T23:49:40+00:00\",\"dateModified\":\"2026-05-11T23:49:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnungen-gaestehaus-bauernhof-ermen-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnungen-gaestehaus-bauernhof-ermen-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnungen-gaestehaus-bauernhof-ermen-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gastgeber\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ferienwohnungen \\\"G\u00e4stehaus Bauernhof Ermen\\\"\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ferienwohnungen \"G\u00e4stehaus Bauernhof Ermen\" - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnungen-gaestehaus-bauernhof-ermen-2\/","og_locale":"en_US","og_type":"article","og_title":"Ferienwohnungen \"G\u00e4stehaus Bauernhof Ermen\" - Stadt. Land. Niederrhein","og_description":"Der ehemalige Bauernhof befindet sich in idyllischer l\u00e4ndlicher Lage und bietet eine bequeme Verkehrsanbindung. Die Ferienwohnungen sind modern ausgestattet und erm\u00f6glichen dank voll ausgestatteter K\u00fcchen ein hohes Ma\u00df an Unabh\u00e4ngigkeit. Besonders hervorzuheben sind die zwei Maisonettewohnungen, die \u00fcber jeweils zwei Etagen, zwei Schlafzimmer und Balkone verf\u00fcgen und Platz f\u00fcr bis zu vier Personen bieten. Ein [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":1024,"height":683,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/03\/ferienwohnungen.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnungen-gaestehaus-bauernhof-ermen-2\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnungen-gaestehaus-bauernhof-ermen-2\/","name":"Ferienwohnungen \"G\u00e4stehaus Bauernhof Ermen\" - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-05-11T23:49:40+00:00","dateModified":"2026-05-11T23:49:40+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnungen-gaestehaus-bauernhof-ermen-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnungen-gaestehaus-bauernhof-ermen-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnungen-gaestehaus-bauernhof-ermen-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Gastgeber","item":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/"},{"@type":"ListItem","position":3,"name":"Ferienwohnungen \"G\u00e4stehaus Bauernhof Ermen\""}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/124608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/host"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/124608\/revisions"}],"predecessor-version":[{"id":124701,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/124608\/revisions\/124701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/103957"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=124608"}],"wp:term":[{"taxonomy":"accommodation_type","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/accommodation_types?post=124608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}