{"id":125619,"date":"2026-05-12T01:57:39","date_gmt":"2026-05-11T23:57:39","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/gastgeber\/ferienwohnung-grothoff\/"},"modified":"2026-05-12T01:57:39","modified_gmt":"2026-05-11T23:57:39","slug":"ferienwohnung-grothoff","status":"publish","type":"host","link":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-grothoff\/","title":{"rendered":"Ferienwohnung Grothoff"},"content":{"rendered":"<p>Ferienwohnung Grothoff bietet zwei charmante Appartements, ideal f\u00fcr erholsame Aufenthalte in Wachtendonk. Mit jeweils rund 35 Quadratmetern erstreckt sich Appartement 1 im Dachgeschoss und Appartement 2 im ersten Obergeschoss. Beide Einheiten vermitteln ein Gef\u00fchl von Komfort und Privatsph\u00e4re, umgeben von der ruhigen Atmosph\u00e4re des niederrheinischen Landkreises Kleve. In dieser l\u00e4ndlichen Idylle bietet die Ferienwohnung Grothoff einen idealen R\u00fcckzugsort f\u00fcr alle, die eine erholsame Auszeit suchen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ferienwohnung Grothoff bietet zwei charmante Appartements, ideal f\u00fcr erholsame Aufenthalte in Wachtendonk. Mit jeweils rund 35 Quadratmetern erstreckt sich Appartement 1 im Dachgeschoss und Appartement 2 im ersten Obergeschoss. Beide Einheiten vermitteln ein Gef\u00fchl von Komfort und Privatsph\u00e4re, umgeben von der ruhigen Atmosph\u00e4re des niederrheinischen Landkreises Kleve. In dieser l\u00e4ndlichen Idylle bietet die Ferienwohnung Grothoff [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":127340,"template":"","accommodation_types":[138],"class_list":["post-125619","host","type-host","status-publish","has-post-thumbnail","hentry","accommodation_type-ferienwohnung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ferienwohnung Grothoff - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-grothoff\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferienwohnung Grothoff - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Ferienwohnung Grothoff bietet zwei charmante Appartements, ideal f\u00fcr erholsame Aufenthalte in Wachtendonk. Mit jeweils rund 35 Quadratmetern erstreckt sich Appartement 1 im Dachgeschoss und Appartement 2 im ersten Obergeschoss. Beide Einheiten vermitteln ein Gef\u00fchl von Komfort und Privatsph\u00e4re, umgeben von der ruhigen Atmosph\u00e4re des niederrheinischen Landkreises Kleve. In dieser l\u00e4ndlichen Idylle bietet die Ferienwohnung Grothoff [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2026\/02\/ferienwohnung-grothoff.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1437\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-grothoff\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-grothoff\/\",\"name\":\"Ferienwohnung Grothoff - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-05-11T23:57:39+00:00\",\"dateModified\":\"2026-05-11T23:57:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-grothoff\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-grothoff\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-grothoff\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gastgeber\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ferienwohnung Grothoff\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ferienwohnung Grothoff - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-grothoff\/","og_locale":"en_US","og_type":"article","og_title":"Ferienwohnung Grothoff - Stadt. Land. Niederrhein","og_description":"Ferienwohnung Grothoff bietet zwei charmante Appartements, ideal f\u00fcr erholsame Aufenthalte in Wachtendonk. Mit jeweils rund 35 Quadratmetern erstreckt sich Appartement 1 im Dachgeschoss und Appartement 2 im ersten Obergeschoss. Beide Einheiten vermitteln ein Gef\u00fchl von Komfort und Privatsph\u00e4re, umgeben von der ruhigen Atmosph\u00e4re des niederrheinischen Landkreises Kleve. In dieser l\u00e4ndlichen Idylle bietet die Ferienwohnung Grothoff [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":1437,"height":2048,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2026\/02\/ferienwohnung-grothoff.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-grothoff\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-grothoff\/","name":"Ferienwohnung Grothoff - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-05-11T23:57:39+00:00","dateModified":"2026-05-11T23:57:39+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-grothoff\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-grothoff\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-grothoff\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Gastgeber","item":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/"},{"@type":"ListItem","position":3,"name":"Ferienwohnung Grothoff"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/125619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/host"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/125619\/revisions"}],"predecessor-version":[{"id":125799,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/125619\/revisions\/125799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/127340"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=125619"}],"wp:term":[{"taxonomy":"accommodation_type","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/accommodation_types?post=125619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}