{"id":127151,"date":"2026-05-12T01:47:25","date_gmt":"2026-05-11T23:47:25","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/gastgeber\/reisemobilstellplatz-am-solegarten-st-jakob\/"},"modified":"2026-05-12T01:47:25","modified_gmt":"2026-05-11T23:47:25","slug":"reisemobilstellplatz-am-solegarten-st-jakob","status":"publish","type":"host","link":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/reisemobilstellplatz-am-solegarten-st-jakob\/","title":{"rendered":"Reisemobilstellplatz am Solegarten St. Jakob"},"content":{"rendered":"<p>Der Reisemobilstellplatz am Solegarten St. Jakob in Kevelaer bietet acht Stellpl\u00e4tze auf einer befestigten Fl\u00e4che. Der Standort ist ideal f\u00fcr Erkundungen in der Region, sei es zu Fu\u00df oder mit dem Rad. Die N\u00e4he zu den Niederlanden erm\u00f6glicht ausgedehnte Radtouren. Der Stellplatz ist kostenlos und ohne Anmeldung nutzbar. Im Umfeld befinden sich das Kevelaerer Hallenbad sowie verschiedene gastronomische Einrichtungen. Informationen zu Rad- und Wanderrouten sind im Informationsgeb\u00e4ude des Solegartens erh\u00e4ltlich.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Reisemobilstellplatz am Solegarten St. Jakob in Kevelaer bietet acht Stellpl\u00e4tze auf einer befestigten Fl\u00e4che. Der Standort ist ideal f\u00fcr Erkundungen in der Region, sei es zu Fu\u00df oder mit dem Rad. Die N\u00e4he zu den Niederlanden erm\u00f6glicht ausgedehnte Radtouren. Der Stellplatz ist kostenlos und ohne Anmeldung nutzbar. Im Umfeld befinden sich das Kevelaerer Hallenbad [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":127152,"template":"","accommodation_types":[142,149],"class_list":["post-127151","host","type-host","status-publish","has-post-thumbnail","hentry","accommodation_type-campingplatz","accommodation_type-wohnmobilstellplatz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Reisemobilstellplatz am Solegarten St. Jakob - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/reisemobilstellplatz-am-solegarten-st-jakob\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reisemobilstellplatz am Solegarten St. Jakob - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Der Reisemobilstellplatz am Solegarten St. Jakob in Kevelaer bietet acht Stellpl\u00e4tze auf einer befestigten Fl\u00e4che. Der Standort ist ideal f\u00fcr Erkundungen in der Region, sei es zu Fu\u00df oder mit dem Rad. Die N\u00e4he zu den Niederlanden erm\u00f6glicht ausgedehnte Radtouren. Der Stellplatz ist kostenlos und ohne Anmeldung nutzbar. Im Umfeld befinden sich das Kevelaerer Hallenbad [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2026\/02\/reisemobil-solegarten-04-2023-a-manthey-003.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/reisemobilstellplatz-am-solegarten-st-jakob\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/reisemobilstellplatz-am-solegarten-st-jakob\/\",\"name\":\"Reisemobilstellplatz am Solegarten St. Jakob - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-05-11T23:47:25+00:00\",\"dateModified\":\"2026-05-11T23:47:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/reisemobilstellplatz-am-solegarten-st-jakob\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/reisemobilstellplatz-am-solegarten-st-jakob\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/reisemobilstellplatz-am-solegarten-st-jakob\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gastgeber\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Reisemobilstellplatz am Solegarten St. Jakob\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reisemobilstellplatz am Solegarten St. Jakob - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/reisemobilstellplatz-am-solegarten-st-jakob\/","og_locale":"en_US","og_type":"article","og_title":"Reisemobilstellplatz am Solegarten St. Jakob - Stadt. Land. Niederrhein","og_description":"Der Reisemobilstellplatz am Solegarten St. Jakob in Kevelaer bietet acht Stellpl\u00e4tze auf einer befestigten Fl\u00e4che. Der Standort ist ideal f\u00fcr Erkundungen in der Region, sei es zu Fu\u00df oder mit dem Rad. Die N\u00e4he zu den Niederlanden erm\u00f6glicht ausgedehnte Radtouren. Der Stellplatz ist kostenlos und ohne Anmeldung nutzbar. Im Umfeld befinden sich das Kevelaerer Hallenbad [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2000,"height":1500,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2026\/02\/reisemobil-solegarten-04-2023-a-manthey-003.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/reisemobilstellplatz-am-solegarten-st-jakob\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/reisemobilstellplatz-am-solegarten-st-jakob\/","name":"Reisemobilstellplatz am Solegarten St. Jakob - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-05-11T23:47:25+00:00","dateModified":"2026-05-11T23:47:25+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/reisemobilstellplatz-am-solegarten-st-jakob\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/reisemobilstellplatz-am-solegarten-st-jakob\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/reisemobilstellplatz-am-solegarten-st-jakob\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Gastgeber","item":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/"},{"@type":"ListItem","position":3,"name":"Reisemobilstellplatz am Solegarten St. Jakob"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/127151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/host"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/127151\/revisions"}],"predecessor-version":[{"id":127196,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/127151\/revisions\/127196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/127152"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=127151"}],"wp:term":[{"taxonomy":"accommodation_type","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/accommodation_types?post=127151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}