{"id":128503,"date":"2026-05-12T01:46:17","date_gmt":"2026-05-11T23:46:17","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/gastgeber\/haus-abendruh\/"},"modified":"2026-05-12T01:46:17","modified_gmt":"2026-05-11T23:46:17","slug":"haus-abendruh","status":"publish","type":"host","link":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/haus-abendruh\/","title":{"rendered":"Haus Abendruh"},"content":{"rendered":"<p>Haus Abendruh bietet in Sonsbeck ein ruhiges und komfortables Nachtlager ab einem Aufenthalt von drei Tagen. Das 1996 erbaute Haus liegt optimal nur etwa acht Gehminuten vom Ortsmittelpunkt entfernt. PKW- und Fahrradabstellpl\u00e4tze sind vorhanden. Im Zimmerangebot finden sich ein Doppelzimmer mit 22 m\u00b2, das sowohl als Wohn- und Schlafraum genutzt werden kann und einen gro\u00dfen, nach Westen ausgerichteten Balkon sowie ein ger\u00e4umiges Bad umfasst. Ein weiteres Doppelzimmer von 9 m\u00b2 ist mit eigenem Bad ausgestattet. Fr\u00fchst\u00fcck wird nach Wunsch serviert, und Sat-TV ist vorhanden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Haus Abendruh bietet in Sonsbeck ein ruhiges und komfortables Nachtlager ab einem Aufenthalt von drei Tagen. Das 1996 erbaute Haus liegt optimal nur etwa acht Gehminuten vom Ortsmittelpunkt entfernt. PKW- und Fahrradabstellpl\u00e4tze sind vorhanden. Im Zimmerangebot finden sich ein Doppelzimmer mit 22 m\u00b2, das sowohl als Wohn- und Schlafraum genutzt werden kann und einen gro\u00dfen, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":106919,"template":"","accommodation_types":[135],"class_list":["post-128503","host","type-host","status-publish","has-post-thumbnail","hentry","accommodation_type-pension"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Haus Abendruh - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/haus-abendruh\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Haus Abendruh - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Haus Abendruh bietet in Sonsbeck ein ruhiges und komfortables Nachtlager ab einem Aufenthalt von drei Tagen. Das 1996 erbaute Haus liegt optimal nur etwa acht Gehminuten vom Ortsmittelpunkt entfernt. PKW- und Fahrradabstellpl\u00e4tze sind vorhanden. Im Zimmerangebot finden sich ein Doppelzimmer mit 22 m\u00b2, das sowohl als Wohn- und Schlafraum genutzt werden kann und einen gro\u00dfen, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/05\/sonsbeck-haus-abendruh-au-enansicht.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/haus-abendruh\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/haus-abendruh\/\",\"name\":\"Haus Abendruh - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-05-11T23:46:17+00:00\",\"dateModified\":\"2026-05-11T23:46:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/haus-abendruh\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/haus-abendruh\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/haus-abendruh\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gastgeber\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Haus Abendruh\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Haus Abendruh - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/haus-abendruh\/","og_locale":"en_US","og_type":"article","og_title":"Haus Abendruh - Stadt. Land. Niederrhein","og_description":"Haus Abendruh bietet in Sonsbeck ein ruhiges und komfortables Nachtlager ab einem Aufenthalt von drei Tagen. Das 1996 erbaute Haus liegt optimal nur etwa acht Gehminuten vom Ortsmittelpunkt entfernt. PKW- und Fahrradabstellpl\u00e4tze sind vorhanden. Im Zimmerangebot finden sich ein Doppelzimmer mit 22 m\u00b2, das sowohl als Wohn- und Schlafraum genutzt werden kann und einen gro\u00dfen, [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":1920,"height":1280,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/05\/sonsbeck-haus-abendruh-au-enansicht.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/haus-abendruh\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/haus-abendruh\/","name":"Haus Abendruh - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-05-11T23:46:17+00:00","dateModified":"2026-05-11T23:46:17+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/haus-abendruh\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/haus-abendruh\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/haus-abendruh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Gastgeber","item":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/"},{"@type":"ListItem","position":3,"name":"Haus Abendruh"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/128503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/host"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/128503\/revisions"}],"predecessor-version":[{"id":128535,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/128503\/revisions\/128535"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/106919"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=128503"}],"wp:term":[{"taxonomy":"accommodation_type","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/accommodation_types?post=128503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}