{"id":128507,"date":"2026-05-12T01:47:07","date_gmt":"2026-05-11T23:47:07","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/gastgeber\/ferienwohnung-hof-thiergarten\/"},"modified":"2026-05-12T01:47:07","modified_gmt":"2026-05-11T23:47:07","slug":"ferienwohnung-hof-thiergarten","status":"publish","type":"host","link":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-hof-thiergarten\/","title":{"rendered":"Ferienwohnung Hof Thiergarten"},"content":{"rendered":"<p>Die Ferienwohnung Hof Thiergarten bietet mit ihren 54 Quadratmetern eine durchdachte Raumaufteilung mit drei Zimmern, K\u00fcche und Bad. Die Ausstattung umfasst moderne Steinfu\u00dfb\u00f6den mit Fu\u00dfbodenheizung und eine K\u00fcche, die eine ruhige Aussicht in den angrenzenden Wald erm\u00f6glicht. Mit einer Entfernung von nur 6 Kilometern zum Luftkurort Xanten verbindet die Lage naturnahe Ruhe mit der M\u00f6glichkeit zur Entdeckung regionaler H\u00f6hepunkte. Direkt vor dem Haus laden Wander-, Rad- und Reitwege zur aktiven Erholung ein. Ein eigener kleiner Gartenbereich mit Sitzm\u00f6glichkeiten bietet Entspannung pur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Ferienwohnung Hof Thiergarten bietet mit ihren 54 Quadratmetern eine durchdachte Raumaufteilung mit drei Zimmern, K\u00fcche und Bad. Die Ausstattung umfasst moderne Steinfu\u00dfb\u00f6den mit Fu\u00dfbodenheizung und eine K\u00fcche, die eine ruhige Aussicht in den angrenzenden Wald erm\u00f6glicht. Mit einer Entfernung von nur 6 Kilometern zum Luftkurort Xanten verbindet die Lage naturnahe Ruhe mit der M\u00f6glichkeit [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":107610,"template":"","accommodation_types":[138],"class_list":["post-128507","host","type-host","status-publish","has-post-thumbnail","hentry","accommodation_type-ferienwohnung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ferienwohnung Hof Thiergarten - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-hof-thiergarten\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferienwohnung Hof Thiergarten - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Die Ferienwohnung Hof Thiergarten bietet mit ihren 54 Quadratmetern eine durchdachte Raumaufteilung mit drei Zimmern, K\u00fcche und Bad. Die Ausstattung umfasst moderne Steinfu\u00dfb\u00f6den mit Fu\u00dfbodenheizung und eine K\u00fcche, die eine ruhige Aussicht in den angrenzenden Wald erm\u00f6glicht. Mit einer Entfernung von nur 6 Kilometern zum Luftkurort Xanten verbindet die Lage naturnahe Ruhe mit der M\u00f6glichkeit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/05\/sonsbeck-ferienwohnung-thiergarten-au-enansicht.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"453\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-hof-thiergarten\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-hof-thiergarten\/\",\"name\":\"Ferienwohnung Hof Thiergarten - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-05-11T23:47:07+00:00\",\"dateModified\":\"2026-05-11T23:47:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-hof-thiergarten\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-hof-thiergarten\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-hof-thiergarten\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gastgeber\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ferienwohnung Hof Thiergarten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ferienwohnung Hof Thiergarten - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-hof-thiergarten\/","og_locale":"en_US","og_type":"article","og_title":"Ferienwohnung Hof Thiergarten - Stadt. Land. Niederrhein","og_description":"Die Ferienwohnung Hof Thiergarten bietet mit ihren 54 Quadratmetern eine durchdachte Raumaufteilung mit drei Zimmern, K\u00fcche und Bad. Die Ausstattung umfasst moderne Steinfu\u00dfb\u00f6den mit Fu\u00dfbodenheizung und eine K\u00fcche, die eine ruhige Aussicht in den angrenzenden Wald erm\u00f6glicht. Mit einer Entfernung von nur 6 Kilometern zum Luftkurort Xanten verbindet die Lage naturnahe Ruhe mit der M\u00f6glichkeit [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":680,"height":453,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/05\/sonsbeck-ferienwohnung-thiergarten-au-enansicht.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-hof-thiergarten\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-hof-thiergarten\/","name":"Ferienwohnung Hof Thiergarten - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-05-11T23:47:07+00:00","dateModified":"2026-05-11T23:47:07+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-hof-thiergarten\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-hof-thiergarten\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-hof-thiergarten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Gastgeber","item":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/"},{"@type":"ListItem","position":3,"name":"Ferienwohnung Hof Thiergarten"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/128507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/host"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/128507\/revisions"}],"predecessor-version":[{"id":128539,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/128507\/revisions\/128539"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/107610"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=128507"}],"wp:term":[{"taxonomy":"accommodation_type","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/accommodation_types?post=128507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}