{"id":137848,"date":"2026-09-01T03:35:49","date_gmt":"2026-09-01T01:35:49","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/gastgeber\/ferienwohnung-kempkens-fuer-2-6-personen-hochwertig-modern-eingerichtet-naehe-venlo-mit-4-sternen-vom-dtv-klassifiziert\/"},"modified":"2026-09-01T03:35:49","modified_gmt":"2026-09-01T01:35:49","slug":"ferienwohnung-kempkens-fuer-2-6-personen-hochwertig-modern-eingerichtet-naehe-venlo-mit-4-sternen-vom-dtv-klassifiziert","status":"publish","type":"host","link":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-kempkens-fuer-2-6-personen-hochwertig-modern-eingerichtet-naehe-venlo-mit-4-sternen-vom-dtv-klassifiziert\/","title":{"rendered":"Ferienwohnung Kempkens f\u00fcr 2-6 Personen-Hochwertig &amp; modern eingerichtet &#8211; N\u00e4he Venlo &#8212; mit 4 Sternen vom DTV klassifiziert &#8212;"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":0,"template":"","accommodation_types":[138],"class_list":["post-137848","host","type-host","status-publish","hentry","accommodation_type-ferienwohnung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ferienwohnung Kempkens f\u00fcr 2-6 Personen-Hochwertig &amp; modern eingerichtet - N\u00e4he Venlo - mit 4 Sternen vom DTV klassifiziert - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-kempkens-fuer-2-6-personen-hochwertig-modern-eingerichtet-naehe-venlo-mit-4-sternen-vom-dtv-klassifiziert\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferienwohnung Kempkens f\u00fcr 2-6 Personen-Hochwertig &amp; modern eingerichtet - N\u00e4he Venlo - mit 4 Sternen vom DTV klassifiziert - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-kempkens-fuer-2-6-personen-hochwertig-modern-eingerichtet-naehe-venlo-mit-4-sternen-vom-dtv-klassifiziert\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-kempkens-fuer-2-6-personen-hochwertig-modern-eingerichtet-naehe-venlo-mit-4-sternen-vom-dtv-klassifiziert\/\",\"name\":\"Ferienwohnung Kempkens f\u00fcr 2-6 Personen-Hochwertig &amp; modern eingerichtet - N\u00e4he Venlo - mit 4 Sternen vom DTV klassifiziert - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-09-01T01:35:49+00:00\",\"dateModified\":\"2026-09-01T01:35:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-kempkens-fuer-2-6-personen-hochwertig-modern-eingerichtet-naehe-venlo-mit-4-sternen-vom-dtv-klassifiziert\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-kempkens-fuer-2-6-personen-hochwertig-modern-eingerichtet-naehe-venlo-mit-4-sternen-vom-dtv-klassifiziert\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-kempkens-fuer-2-6-personen-hochwertig-modern-eingerichtet-naehe-venlo-mit-4-sternen-vom-dtv-klassifiziert\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gastgeber\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ferienwohnung Kempkens f\u00fcr 2-6 Personen-Hochwertig &amp; modern eingerichtet - N\u00e4he Venlo --- mit 4 Sternen vom DTV klassifiziert ---\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ferienwohnung Kempkens f\u00fcr 2-6 Personen-Hochwertig &amp; modern eingerichtet - N\u00e4he Venlo - mit 4 Sternen vom DTV klassifiziert - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-kempkens-fuer-2-6-personen-hochwertig-modern-eingerichtet-naehe-venlo-mit-4-sternen-vom-dtv-klassifiziert\/","og_locale":"en_US","og_type":"article","og_title":"Ferienwohnung Kempkens f\u00fcr 2-6 Personen-Hochwertig &amp; modern eingerichtet - N\u00e4he Venlo - mit 4 Sternen vom DTV klassifiziert - Stadt. Land. Niederrhein","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-kempkens-fuer-2-6-personen-hochwertig-modern-eingerichtet-naehe-venlo-mit-4-sternen-vom-dtv-klassifiziert\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-kempkens-fuer-2-6-personen-hochwertig-modern-eingerichtet-naehe-venlo-mit-4-sternen-vom-dtv-klassifiziert\/","name":"Ferienwohnung Kempkens f\u00fcr 2-6 Personen-Hochwertig &amp; modern eingerichtet - N\u00e4he Venlo - mit 4 Sternen vom DTV klassifiziert - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-09-01T01:35:49+00:00","dateModified":"2026-09-01T01:35:49+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-kempkens-fuer-2-6-personen-hochwertig-modern-eingerichtet-naehe-venlo-mit-4-sternen-vom-dtv-klassifiziert\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-kempkens-fuer-2-6-personen-hochwertig-modern-eingerichtet-naehe-venlo-mit-4-sternen-vom-dtv-klassifiziert\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/ferienwohnung-kempkens-fuer-2-6-personen-hochwertig-modern-eingerichtet-naehe-venlo-mit-4-sternen-vom-dtv-klassifiziert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Gastgeber","item":"https:\/\/stadt-land-niederrhein.de\/en\/gastgeber\/"},{"@type":"ListItem","position":3,"name":"Ferienwohnung Kempkens f\u00fcr 2-6 Personen-Hochwertig &amp; modern eingerichtet - N\u00e4he Venlo --- mit 4 Sternen vom DTV klassifiziert ---"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/137848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/host"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/137848\/revisions"}],"predecessor-version":[{"id":140038,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/hosts\/137848\/revisions\/140038"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=137848"}],"wp:term":[{"taxonomy":"accommodation_type","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/accommodation_types?post=137848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}