{"id":109117,"date":"2026-09-02T02:03:16","date_gmt":"2026-09-02T00:03:16","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/muehlenmuseum-hiesfeld-2\/"},"modified":"2026-09-02T02:03:16","modified_gmt":"2026-09-02T00:03:16","slug":"muehlenmuseum-hiesfeld-2","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muehlenmuseum-hiesfeld-2\/","title":{"rendered":"M\u00fchlenmuseum Hiesfeld"},"content":{"rendered":"<p>Das M\u00fchlenmuseum Hiesfeld beeindruckt mit einem imposanten mittelsch\u00e4chtigen Wasserrad, das bis an den Walm des Fachwerkhauses reicht und den historischen Backsteinbau vom sp\u00e4ter errichteten Wohngeb\u00e4ude des M\u00fcllers trennt. In den R\u00e4umlichkeiten der ehemaligen Wasserm\u00fchle wird die Entwicklung des M\u00fcllerhandwerks anschaulich dargestellt. Das Museum bietet zudem einen hervorragenden Ausgangspunkt f\u00fcr Erkundungen des Rotbachtals. Das \u00fcber 100 Jahre alte Wasserrad wurde 2007 erneuert und ist ein zentrales Element der Ausstellung. Auf drei Etagen pr\u00e4sentiert das Museum \u00fcber 60 M\u00fchlenmodelle aus aller Welt. Erg\u00e4nzt wird die Ausstellung durch wechselnde Sonderschauen, darunter auch Fotoausstellungen, die das Angebot bereichern.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das M\u00fchlenmuseum Hiesfeld beeindruckt mit einem imposanten mittelsch\u00e4chtigen Wasserrad, das bis an den Walm des Fachwerkhauses reicht und den historischen Backsteinbau vom sp\u00e4ter errichteten Wohngeb\u00e4ude des M\u00fcllers trennt. In den R\u00e4umlichkeiten der ehemaligen Wasserm\u00fchle wird die Entwicklung des M\u00fcllerhandwerks anschaulich dargestellt. Das Museum bietet zudem einen hervorragenden Ausgangspunkt f\u00fcr Erkundungen des Rotbachtals. Das \u00fcber 100 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":98434,"template":"","destinations":[235,170],"class_list":["post-109117","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-historische-orte","destination-museen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00fchlenmuseum Hiesfeld - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muehlenmuseum-hiesfeld-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00fchlenmuseum Hiesfeld - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Das M\u00fchlenmuseum Hiesfeld beeindruckt mit einem imposanten mittelsch\u00e4chtigen Wasserrad, das bis an den Walm des Fachwerkhauses reicht und den historischen Backsteinbau vom sp\u00e4ter errichteten Wohngeb\u00e4ude des M\u00fcllers trennt. In den R\u00e4umlichkeiten der ehemaligen Wasserm\u00fchle wird die Entwicklung des M\u00fcllerhandwerks anschaulich dargestellt. Das Museum bietet zudem einen hervorragenden Ausgangspunkt f\u00fcr Erkundungen des Rotbachtals. Das \u00fcber 100 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/m-hlenmuseum-hiesfeld.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1110\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muehlenmuseum-hiesfeld-2\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muehlenmuseum-hiesfeld-2\/\",\"name\":\"M\u00fchlenmuseum Hiesfeld - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-09-02T00:03:16+00:00\",\"dateModified\":\"2026-09-02T00:03:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muehlenmuseum-hiesfeld-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muehlenmuseum-hiesfeld-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muehlenmuseum-hiesfeld-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"M\u00fchlenmuseum Hiesfeld\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00fchlenmuseum Hiesfeld - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muehlenmuseum-hiesfeld-2\/","og_locale":"en_US","og_type":"article","og_title":"M\u00fchlenmuseum Hiesfeld - Stadt. Land. Niederrhein","og_description":"Das M\u00fchlenmuseum Hiesfeld beeindruckt mit einem imposanten mittelsch\u00e4chtigen Wasserrad, das bis an den Walm des Fachwerkhauses reicht und den historischen Backsteinbau vom sp\u00e4ter errichteten Wohngeb\u00e4ude des M\u00fcllers trennt. In den R\u00e4umlichkeiten der ehemaligen Wasserm\u00fchle wird die Entwicklung des M\u00fcllerhandwerks anschaulich dargestellt. Das Museum bietet zudem einen hervorragenden Ausgangspunkt f\u00fcr Erkundungen des Rotbachtals. Das \u00fcber 100 [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":1500,"height":1110,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/m-hlenmuseum-hiesfeld.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muehlenmuseum-hiesfeld-2\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muehlenmuseum-hiesfeld-2\/","name":"M\u00fchlenmuseum Hiesfeld - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-09-02T00:03:16+00:00","dateModified":"2026-09-02T00:03:16+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muehlenmuseum-hiesfeld-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muehlenmuseum-hiesfeld-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muehlenmuseum-hiesfeld-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culture","item":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/"},{"@type":"ListItem","position":3,"name":"M\u00fchlenmuseum Hiesfeld"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/109117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":3,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/109117\/revisions"}],"predecessor-version":[{"id":123351,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/109117\/revisions\/123351"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/98434"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=109117"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/destinations?post=109117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}