{"id":125052,"date":"2026-09-02T01:22:20","date_gmt":"2026-09-01T23:22:20","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/hoerstein-2\/"},"modified":"2026-09-02T01:22:20","modified_gmt":"2026-09-01T23:22:20","slug":"hoerstein-2","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/hoerstein-2\/","title":{"rendered":"H\u00f6rstein"},"content":{"rendered":"<p>Der H\u00f6rstein ist ein bedeutender Bestandteil der \u201eLiberation Route Europe\u201c, die von S\u00fcdengland \u00fcber Nordfrankreich, die Ardennen und das niederl\u00e4ndisch-belgische Grenzgebiet bis nach Berlin und Danzig verl\u00e4uft. Diese Route beleuchtet zentrale Stationen und regionale Ereignisse der Befreiung Europas am Ende des Zweiten Weltkrieges. Die Gemeinde Niederkr\u00fcchten, als Teil dieser Route, engagiert sich mit einem innovativen Ansatz in der aktiven Erinnerungskultur. Der H\u00f6rstein symbolisiert dabei die historische Bedeutung und das Engagement f\u00fcr die Bewahrung der Geschichte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der H\u00f6rstein ist ein bedeutender Bestandteil der \u201eLiberation Route Europe\u201c, die von S\u00fcdengland \u00fcber Nordfrankreich, die Ardennen und das niederl\u00e4ndisch-belgische Grenzgebiet bis nach Berlin und Danzig verl\u00e4uft. Diese Route beleuchtet zentrale Stationen und regionale Ereignisse der Befreiung Europas am Ende des Zweiten Weltkrieges. Die Gemeinde Niederkr\u00fcchten, als Teil dieser Route, engagiert sich mit einem innovativen [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":104484,"template":"","destinations":[235],"class_list":["post-125052","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-historische-orte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>H\u00f6rstein - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/hoerstein-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"H\u00f6rstein - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Der H\u00f6rstein ist ein bedeutender Bestandteil der \u201eLiberation Route Europe\u201c, die von S\u00fcdengland \u00fcber Nordfrankreich, die Ardennen und das niederl\u00e4ndisch-belgische Grenzgebiet bis nach Berlin und Danzig verl\u00e4uft. Diese Route beleuchtet zentrale Stationen und regionale Ereignisse der Befreiung Europas am Ende des Zweiten Weltkrieges. Die Gemeinde Niederkr\u00fcchten, als Teil dieser Route, engagiert sich mit einem innovativen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/03\/h-rstein-in-oberkr-chten.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/hoerstein-2\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/hoerstein-2\/\",\"name\":\"H\u00f6rstein - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-09-01T23:22:20+00:00\",\"dateModified\":\"2026-09-01T23:22:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/hoerstein-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/hoerstein-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/hoerstein-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"H\u00f6rstein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"H\u00f6rstein - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/hoerstein-2\/","og_locale":"en_US","og_type":"article","og_title":"H\u00f6rstein - Stadt. Land. Niederrhein","og_description":"Der H\u00f6rstein ist ein bedeutender Bestandteil der \u201eLiberation Route Europe\u201c, die von S\u00fcdengland \u00fcber Nordfrankreich, die Ardennen und das niederl\u00e4ndisch-belgische Grenzgebiet bis nach Berlin und Danzig verl\u00e4uft. Diese Route beleuchtet zentrale Stationen und regionale Ereignisse der Befreiung Europas am Ende des Zweiten Weltkrieges. Die Gemeinde Niederkr\u00fcchten, als Teil dieser Route, engagiert sich mit einem innovativen [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":1024,"height":682,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/03\/h-rstein-in-oberkr-chten.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/hoerstein-2\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/hoerstein-2\/","name":"H\u00f6rstein - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-09-01T23:22:20+00:00","dateModified":"2026-09-01T23:22:20+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/hoerstein-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kultur\/hoerstein-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/hoerstein-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culture","item":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/"},{"@type":"ListItem","position":3,"name":"H\u00f6rstein"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/125052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/125052\/revisions"}],"predecessor-version":[{"id":125399,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/125052\/revisions\/125399"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/104484"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=125052"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/destinations?post=125052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}