{"id":125150,"date":"2026-05-13T01:02:26","date_gmt":"2026-05-12T23:02:26","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/gerebernus-kapelle\/"},"modified":"2026-05-13T01:02:26","modified_gmt":"2026-05-12T23:02:26","slug":"gerebernus-kapelle","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/gerebernus-kapelle\/","title":{"rendered":"Gerebernus-Kapelle"},"content":{"rendered":"<p>Die St.-Gerebernus-Kapelle in Sonsbeck ist ein bedeutendes Zeugnis der regionalen Geschichte. Ihre Urspr\u00fcnge lassen sich bis zu einer Hofkapelle in der Keimzelle des \u201ealten Sonsbeck\u201c zur\u00fcckverfolgen, einer Siedlung, die bis in die R\u00f6merzeit reicht. Die r\u00f6mische Heerstra\u00dfe von Xanten nach Venlo f\u00fchrte einst direkt an diesem Ort vorbei, und ein noch erhaltener R\u00f6merturm zeugt von der historischen Bedeutung dieser Gegend. In der Stauferzeit errichteten die K\u00f6lner Erzbisch\u00f6fe hier einen befestigten Hof, und um das Jahr 900 entstand die erste Kapelle, die dem Heiligen Gerebernus geweiht wurde. Dieser soll um das Jahr 600 gemeinsam mit der Heiligen Dymphna den M\u00e4rtyrertod erlitten haben, eine Geschichte, die bis heute viele Menschen bewegt. Ein besonderes Merkmal der Kapelle ist der Kriechaltar, eine von nur zwei erhaltenen Anlagen dieser Art in Deutschland. Dieses seltene Ritual, bei dem Besucher:innen unter dem Altar hindurchkriechen k\u00f6nnen, symbolisiert Demut und Neubeginn und stellt eine einzigartige Erfahrung f\u00fcr Interessierte sakraler Baukunst dar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die St.-Gerebernus-Kapelle in Sonsbeck erz\u00e4hlt Geschichte von R\u00f6mern bis ins Mittelalter. Einzigartig: der Kriechaltar \u2013 eine von nur zwei Anlagen in Deutschland. Sie fungiert als St\u00e4tte kultureller und spiritueller Begegnung.<\/p>\n","protected":false},"author":0,"featured_media":111357,"template":"","destinations":[242],"class_list":["post-125150","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-kirchen-kloester"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gerebernus-Kapelle - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/gerebernus-kapelle\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gerebernus-Kapelle - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Die St.-Gerebernus-Kapelle in Sonsbeck erz\u00e4hlt Geschichte von R\u00f6mern bis ins Mittelalter. Einzigartig: der Kriechaltar \u2013 eine von nur zwei Anlagen in Deutschland. Sie fungiert als St\u00e4tte kultureller und spiritueller Begegnung.\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/08\/sonsbeck-gerebernuskapelle-10-cc-by-sa-gemeinde-sonsbeck-nicole-wagener-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1928\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/gerebernus-kapelle\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/gerebernus-kapelle\/\",\"name\":\"Gerebernus-Kapelle - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-05-12T23:02:26+00:00\",\"dateModified\":\"2026-05-12T23:02:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/gerebernus-kapelle\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/gerebernus-kapelle\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/gerebernus-kapelle\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gerebernus-Kapelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gerebernus-Kapelle - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/gerebernus-kapelle\/","og_locale":"en_US","og_type":"article","og_title":"Gerebernus-Kapelle - Stadt. Land. Niederrhein","og_description":"Die St.-Gerebernus-Kapelle in Sonsbeck erz\u00e4hlt Geschichte von R\u00f6mern bis ins Mittelalter. Einzigartig: der Kriechaltar \u2013 eine von nur zwei Anlagen in Deutschland. Sie fungiert als St\u00e4tte kultureller und spiritueller Begegnung.","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":1928,"height":2560,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/08\/sonsbeck-gerebernuskapelle-10-cc-by-sa-gemeinde-sonsbeck-nicole-wagener-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/gerebernus-kapelle\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/gerebernus-kapelle\/","name":"Gerebernus-Kapelle - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-05-12T23:02:26+00:00","dateModified":"2026-05-12T23:02:26+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/gerebernus-kapelle\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kultur\/gerebernus-kapelle\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/gerebernus-kapelle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culture","item":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/"},{"@type":"ListItem","position":3,"name":"Gerebernus-Kapelle"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/125150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/125150\/revisions"}],"predecessor-version":[{"id":125496,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/125150\/revisions\/125496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/111357"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=125150"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/destinations?post=125150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}