{"id":125193,"date":"2026-05-13T01:09:34","date_gmt":"2026-05-12T23:09:34","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/pieta-in-wesel-bislich\/"},"modified":"2026-05-13T01:09:34","modified_gmt":"2026-05-12T23:09:34","slug":"pieta-in-wesel-bislich","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pieta-in-wesel-bislich\/","title":{"rendered":"Pieta in Wesel-Bislich"},"content":{"rendered":"<p>Zur Erinnerung an die Opfer und Zerst\u00f6rungen des Zweiten Weltkrieges wurde am 23. M\u00e4rz 1985, genau 40 Jahre nach dem Rhein\u00fcbergang der Alliierten bei Bislich, die Gedenkst\u00e4tte auf dem Rheindeich in Wesel-Bislich eingeweiht. Die Pieta, urspr\u00fcnglich f\u00fcr die katholische Kirche St. Johannes in Bislich Ende des 19. Jahrhunderts geschaffen, wurde im Zuge von Renovierungen aus der Kirche entfernt und fand hier einen neuen Platz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zur Erinnerung an die Opfer und Zerst\u00f6rungen des Zweiten Weltkrieges wurde am 23. M\u00e4rz 1985, genau 40 Jahre nach dem Rhein\u00fcbergang der Alliierten bei Bislich, die Gedenkst\u00e4tte auf dem Rheindeich in Wesel-Bislich eingeweiht. Die Pieta, urspr\u00fcnglich f\u00fcr die katholische Kirche St. Johannes in Bislich Ende des 19. Jahrhunderts geschaffen, wurde im Zuge von Renovierungen aus [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":101255,"template":"","destinations":[235],"class_list":["post-125193","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-historische-orte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pieta in Wesel-Bislich - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pieta-in-wesel-bislich\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pieta in Wesel-Bislich - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Zur Erinnerung an die Opfer und Zerst\u00f6rungen des Zweiten Weltkrieges wurde am 23. M\u00e4rz 1985, genau 40 Jahre nach dem Rhein\u00fcbergang der Alliierten bei Bislich, die Gedenkst\u00e4tte auf dem Rheindeich in Wesel-Bislich eingeweiht. Die Pieta, urspr\u00fcnglich f\u00fcr die katholische Kirche St. Johannes in Bislich Ende des 19. Jahrhunderts geschaffen, wurde im Zuge von Renovierungen aus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/pieta-am-rheindeich-in-bislich.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pieta-in-wesel-bislich\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pieta-in-wesel-bislich\/\",\"name\":\"Pieta in Wesel-Bislich - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-05-12T23:09:34+00:00\",\"dateModified\":\"2026-05-12T23:09:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pieta-in-wesel-bislich\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pieta-in-wesel-bislich\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pieta-in-wesel-bislich\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pieta in Wesel-Bislich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pieta in Wesel-Bislich - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pieta-in-wesel-bislich\/","og_locale":"en_US","og_type":"article","og_title":"Pieta in Wesel-Bislich - Stadt. Land. Niederrhein","og_description":"Zur Erinnerung an die Opfer und Zerst\u00f6rungen des Zweiten Weltkrieges wurde am 23. M\u00e4rz 1985, genau 40 Jahre nach dem Rhein\u00fcbergang der Alliierten bei Bislich, die Gedenkst\u00e4tte auf dem Rheindeich in Wesel-Bislich eingeweiht. Die Pieta, urspr\u00fcnglich f\u00fcr die katholische Kirche St. Johannes in Bislich Ende des 19. Jahrhunderts geschaffen, wurde im Zuge von Renovierungen aus [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":800,"height":600,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/pieta-am-rheindeich-in-bislich.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pieta-in-wesel-bislich\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pieta-in-wesel-bislich\/","name":"Pieta in Wesel-Bislich - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-05-12T23:09:34+00:00","dateModified":"2026-05-12T23:09:34+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pieta-in-wesel-bislich\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pieta-in-wesel-bislich\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pieta-in-wesel-bislich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culture","item":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/"},{"@type":"ListItem","position":3,"name":"Pieta in Wesel-Bislich"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/125193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/125193\/revisions"}],"predecessor-version":[{"id":125517,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/125193\/revisions\/125517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/101255"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=125193"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/destinations?post=125193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}