{"id":126797,"date":"2026-08-29T04:17:58","date_gmt":"2026-08-29T02:17:58","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/pfarrkirche-st-thomas\/"},"modified":"2026-08-29T04:17:58","modified_gmt":"2026-08-29T02:17:58","slug":"pfarrkirche-st-thomas","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pfarrkirche-st-thomas\/","title":{"rendered":"Pfarrkirche St. Thomas"},"content":{"rendered":"<p>Der Beschluss zum Bau der neuen St. Thomas Kirche wurde am 24. Mai 1900 gefasst. Der kreuzf\u00f6rmige Backsteinbau vereint vorwiegend romanische Stilelemente mit Details der fr\u00fchen Gotik. An das zweieinhalbjochige L\u00e4ngsschiff schlie\u00dft sich ein Querhaus mit Vierungsturm an, gefolgt von einem querrechteckigen Chorjoch mit Halbkreisapsis. Die aufwendig gestaltete Westfassade mit dem Hauptportal und den betonten mittleren Fenstern ist ein architektonisches Highlight. Die innere Baufassung und die fig\u00fcrlichen Malereien im Chor, die bald nach der Fertigstellung der Kirche ausgef\u00fchrt wurden, wurden in den Jahren 1977\/78 aufgedeckt und restauriert. Im Jahr 1863 erwarb die Pfarrgemeinde eine alte Orgel aus der Barockzeit, die ab 1979 mehrfach renoviert und zu einem anspruchsvollen Orgelwerk erweitert wurde. Am 2. Oktober 1982 waren die Arbeiten abgeschlossen und die Orgel wurde feierlich eingeweiht. Die Pfarrkirche St. Thomas bietet somit nicht nur architektonische, sondern auch musikalische Erlebnisse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Beschluss zum Bau der neuen St. Thomas Kirche wurde am 24. Mai 1900 gefasst. Der kreuzf\u00f6rmige Backsteinbau vereint vorwiegend romanische Stilelemente mit Details der fr\u00fchen Gotik. An das zweieinhalbjochige L\u00e4ngsschiff schlie\u00dft sich ein Querhaus mit Vierungsturm an, gefolgt von einem querrechteckigen Chorjoch mit Halbkreisapsis. Die aufwendig gestaltete Westfassade mit dem Hauptportal und den betonten [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","destinations":[242],"class_list":["post-126797","poi","type-poi","status-publish","hentry","destination-kirchen-kloester"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pfarrkirche St. Thomas - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pfarrkirche-st-thomas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pfarrkirche St. Thomas - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Der Beschluss zum Bau der neuen St. Thomas Kirche wurde am 24. Mai 1900 gefasst. Der kreuzf\u00f6rmige Backsteinbau vereint vorwiegend romanische Stilelemente mit Details der fr\u00fchen Gotik. An das zweieinhalbjochige L\u00e4ngsschiff schlie\u00dft sich ein Querhaus mit Vierungsturm an, gefolgt von einem querrechteckigen Chorjoch mit Halbkreisapsis. Die aufwendig gestaltete Westfassade mit dem Hauptportal und den betonten [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pfarrkirche-st-thomas\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pfarrkirche-st-thomas\/\",\"name\":\"Pfarrkirche St. Thomas - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-08-29T02:17:58+00:00\",\"dateModified\":\"2026-08-29T02:17:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pfarrkirche-st-thomas\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pfarrkirche-st-thomas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pfarrkirche-st-thomas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pfarrkirche St. Thomas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pfarrkirche St. Thomas - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pfarrkirche-st-thomas\/","og_locale":"en_US","og_type":"article","og_title":"Pfarrkirche St. Thomas - Stadt. Land. Niederrhein","og_description":"Der Beschluss zum Bau der neuen St. Thomas Kirche wurde am 24. Mai 1900 gefasst. Der kreuzf\u00f6rmige Backsteinbau vereint vorwiegend romanische Stilelemente mit Details der fr\u00fchen Gotik. An das zweieinhalbjochige L\u00e4ngsschiff schlie\u00dft sich ein Querhaus mit Vierungsturm an, gefolgt von einem querrechteckigen Chorjoch mit Halbkreisapsis. Die aufwendig gestaltete Westfassade mit dem Hauptportal und den betonten [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pfarrkirche-st-thomas\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pfarrkirche-st-thomas\/","name":"Pfarrkirche St. Thomas - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-08-29T02:17:58+00:00","dateModified":"2026-08-29T02:17:58+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pfarrkirche-st-thomas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pfarrkirche-st-thomas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pfarrkirche-st-thomas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culture","item":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/"},{"@type":"ListItem","position":3,"name":"Pfarrkirche St. Thomas"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/126797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/126797\/revisions"}],"predecessor-version":[{"id":126928,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/126797\/revisions\/126928"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=126797"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/destinations?post=126797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}