{"id":128904,"date":"2026-09-02T01:36:48","date_gmt":"2026-09-01T23:36:48","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/korbmacher-museum-in-hueckelhoven-hilfarth-2\/"},"modified":"2026-09-02T01:36:48","modified_gmt":"2026-09-01T23:36:48","slug":"korbmacher-museum-in-hueckelhoven-hilfarth-2","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/korbmacher-museum-in-hueckelhoven-hilfarth-2\/","title":{"rendered":"Korbmacher-Museum in H\u00fcckelhoven-Hilfarth"},"content":{"rendered":"<p>Das Korbmacher-Museum in H\u00fcckelhoven-Hilfarth bietet einen umfassenden Einblick in die traditionsreiche Geschichte des Korbmacherhandwerks entlang von Rur und Wurm. Im 18. und 19. Jahrhundert florierten hier zahlreiche Korbmacherd\u00f6rfer, da die feuchten Auen ideale Bedingungen f\u00fcr den Anbau von Weidenb\u00e4umen boten. Um 1950 waren etwa 1500 Korbmacher in der Region t\u00e4tig, davon rund 200 in Hilfarth. Die Herstellung von Wei\u00dfkorbwaren aus gesch\u00e4lten Weiden war ein Markenzeichen der Region. Mit der Einf\u00fchrung preiswerter Importe und Plastikprodukte verschwand das Handwerk jedoch fast vollst\u00e4ndig zwischen 1957 und 1961. Um das Wissen zu bewahren, gr\u00fcndeten ehemalige und aktive Korbmacher 1999 den Historischen Verein der Rurtalkorbmacher e.V. und er\u00f6ffneten 2003 das erste Museum. Seit 2008 befindet sich das Museum in der Nohlmannstra\u00dfe. F\u00fchrungen bieten detaillierte Einblicke in die Geschichte und Techniken des Handwerks. Praktische Vorf\u00fchrungen in der Werkstatt zeigen das Flechten von K\u00f6rben und verschiedene Techniken, die Besucher:innen selbst ausprobieren k\u00f6nnen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Korbmacher-Museum in H\u00fcckelhoven-Hilfarth bietet einen umfassenden Einblick in die traditionsreiche Geschichte des Korbmacherhandwerks entlang von Rur und Wurm. Im 18. und 19. Jahrhundert florierten hier zahlreiche Korbmacherd\u00f6rfer, da die feuchten Auen ideale Bedingungen f\u00fcr den Anbau von Weidenb\u00e4umen boten. Um 1950 waren etwa 1500 Korbmacher in der Region t\u00e4tig, davon rund 200 in Hilfarth. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":107013,"template":"","destinations":[170],"class_list":["post-128904","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-museen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Korbmacher-Museum in H\u00fcckelhoven-Hilfarth - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/korbmacher-museum-in-hueckelhoven-hilfarth-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Korbmacher-Museum in H\u00fcckelhoven-Hilfarth - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Das Korbmacher-Museum in H\u00fcckelhoven-Hilfarth bietet einen umfassenden Einblick in die traditionsreiche Geschichte des Korbmacherhandwerks entlang von Rur und Wurm. Im 18. und 19. Jahrhundert florierten hier zahlreiche Korbmacherd\u00f6rfer, da die feuchten Auen ideale Bedingungen f\u00fcr den Anbau von Weidenb\u00e4umen boten. Um 1950 waren etwa 1500 Korbmacher in der Region t\u00e4tig, davon rund 200 in Hilfarth. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/05\/korbwaren-der-rurtal-korbmacher-aus-h-ckelhoven-hilfarth.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/korbmacher-museum-in-hueckelhoven-hilfarth-2\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/korbmacher-museum-in-hueckelhoven-hilfarth-2\/\",\"name\":\"Korbmacher-Museum in H\u00fcckelhoven-Hilfarth - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-09-01T23:36:48+00:00\",\"dateModified\":\"2026-09-01T23:36:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/korbmacher-museum-in-hueckelhoven-hilfarth-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/korbmacher-museum-in-hueckelhoven-hilfarth-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/korbmacher-museum-in-hueckelhoven-hilfarth-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Korbmacher-Museum in H\u00fcckelhoven-Hilfarth\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Korbmacher-Museum in H\u00fcckelhoven-Hilfarth - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/korbmacher-museum-in-hueckelhoven-hilfarth-2\/","og_locale":"en_US","og_type":"article","og_title":"Korbmacher-Museum in H\u00fcckelhoven-Hilfarth - Stadt. Land. Niederrhein","og_description":"Das Korbmacher-Museum in H\u00fcckelhoven-Hilfarth bietet einen umfassenden Einblick in die traditionsreiche Geschichte des Korbmacherhandwerks entlang von Rur und Wurm. Im 18. und 19. Jahrhundert florierten hier zahlreiche Korbmacherd\u00f6rfer, da die feuchten Auen ideale Bedingungen f\u00fcr den Anbau von Weidenb\u00e4umen boten. Um 1950 waren etwa 1500 Korbmacher in der Region t\u00e4tig, davon rund 200 in Hilfarth. [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2048,"height":1536,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/05\/korbwaren-der-rurtal-korbmacher-aus-h-ckelhoven-hilfarth.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/korbmacher-museum-in-hueckelhoven-hilfarth-2\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/korbmacher-museum-in-hueckelhoven-hilfarth-2\/","name":"Korbmacher-Museum in H\u00fcckelhoven-Hilfarth - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-09-01T23:36:48+00:00","dateModified":"2026-09-01T23:36:48+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/korbmacher-museum-in-hueckelhoven-hilfarth-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kultur\/korbmacher-museum-in-hueckelhoven-hilfarth-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/korbmacher-museum-in-hueckelhoven-hilfarth-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culture","item":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/"},{"@type":"ListItem","position":3,"name":"Korbmacher-Museum in H\u00fcckelhoven-Hilfarth"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/128904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/128904\/revisions"}],"predecessor-version":[{"id":128981,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/128904\/revisions\/128981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/107013"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=128904"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/destinations?post=128904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}