{"id":130863,"date":"2026-05-13T01:10:02","date_gmt":"2026-05-12T23:10:02","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/stadtfuehrungen-brueggen\/"},"modified":"2026-05-13T01:10:02","modified_gmt":"2026-05-12T23:10:02","slug":"stadtfuehrungen-brueggen","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stadtfuehrungen-brueggen\/","title":{"rendered":"Stadtf\u00fchrungen &#8211; Br\u00fcggen"},"content":{"rendered":"<p>Stadtf\u00fchrungen in Br\u00fcggen bieten eine fundierte Erkundung des historischen Ortsteils. Die F\u00fchrungen umfassen Kost\u00fcm-, Kinderstadt- und Nachtw\u00e4chterf\u00fchrungen sowie spezielle Kasemattenf\u00fchrungen, die seit 2019 im Programm sind. Diese Touren vermitteln umfassendes Wissen \u00fcber die Geschichte Br\u00fcggens und sind f\u00fcr Gruppen bis zu 25 Personen konzipiert. Die Dauer betr\u00e4gt etwa 60 bis 70 Minuten. Eine Voranmeldung wird empfohlen, um die Teilnahme zu sichern.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stadtf\u00fchrungen in Br\u00fcggen bieten eine fundierte Erkundung des historischen Ortsteils. Die F\u00fchrungen umfassen Kost\u00fcm-, Kinderstadt- und Nachtw\u00e4chterf\u00fchrungen sowie spezielle Kasemattenf\u00fchrungen, die seit 2019 im Programm sind. Diese Touren vermitteln umfassendes Wissen \u00fcber die Geschichte Br\u00fcggens und sind f\u00fcr Gruppen bis zu 25 Personen konzipiert. Die Dauer betr\u00e4gt etwa 60 bis 70 Minuten. Eine Voranmeldung wird [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":98335,"template":"","destinations":[235],"class_list":["post-130863","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-historische-orte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Stadtf\u00fchrungen - Br\u00fcggen - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stadtfuehrungen-brueggen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stadtf\u00fchrungen - Br\u00fcggen - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Stadtf\u00fchrungen in Br\u00fcggen bieten eine fundierte Erkundung des historischen Ortsteils. Die F\u00fchrungen umfassen Kost\u00fcm-, Kinderstadt- und Nachtw\u00e4chterf\u00fchrungen sowie spezielle Kasemattenf\u00fchrungen, die seit 2019 im Programm sind. Diese Touren vermitteln umfassendes Wissen \u00fcber die Geschichte Br\u00fcggens und sind f\u00fcr Gruppen bis zu 25 Personen konzipiert. Die Dauer betr\u00e4gt etwa 60 bis 70 Minuten. Eine Voranmeldung wird [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/stadtf-hrung-br-ggen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2494\" \/>\n\t<meta property=\"og:image:height\" content=\"1662\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stadtfuehrungen-brueggen\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stadtfuehrungen-brueggen\/\",\"name\":\"Stadtf\u00fchrungen - Br\u00fcggen - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-05-12T23:10:02+00:00\",\"dateModified\":\"2026-05-12T23:10:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stadtfuehrungen-brueggen\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stadtfuehrungen-brueggen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stadtfuehrungen-brueggen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Stadtf\u00fchrungen - Br\u00fcggen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stadtf\u00fchrungen - Br\u00fcggen - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stadtfuehrungen-brueggen\/","og_locale":"en_US","og_type":"article","og_title":"Stadtf\u00fchrungen - Br\u00fcggen - Stadt. Land. Niederrhein","og_description":"Stadtf\u00fchrungen in Br\u00fcggen bieten eine fundierte Erkundung des historischen Ortsteils. Die F\u00fchrungen umfassen Kost\u00fcm-, Kinderstadt- und Nachtw\u00e4chterf\u00fchrungen sowie spezielle Kasemattenf\u00fchrungen, die seit 2019 im Programm sind. Diese Touren vermitteln umfassendes Wissen \u00fcber die Geschichte Br\u00fcggens und sind f\u00fcr Gruppen bis zu 25 Personen konzipiert. Die Dauer betr\u00e4gt etwa 60 bis 70 Minuten. Eine Voranmeldung wird [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2494,"height":1662,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/stadtf-hrung-br-ggen.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stadtfuehrungen-brueggen\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stadtfuehrungen-brueggen\/","name":"Stadtf\u00fchrungen - Br\u00fcggen - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-05-12T23:10:02+00:00","dateModified":"2026-05-12T23:10:02+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stadtfuehrungen-brueggen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stadtfuehrungen-brueggen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stadtfuehrungen-brueggen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culture","item":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/"},{"@type":"ListItem","position":3,"name":"Stadtf\u00fchrungen - Br\u00fcggen"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/130863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/130863\/revisions"}],"predecessor-version":[{"id":131060,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/130863\/revisions\/131060"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/98335"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=130863"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/destinations?post=130863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}