{"id":130873,"date":"2026-05-13T01:10:07","date_gmt":"2026-05-12T23:10:07","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/pestkreuz-in-labbeck\/"},"modified":"2026-05-13T01:10:07","modified_gmt":"2026-05-12T23:10:07","slug":"pestkreuz-in-labbeck","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pestkreuz-in-labbeck\/","title":{"rendered":"Pestkreuz in Labbeck"},"content":{"rendered":"<p>Das Pestkreuz in Labbeck, errichtet im Jahr 1628, ist ein bedeutendes Denkmal, das urspr\u00fcnglich in einer Kapelle am Haneshof stand. Seit 1977 ziert es die Marienbaumer Stra\u00dfe, n\u00f6rdlich des Dorfes. Das Kreuz ruht auf einem quadratischen Sockel, aus dem sich eine nach oben verj\u00fcngende S\u00e4ule erhebt, gefertigt aus drei Trommeln unterschiedlicher Gesteinsarten. Ein kunstvolles Kapitell kr\u00f6nt die S\u00e4ule. Die eingravierte Jahreszahl 1628 auf Vorder- und R\u00fcckseite erinnert an seine historische Bedeutung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Pestkreuz in Labbeck, errichtet im Jahr 1628, ist ein bedeutendes Denkmal, das urspr\u00fcnglich in einer Kapelle am Haneshof stand. Seit 1977 ziert es die Marienbaumer Stra\u00dfe, n\u00f6rdlich des Dorfes. Das Kreuz ruht auf einem quadratischen Sockel, aus dem sich eine nach oben verj\u00fcngende S\u00e4ule erhebt, gefertigt aus drei Trommeln unterschiedlicher Gesteinsarten. Ein kunstvolles Kapitell [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":108459,"template":"","destinations":[235],"class_list":["post-130873","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-historische-orte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pestkreuz in Labbeck - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pestkreuz-in-labbeck\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pestkreuz in Labbeck - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Das Pestkreuz in Labbeck, errichtet im Jahr 1628, ist ein bedeutendes Denkmal, das urspr\u00fcnglich in einer Kapelle am Haneshof stand. Seit 1977 ziert es die Marienbaumer Stra\u00dfe, n\u00f6rdlich des Dorfes. Das Kreuz ruht auf einem quadratischen Sockel, aus dem sich eine nach oben verj\u00fcngende S\u00e4ule erhebt, gefertigt aus drei Trommeln unterschiedlicher Gesteinsarten. Ein kunstvolles Kapitell [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/06\/sonsbeck-pestkreuz-labbeck.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pestkreuz-in-labbeck\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pestkreuz-in-labbeck\/\",\"name\":\"Pestkreuz in Labbeck - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-05-12T23:10:07+00:00\",\"dateModified\":\"2026-05-12T23:10:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pestkreuz-in-labbeck\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pestkreuz-in-labbeck\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pestkreuz-in-labbeck\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pestkreuz in Labbeck\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pestkreuz in Labbeck - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pestkreuz-in-labbeck\/","og_locale":"en_US","og_type":"article","og_title":"Pestkreuz in Labbeck - Stadt. Land. Niederrhein","og_description":"Das Pestkreuz in Labbeck, errichtet im Jahr 1628, ist ein bedeutendes Denkmal, das urspr\u00fcnglich in einer Kapelle am Haneshof stand. Seit 1977 ziert es die Marienbaumer Stra\u00dfe, n\u00f6rdlich des Dorfes. Das Kreuz ruht auf einem quadratischen Sockel, aus dem sich eine nach oben verj\u00fcngende S\u00e4ule erhebt, gefertigt aus drei Trommeln unterschiedlicher Gesteinsarten. Ein kunstvolles Kapitell [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":1280,"height":1920,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/06\/sonsbeck-pestkreuz-labbeck.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pestkreuz-in-labbeck\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pestkreuz-in-labbeck\/","name":"Pestkreuz in Labbeck - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-05-12T23:10:07+00:00","dateModified":"2026-05-12T23:10:07+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pestkreuz-in-labbeck\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pestkreuz-in-labbeck\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/pestkreuz-in-labbeck\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culture","item":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/"},{"@type":"ListItem","position":3,"name":"Pestkreuz in Labbeck"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/130873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/130873\/revisions"}],"predecessor-version":[{"id":131070,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/130873\/revisions\/131070"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/108459"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=130873"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/destinations?post=130873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}