{"id":130914,"date":"2026-05-12T02:18:47","date_gmt":"2026-05-12T00:18:47","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/dizeum-dokumentations-und-informationszentrum-ledigenheime\/"},"modified":"2026-05-12T02:18:47","modified_gmt":"2026-05-12T00:18:47","slug":"dizeum-dokumentations-und-informationszentrum-ledigenheime","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/dizeum-dokumentations-und-informationszentrum-ledigenheime\/","title":{"rendered":"DIZeum (Dokumentations- und Informationszentrum Ledigenheime)"},"content":{"rendered":"<p>Das DIZeum, das Dokumentations- und Informationszentrum Ledigenheime, bietet eine umfassende Sammlung zur Geschichte der Ledigenheime. Die Ausstellung erstreckt sich \u00fcber zwei R\u00e4ume und pr\u00e4sentiert auf Schautafeln und in Vitrinen eine Vielzahl an Exponaten. Diese vermitteln nicht nur Informationen zu verschiedenen Aspekten der Ledigenheime, sondern auch biografische Erz\u00e4hlungen von Zeitzeug:innen. Ein besonderes Highlight ist der bergm\u00e4nnische T\u00fcrstock, der besichtigt und durchschritten werden kann. Im Zeitzeugenkino werden auf einem Monitor Erz\u00e4hlungen von Zeitzeug:innen pr\u00e4sentiert. Der angrenzende nachgebaute Wohnraum, der die Wohnsituation um 1920 darstellt, vermittelt die authentische Atmosph\u00e4re eines typischen Ledigenheimzimmers. Hier wird Geschichte auf eindrucksvolle Weise lebendig und greifbar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Ledigenheim der Gartenstadt Lohberg beherbergt seit September 2014 das DIZeum. Dieses Dokumentationszentrum beleuchtet die Industrie- und Sozialgeschichte der Ledigenheime im Ruhrbergbau, einst Unterkunft f\u00fcr Bergleute.<\/p>\n","protected":false},"author":0,"featured_media":98640,"template":"","destinations":[242,170],"class_list":["post-130914","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-kirchen-kloester","destination-museen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>DIZeum (Dokumentations- und Informationszentrum Ledigenheime) - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/dizeum-dokumentations-und-informationszentrum-ledigenheime\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DIZeum (Dokumentations- und Informationszentrum Ledigenheime) - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Das Ledigenheim der Gartenstadt Lohberg beherbergt seit September 2014 das DIZeum. Dieses Dokumentationszentrum beleuchtet die Industrie- und Sozialgeschichte der Ledigenheime im Ruhrbergbau, einst Unterkunft f\u00fcr Bergleute.\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/ausstellungsraum-dizeum.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"274\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/dizeum-dokumentations-und-informationszentrum-ledigenheime\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/dizeum-dokumentations-und-informationszentrum-ledigenheime\/\",\"name\":\"DIZeum (Dokumentations- und Informationszentrum Ledigenheime) - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-05-12T00:18:47+00:00\",\"dateModified\":\"2026-05-12T00:18:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/dizeum-dokumentations-und-informationszentrum-ledigenheime\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/dizeum-dokumentations-und-informationszentrum-ledigenheime\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/dizeum-dokumentations-und-informationszentrum-ledigenheime\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DIZeum (Dokumentations- und Informationszentrum Ledigenheime)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DIZeum (Dokumentations- und Informationszentrum Ledigenheime) - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/dizeum-dokumentations-und-informationszentrum-ledigenheime\/","og_locale":"en_US","og_type":"article","og_title":"DIZeum (Dokumentations- und Informationszentrum Ledigenheime) - Stadt. Land. Niederrhein","og_description":"Das Ledigenheim der Gartenstadt Lohberg beherbergt seit September 2014 das DIZeum. Dieses Dokumentationszentrum beleuchtet die Industrie- und Sozialgeschichte der Ledigenheime im Ruhrbergbau, einst Unterkunft f\u00fcr Bergleute.","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":400,"height":274,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/ausstellungsraum-dizeum.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/dizeum-dokumentations-und-informationszentrum-ledigenheime\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/dizeum-dokumentations-und-informationszentrum-ledigenheime\/","name":"DIZeum (Dokumentations- und Informationszentrum Ledigenheime) - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-05-12T00:18:47+00:00","dateModified":"2026-05-12T00:18:47+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/dizeum-dokumentations-und-informationszentrum-ledigenheime\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kultur\/dizeum-dokumentations-und-informationszentrum-ledigenheime\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/dizeum-dokumentations-und-informationszentrum-ledigenheime\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culture","item":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/"},{"@type":"ListItem","position":3,"name":"DIZeum (Dokumentations- und Informationszentrum Ledigenheime)"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/130914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/130914\/revisions"}],"predecessor-version":[{"id":131111,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/130914\/revisions\/131111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/98640"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=130914"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/destinations?post=130914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}