{"id":131676,"date":"2026-05-13T01:06:54","date_gmt":"2026-05-12T23:06:54","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/zollfeste-zons\/"},"modified":"2026-05-13T01:06:54","modified_gmt":"2026-05-12T23:06:54","slug":"zollfeste-zons","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/zollfeste-zons\/","title":{"rendered":"Zollfeste Zons"},"content":{"rendered":"<p>Die Zollfeste Zons beeindruckt mit ihrem historischen Altstadtkern, der durch markante Bauwerke wie den Rheinturm, den Juddeturm und den M\u00fchlenturm gepr\u00e4gt ist. Der Rheinturm, 1388 als Teil der Stadtbefestigung vollendet, und der Juddeturm mit seiner barocken Haube sind ebenso wie der M\u00fchlenturm, dessen h\u00f6lzernes Mahlwerk aus dem Jahr 1694 stammt, beliebte Fotomotive. Die Stadtmauern und der vorgelagerte Zwinger, der sich parallel zur Mauer erstreckt, unterstreichen die mittelalterliche Atmosph\u00e4re. Im Zentrum von Zons befindet sich die ehemalige kurk\u00f6lnische Landesburg Friedestrom, heute ein Kulturzentrum mit Kreismuseum, Kreisarchiv und Mundartarchiv. J\u00e4hrlich ziehen Veranstaltungen wie der Matth\u00e4usmarkt, M\u00e4rchenspiele, Kunstm\u00e4rkte und das Sch\u00fctzenfest zahlreiche Besucher:innen an. Ein Kinderspielplatz im Freien erg\u00e4nzt das Angebot f\u00fcr Familien. Die Zollfeste Zons bietet somit ein vielf\u00e4ltiges Erlebnis, das Geschichte und Kultur auf eindrucksvolle Weise erlebbar macht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Zollfeste Zons beeindruckt mit ihrem historischen Altstadtkern, der durch markante Bauwerke wie den Rheinturm, den Juddeturm und den M\u00fchlenturm gepr\u00e4gt ist. Der Rheinturm, 1388 als Teil der Stadtbefestigung vollendet, und der Juddeturm mit seiner barocken Haube sind ebenso wie der M\u00fchlenturm, dessen h\u00f6lzernes Mahlwerk aus dem Jahr 1694 stammt, beliebte Fotomotive. Die Stadtmauern und [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":7843,"template":"","destinations":[235],"class_list":["post-131676","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-historische-orte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Zollfeste Zons - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/zollfeste-zons\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zollfeste Zons - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Die Zollfeste Zons beeindruckt mit ihrem historischen Altstadtkern, der durch markante Bauwerke wie den Rheinturm, den Juddeturm und den M\u00fchlenturm gepr\u00e4gt ist. Der Rheinturm, 1388 als Teil der Stadtbefestigung vollendet, und der Juddeturm mit seiner barocken Haube sind ebenso wie der M\u00fchlenturm, dessen h\u00f6lzernes Mahlwerk aus dem Jahr 1694 stammt, beliebte Fotomotive. Die Stadtmauern und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/08\/radfahrer-im-schlossgarten-der-zollfeste-zons-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/zollfeste-zons\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/zollfeste-zons\/\",\"name\":\"Zollfeste Zons - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-05-12T23:06:54+00:00\",\"dateModified\":\"2026-05-12T23:06:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/zollfeste-zons\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/zollfeste-zons\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/zollfeste-zons\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zollfeste Zons\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zollfeste Zons - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/zollfeste-zons\/","og_locale":"en_US","og_type":"article","og_title":"Zollfeste Zons - Stadt. Land. Niederrhein","og_description":"Die Zollfeste Zons beeindruckt mit ihrem historischen Altstadtkern, der durch markante Bauwerke wie den Rheinturm, den Juddeturm und den M\u00fchlenturm gepr\u00e4gt ist. Der Rheinturm, 1388 als Teil der Stadtbefestigung vollendet, und der Juddeturm mit seiner barocken Haube sind ebenso wie der M\u00fchlenturm, dessen h\u00f6lzernes Mahlwerk aus dem Jahr 1694 stammt, beliebte Fotomotive. Die Stadtmauern und [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2560,"height":1707,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/08\/radfahrer-im-schlossgarten-der-zollfeste-zons-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/zollfeste-zons\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/zollfeste-zons\/","name":"Zollfeste Zons - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-05-12T23:06:54+00:00","dateModified":"2026-05-12T23:06:54+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/zollfeste-zons\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kultur\/zollfeste-zons\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/zollfeste-zons\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culture","item":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/"},{"@type":"ListItem","position":3,"name":"Zollfeste Zons"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/131676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/131676\/revisions"}],"predecessor-version":[{"id":131755,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/131676\/revisions\/131755"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/7843"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=131676"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/destinations?post=131676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}