{"id":131736,"date":"2026-05-12T02:18:38","date_gmt":"2026-05-12T00:18:38","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/stifts-und-propsteikirche-st-mariae-himmelfahrt\/"},"modified":"2026-05-12T02:18:38","modified_gmt":"2026-05-12T00:18:38","slug":"stifts-und-propsteikirche-st-mariae-himmelfahrt","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stifts-und-propsteikirche-st-mariae-himmelfahrt\/","title":{"rendered":"Stifts- und Propsteikirche St. Mari\u00e4 Himmelfahrt"},"content":{"rendered":"<p>Die Stifts- und Propsteikirche St. Mari\u00e4 Himmelfahrt in Kleve, deren Urspr\u00fcnge auf das Jahr 1341 zur\u00fcckgehen, wurde von Graf Dietrich IX. initiiert, um das Stift Monterberg zu verlegen und die alte Johanniskirche zu ersetzen. Nach der Zerst\u00f6rung im Zweiten Weltkrieg begann 1951 der Wiederaufbau. Heute beeindruckt die Kirche mit ihren imposanten Trachytpfeilern, die das Gew\u00f6lbe tragen, und dem Kreuzaltar aus dem 16. Jahrhundert, gefertigt in Antwerpen. Der restaurierte Marienaltar im Hochchor von H. Douverman, das Epitaph im rechten Seitenschiff, die Herzogsgruft und der Zelebrationsaltar sind ebenfalls von besonderem Interesse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Stifts- und Propsteikirche St. Mari\u00e4 Himmelfahrt in Kleve, deren Urspr\u00fcnge auf das Jahr 1341 zur\u00fcckgehen, wurde von Graf Dietrich IX. initiiert, um das Stift Monterberg zu verlegen und die alte Johanniskirche zu ersetzen. Nach der Zerst\u00f6rung im Zweiten Weltkrieg begann 1951 der Wiederaufbau. Heute beeindruckt die Kirche mit ihren imposanten Trachytpfeilern, die das Gew\u00f6lbe [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":101448,"template":"","destinations":[242],"class_list":["post-131736","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-kirchen-kloester"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Stifts- und Propsteikirche St. Mari\u00e4 Himmelfahrt - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stifts-und-propsteikirche-st-mariae-himmelfahrt\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stifts- und Propsteikirche St. Mari\u00e4 Himmelfahrt - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Die Stifts- und Propsteikirche St. Mari\u00e4 Himmelfahrt in Kleve, deren Urspr\u00fcnge auf das Jahr 1341 zur\u00fcckgehen, wurde von Graf Dietrich IX. initiiert, um das Stift Monterberg zu verlegen und die alte Johanniskirche zu ersetzen. Nach der Zerst\u00f6rung im Zweiten Weltkrieg begann 1951 der Wiederaufbau. Heute beeindruckt die Kirche mit ihren imposanten Trachytpfeilern, die das Gew\u00f6lbe [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/03\/stiftskirche-und-narrenbrunnen-in-kleve.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stifts-und-propsteikirche-st-mariae-himmelfahrt\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stifts-und-propsteikirche-st-mariae-himmelfahrt\/\",\"name\":\"Stifts- und Propsteikirche St. Mari\u00e4 Himmelfahrt - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-05-12T00:18:38+00:00\",\"dateModified\":\"2026-05-12T00:18:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stifts-und-propsteikirche-st-mariae-himmelfahrt\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stifts-und-propsteikirche-st-mariae-himmelfahrt\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stifts-und-propsteikirche-st-mariae-himmelfahrt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Stifts- und Propsteikirche St. Mari\u00e4 Himmelfahrt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stifts- und Propsteikirche St. Mari\u00e4 Himmelfahrt - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stifts-und-propsteikirche-st-mariae-himmelfahrt\/","og_locale":"en_US","og_type":"article","og_title":"Stifts- und Propsteikirche St. Mari\u00e4 Himmelfahrt - Stadt. Land. Niederrhein","og_description":"Die Stifts- und Propsteikirche St. Mari\u00e4 Himmelfahrt in Kleve, deren Urspr\u00fcnge auf das Jahr 1341 zur\u00fcckgehen, wurde von Graf Dietrich IX. initiiert, um das Stift Monterberg zu verlegen und die alte Johanniskirche zu ersetzen. Nach der Zerst\u00f6rung im Zweiten Weltkrieg begann 1951 der Wiederaufbau. Heute beeindruckt die Kirche mit ihren imposanten Trachytpfeilern, die das Gew\u00f6lbe [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2048,"height":1536,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/03\/stiftskirche-und-narrenbrunnen-in-kleve.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stifts-und-propsteikirche-st-mariae-himmelfahrt\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stifts-und-propsteikirche-st-mariae-himmelfahrt\/","name":"Stifts- und Propsteikirche St. Mari\u00e4 Himmelfahrt - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-05-12T00:18:38+00:00","dateModified":"2026-05-12T00:18:38+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stifts-und-propsteikirche-st-mariae-himmelfahrt\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stifts-und-propsteikirche-st-mariae-himmelfahrt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/stifts-und-propsteikirche-st-mariae-himmelfahrt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culture","item":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/"},{"@type":"ListItem","position":3,"name":"Stifts- und Propsteikirche St. Mari\u00e4 Himmelfahrt"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/131736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/131736\/revisions"}],"predecessor-version":[{"id":131816,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/131736\/revisions\/131816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/101448"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=131736"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/destinations?post=131736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}