{"id":131931,"date":"2026-09-02T02:03:39","date_gmt":"2026-09-02T00:03:39","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/muenster-basilika-st-vitus-westportal\/"},"modified":"2026-09-02T02:03:39","modified_gmt":"2026-09-02T00:03:39","slug":"muenster-basilika-st-vitus-westportal","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muenster-basilika-st-vitus-westportal\/","title":{"rendered":"M\u00fcnster Basilika St. Vitus, Westportal"},"content":{"rendered":"<p>Von 974 bis 1802 diente das M\u00fcnster als Abteikirche der Benediktinerabtei Gladbach. 1974 wurde es von Papst Paul VI. zur p\u00e4pstlichen Basilika minor erhoben, anl\u00e4sslich des 84. Deutschen Katholikentages und der 1000-Jahr-Feier der Abteigr\u00fcndung. Das M\u00fcnster ist ein bedeutendes Wahrzeichen M\u00f6nchengladbachs. Besonders beeindruckend ist der Blick vom Abteiberg, der eine weite Sicht \u00fcber die Stadt, den Geroweiher, die Stadtmauer und die historische H\u00e4userzeile entlang der Weiherstra\u00dfe bietet. Abends wird die Szenerie stimmungsvoll beleuchtet, was den Besuch zu einem besonderen Erlebnis macht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von 974 bis 1802 diente das M\u00fcnster als Abteikirche der Benediktinerabtei Gladbach. 1974 wurde es von Papst Paul VI. zur p\u00e4pstlichen Basilika minor erhoben, anl\u00e4sslich des 84. Deutschen Katholikentages und der 1000-Jahr-Feier der Abteigr\u00fcndung. Das M\u00fcnster ist ein bedeutendes Wahrzeichen M\u00f6nchengladbachs. Besonders beeindruckend ist der Blick vom Abteiberg, der eine weite Sicht \u00fcber die Stadt, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":100868,"template":"","destinations":[242],"class_list":["post-131931","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-kirchen-kloester"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00fcnster Basilika St. Vitus, Westportal - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muenster-basilika-st-vitus-westportal\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00fcnster Basilika St. Vitus, Westportal - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Von 974 bis 1802 diente das M\u00fcnster als Abteikirche der Benediktinerabtei Gladbach. 1974 wurde es von Papst Paul VI. zur p\u00e4pstlichen Basilika minor erhoben, anl\u00e4sslich des 84. Deutschen Katholikentages und der 1000-Jahr-Feier der Abteigr\u00fcndung. Das M\u00fcnster ist ein bedeutendes Wahrzeichen M\u00f6nchengladbachs. Besonders beeindruckend ist der Blick vom Abteiberg, der eine weite Sicht \u00fcber die Stadt, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/m-nster-st-vitus.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muenster-basilika-st-vitus-westportal\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muenster-basilika-st-vitus-westportal\/\",\"name\":\"M\u00fcnster Basilika St. Vitus, Westportal - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-09-02T00:03:39+00:00\",\"dateModified\":\"2026-09-02T00:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muenster-basilika-st-vitus-westportal\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muenster-basilika-st-vitus-westportal\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muenster-basilika-st-vitus-westportal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"M\u00fcnster Basilika St. Vitus, Westportal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00fcnster Basilika St. Vitus, Westportal - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muenster-basilika-st-vitus-westportal\/","og_locale":"en_US","og_type":"article","og_title":"M\u00fcnster Basilika St. Vitus, Westportal - Stadt. Land. Niederrhein","og_description":"Von 974 bis 1802 diente das M\u00fcnster als Abteikirche der Benediktinerabtei Gladbach. 1974 wurde es von Papst Paul VI. zur p\u00e4pstlichen Basilika minor erhoben, anl\u00e4sslich des 84. Deutschen Katholikentages und der 1000-Jahr-Feier der Abteigr\u00fcndung. Das M\u00fcnster ist ein bedeutendes Wahrzeichen M\u00f6nchengladbachs. Besonders beeindruckend ist der Blick vom Abteiberg, der eine weite Sicht \u00fcber die Stadt, [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2048,"height":1536,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/m-nster-st-vitus.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muenster-basilika-st-vitus-westportal\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muenster-basilika-st-vitus-westportal\/","name":"M\u00fcnster Basilika St. Vitus, Westportal - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-09-02T00:03:39+00:00","dateModified":"2026-09-02T00:03:39+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muenster-basilika-st-vitus-westportal\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muenster-basilika-st-vitus-westportal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/muenster-basilika-st-vitus-westportal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culture","item":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/"},{"@type":"ListItem","position":3,"name":"M\u00fcnster Basilika St. Vitus, Westportal"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/131931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/131931\/revisions"}],"predecessor-version":[{"id":131998,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/131931\/revisions\/131998"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/100868"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=131931"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/destinations?post=131931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}