{"id":131933,"date":"2026-05-12T02:17:08","date_gmt":"2026-05-12T00:17:08","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/altes-zeughaus-karnevalsmuseum\/"},"modified":"2026-05-12T02:17:08","modified_gmt":"2026-05-12T00:17:08","slug":"altes-zeughaus-karnevalsmuseum","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/altes-zeughaus-karnevalsmuseum\/","title":{"rendered":"Altes Zeughaus \u2013 Karnevalsmuseum"},"content":{"rendered":"<p>Das Karnevalsmuseum im Alten Zeughaus, er\u00f6ffnet 2002, bietet eine umfassende Sammlung von Uniformen, Kost\u00fcmen, Orden und weiteren Karnevalsutensilien, die vom Verein Altes Zeughaus e.V. liebevoll zusammengetragen wurden. Es befindet sich in der Innenstadt von M\u00f6nchengladbach, unweit des Alten Marktes. Besucher:innen erhalten Einblicke in die Traditionen und die Bedeutung des Karnevals sowie in die Stadtgeschichte. Das Museum ist ein bedeutender Ort, um die kulturellen Wurzeln und die lebendige Praxis der &#8220;f\u00fcnften Jahreszeit&#8221; zu erkunden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Karnevalsmuseum im Alten Zeughaus, er\u00f6ffnet 2002, bietet eine umfassende Sammlung von Uniformen, Kost\u00fcmen, Orden und weiteren Karnevalsutensilien, die vom Verein Altes Zeughaus e.V. liebevoll zusammengetragen wurden. Es befindet sich in der Innenstadt von M\u00f6nchengladbach, unweit des Alten Marktes. Besucher:innen erhalten Einblicke in die Traditionen und die Bedeutung des Karnevals sowie in die Stadtgeschichte. Das [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":100054,"template":"","destinations":[235,170],"class_list":["post-131933","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-historische-orte","destination-museen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Altes Zeughaus \u2013 Karnevalsmuseum - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/altes-zeughaus-karnevalsmuseum\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Altes Zeughaus \u2013 Karnevalsmuseum - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Das Karnevalsmuseum im Alten Zeughaus, er\u00f6ffnet 2002, bietet eine umfassende Sammlung von Uniformen, Kost\u00fcmen, Orden und weiteren Karnevalsutensilien, die vom Verein Altes Zeughaus e.V. liebevoll zusammengetragen wurden. Es befindet sich in der Innenstadt von M\u00f6nchengladbach, unweit des Alten Marktes. Besucher:innen erhalten Einblicke in die Traditionen und die Bedeutung des Karnevals sowie in die Stadtgeschichte. Das [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/altes-zeughaus-karnevalsmuseum.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1463\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/altes-zeughaus-karnevalsmuseum\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/altes-zeughaus-karnevalsmuseum\/\",\"name\":\"Altes Zeughaus \u2013 Karnevalsmuseum - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-05-12T00:17:08+00:00\",\"dateModified\":\"2026-05-12T00:17:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/altes-zeughaus-karnevalsmuseum\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/altes-zeughaus-karnevalsmuseum\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/altes-zeughaus-karnevalsmuseum\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Altes Zeughaus \u2013 Karnevalsmuseum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Altes Zeughaus \u2013 Karnevalsmuseum - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/altes-zeughaus-karnevalsmuseum\/","og_locale":"en_US","og_type":"article","og_title":"Altes Zeughaus \u2013 Karnevalsmuseum - Stadt. Land. Niederrhein","og_description":"Das Karnevalsmuseum im Alten Zeughaus, er\u00f6ffnet 2002, bietet eine umfassende Sammlung von Uniformen, Kost\u00fcmen, Orden und weiteren Karnevalsutensilien, die vom Verein Altes Zeughaus e.V. liebevoll zusammengetragen wurden. Es befindet sich in der Innenstadt von M\u00f6nchengladbach, unweit des Alten Marktes. Besucher:innen erhalten Einblicke in die Traditionen und die Bedeutung des Karnevals sowie in die Stadtgeschichte. Das [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2048,"height":1463,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/altes-zeughaus-karnevalsmuseum.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/altes-zeughaus-karnevalsmuseum\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/altes-zeughaus-karnevalsmuseum\/","name":"Altes Zeughaus \u2013 Karnevalsmuseum - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-05-12T00:17:08+00:00","dateModified":"2026-05-12T00:17:08+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/altes-zeughaus-karnevalsmuseum\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kultur\/altes-zeughaus-karnevalsmuseum\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/altes-zeughaus-karnevalsmuseum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culture","item":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/"},{"@type":"ListItem","position":3,"name":"Altes Zeughaus \u2013 Karnevalsmuseum"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/131933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/131933\/revisions"}],"predecessor-version":[{"id":132002,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/131933\/revisions\/132002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/100054"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=131933"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/destinations?post=131933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}