{"id":131935,"date":"2026-05-12T02:17:08","date_gmt":"2026-05-12T00:17:08","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/das-textiltechnikum-im-monforts-quartier\/"},"modified":"2026-05-12T02:17:08","modified_gmt":"2026-05-12T00:17:08","slug":"das-textiltechnikum-im-monforts-quartier","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/en\/cultuur\/das-textiltechnikum-im-monforts-quartier\/","title":{"rendered":"Das TextilTechnikum im Monforts Quartier"},"content":{"rendered":"<p>Das TextilTechnikum im Monforts Quartier in M\u00f6nchengladbach bietet eine beeindruckende Sammlung historischer und moderner Textiltechnik. Seit Jahren werden hier Webst\u00fchle, Spinnmaschinen und weitere Ger\u00e4tschaften aus alten Fabriken zusammengetragen. Diese international einzigartige Sammlung legt den Fokus auf die Weberei und zeigt die Entwicklung von den \u00e4ltesten Webst\u00fchlen bis zur modernen Luftd\u00fcsentechnik. In der ehemaligen Textilmaschinenfabrik werden die Zeugnisse der textilen Vergangenheit M\u00f6nchengladbachs bewahrt, restauriert und der \u00d6ffentlichkeit zug\u00e4nglich gemacht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das TextilTechnikum im Monforts Quartier in M\u00f6nchengladbach bietet eine beeindruckende Sammlung historischer und moderner Textiltechnik. Seit Jahren werden hier Webst\u00fchle, Spinnmaschinen und weitere Ger\u00e4tschaften aus alten Fabriken zusammengetragen. Diese international einzigartige Sammlung legt den Fokus auf die Weberei und zeigt die Entwicklung von den \u00e4ltesten Webst\u00fchlen bis zur modernen Luftd\u00fcsentechnik. In der ehemaligen Textilmaschinenfabrik werden [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":100203,"template":"","destinations":[242,170],"class_list":["post-131935","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-kirchen-kloester","destination-museen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Das TextilTechnikum im Monforts Quartier - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/cultuur\/das-textiltechnikum-im-monforts-quartier\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Das TextilTechnikum im Monforts Quartier - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Das TextilTechnikum im Monforts Quartier in M\u00f6nchengladbach bietet eine beeindruckende Sammlung historischer und moderner Textiltechnik. Seit Jahren werden hier Webst\u00fchle, Spinnmaschinen und weitere Ger\u00e4tschaften aus alten Fabriken zusammengetragen. Diese international einzigartige Sammlung legt den Fokus auf die Weberei und zeigt die Entwicklung von den \u00e4ltesten Webst\u00fchlen bis zur modernen Luftd\u00fcsentechnik. In der ehemaligen Textilmaschinenfabrik werden [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/eingang-museum-textiltechnikum.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1214\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/cultuur\/das-textiltechnikum-im-monforts-quartier\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/cultuur\/das-textiltechnikum-im-monforts-quartier\/\",\"name\":\"Das TextilTechnikum im Monforts Quartier - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-05-12T00:17:08+00:00\",\"dateModified\":\"2026-05-12T00:17:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/cultuur\/das-textiltechnikum-im-monforts-quartier\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/cultuur\/das-textiltechnikum-im-monforts-quartier\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/cultuur\/das-textiltechnikum-im-monforts-quartier\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Das TextilTechnikum im Monforts Quartier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Das TextilTechnikum im Monforts Quartier - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/cultuur\/das-textiltechnikum-im-monforts-quartier\/","og_locale":"en_US","og_type":"article","og_title":"Das TextilTechnikum im Monforts Quartier - Stadt. Land. Niederrhein","og_description":"Das TextilTechnikum im Monforts Quartier in M\u00f6nchengladbach bietet eine beeindruckende Sammlung historischer und moderner Textiltechnik. Seit Jahren werden hier Webst\u00fchle, Spinnmaschinen und weitere Ger\u00e4tschaften aus alten Fabriken zusammengetragen. Diese international einzigartige Sammlung legt den Fokus auf die Weberei und zeigt die Entwicklung von den \u00e4ltesten Webst\u00fchlen bis zur modernen Luftd\u00fcsentechnik. In der ehemaligen Textilmaschinenfabrik werden [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2048,"height":1214,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/eingang-museum-textiltechnikum.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/cultuur\/das-textiltechnikum-im-monforts-quartier\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/cultuur\/das-textiltechnikum-im-monforts-quartier\/","name":"Das TextilTechnikum im Monforts Quartier - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-05-12T00:17:08+00:00","dateModified":"2026-05-12T00:17:08+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/cultuur\/das-textiltechnikum-im-monforts-quartier\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/cultuur\/das-textiltechnikum-im-monforts-quartier\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/cultuur\/das-textiltechnikum-im-monforts-quartier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culture","item":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/"},{"@type":"ListItem","position":3,"name":"Das TextilTechnikum im Monforts Quartier"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/131935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/131935\/revisions"}],"predecessor-version":[{"id":132004,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/131935\/revisions\/132004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/100203"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=131935"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/destinations?post=131935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}