{"id":133011,"date":"2026-09-02T01:36:48","date_gmt":"2026-09-01T23:36:48","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/wasserschloss-haus-voerde\/"},"modified":"2026-09-02T01:36:48","modified_gmt":"2026-09-01T23:36:48","slug":"wasserschloss-haus-voerde","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/wasserschloss-haus-voerde\/","title":{"rendered":"Wasserschloss &#8220;Haus Voerde&#8221;"},"content":{"rendered":"<p>Das Wasserschloss &#8220;Haus Voerde&#8221; ist ein bedeutendes historisches Bauwerk in der Stadt Voerde. Urspr\u00fcnglich befand sich hier ein Wirtschaftshof der Abtei Werden, der erstmals 1344 urkundlich erw\u00e4hnt wurde. Im Laufe der Jahrhunderte erlebte das Schloss zahlreiche Besitzerwechsel und bauliche Ver\u00e4nderungen. 1486 erwarb Jakob von der Kapellen das Anwesen, und 1563 gelangte es durch Heirat in den Besitz der Familie von Syberg. Diese pr\u00e4gte die Geschichte des Schlosses \u00fcber zwei Jahrhunderte hinweg. Im Achtzigj\u00e4hrigen Krieg wurde das Schloss 1596 von spanischen Truppen gepl\u00fcndert und besch\u00e4digt. 1668 errichteten die von Sybergs zwei T\u00fcrme, die die Bedeutung der Familie symbolisierten. Nach wirtschaftlichen Schwierigkeiten wurde das Schloss 1809 an den Freiherrn zu Wittenhorst-Sonsfeld verkauft, der es im sp\u00e4tklassizistischen Stil umgestaltete. Die Vorburg wurde im 20. Jahrhundert abgerissen, doch Natursteine markieren heute ihre Lage. Seit 1922 geh\u00f6rt das Anwesen der Gemeinde Voerde. Haus Voerde ist Teil des Geschichtspfades des Heimatvereins Voerde, der die historische Bedeutung des Ortes hervorhebt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Wasserschloss &#8220;Haus Voerde&#8221; ist ein bedeutendes historisches Bauwerk in der Stadt Voerde. Urspr\u00fcnglich befand sich hier ein Wirtschaftshof der Abtei Werden, der erstmals 1344 urkundlich erw\u00e4hnt wurde. Im Laufe der Jahrhunderte erlebte das Schloss zahlreiche Besitzerwechsel und bauliche Ver\u00e4nderungen. 1486 erwarb Jakob von der Kapellen das Anwesen, und 1563 gelangte es durch Heirat in [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":132832,"template":"","destinations":[171],"class_list":["post-133011","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-burgen-schloesser"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wasserschloss &quot;Haus Voerde&quot; - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/wasserschloss-haus-voerde\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wasserschloss &quot;Haus Voerde&quot; - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Das Wasserschloss &#8220;Haus Voerde&#8221; ist ein bedeutendes historisches Bauwerk in der Stadt Voerde. Urspr\u00fcnglich befand sich hier ein Wirtschaftshof der Abtei Werden, der erstmals 1344 urkundlich erw\u00e4hnt wurde. Im Laufe der Jahrhunderte erlebte das Schloss zahlreiche Besitzerwechsel und bauliche Ver\u00e4nderungen. 1486 erwarb Jakob von der Kapellen das Anwesen, und 1563 gelangte es durch Heirat in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2026\/05\/drohnenbild-von-haus-voerde.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/wasserschloss-haus-voerde\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/wasserschloss-haus-voerde\/\",\"name\":\"Wasserschloss \\\"Haus Voerde\\\" - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-09-01T23:36:48+00:00\",\"dateModified\":\"2026-09-01T23:36:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/wasserschloss-haus-voerde\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/wasserschloss-haus-voerde\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/wasserschloss-haus-voerde\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wasserschloss \\\"Haus Voerde\\\"\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wasserschloss \"Haus Voerde\" - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/wasserschloss-haus-voerde\/","og_locale":"en_US","og_type":"article","og_title":"Wasserschloss \"Haus Voerde\" - Stadt. Land. Niederrhein","og_description":"Das Wasserschloss &#8220;Haus Voerde&#8221; ist ein bedeutendes historisches Bauwerk in der Stadt Voerde. Urspr\u00fcnglich befand sich hier ein Wirtschaftshof der Abtei Werden, der erstmals 1344 urkundlich erw\u00e4hnt wurde. Im Laufe der Jahrhunderte erlebte das Schloss zahlreiche Besitzerwechsel und bauliche Ver\u00e4nderungen. 1486 erwarb Jakob von der Kapellen das Anwesen, und 1563 gelangte es durch Heirat in [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2048,"height":1152,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2026\/05\/drohnenbild-von-haus-voerde.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/wasserschloss-haus-voerde\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/wasserschloss-haus-voerde\/","name":"Wasserschloss \"Haus Voerde\" - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-09-01T23:36:48+00:00","dateModified":"2026-09-01T23:36:48+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/wasserschloss-haus-voerde\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kultur\/wasserschloss-haus-voerde\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/wasserschloss-haus-voerde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culture","item":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/"},{"@type":"ListItem","position":3,"name":"Wasserschloss \"Haus Voerde\""}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/133011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/133011\/revisions"}],"predecessor-version":[{"id":133243,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/133011\/revisions\/133243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/132832"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=133011"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/destinations?post=133011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}