{"id":133014,"date":"2026-09-02T02:03:07","date_gmt":"2026-09-02T00:03:07","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/ehemalige-reformierte-kirche\/"},"modified":"2026-09-02T02:03:07","modified_gmt":"2026-09-02T00:03:07","slug":"ehemalige-reformierte-kirche","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehemalige-reformierte-kirche\/","title":{"rendered":"Ehemalige reformierte Kirche"},"content":{"rendered":"<p>Die ehemalige reformierte Kirche in Schermbeck ist ein bemerkenswertes Beispiel f\u00fcr die vielseitige Nutzung historischer Geb\u00e4ude. Urspr\u00fcnglich in der zweiten H\u00e4lfte des 17. Jahrhunderts errichtet, wurde der achteckige Zentralbau 1786 eingeweiht. Nach der letzten Predigt am 24. Oktober 1830 zogen die Gl\u00e4ubigen in die benachbarte Georgskirche um. Der barocke Bau diente daraufhin 85 Jahre lang als Schulgeb\u00e4ude. Nach einer umfassenden Renovierung wurde am 1. Juni 1956 eine Zweigstelle der Kreisb\u00fccherei er\u00f6ffnet, die 1975 zur Kommunalb\u00fccherei ausgebaut wurde. Aufgrund von Platzmangel entstand im Zuge der Planungen f\u00fcr ein neues Rathaus ein Anbau f\u00fcr die B\u00fccherei, die am 1. Oktober 1996 bezogen wurde. Seit 2004, nach einer weiteren Renovierung, fungiert die ehemalige Kirche als Kulturstube und bietet Raum f\u00fcr vielf\u00e4ltige Veranstaltungen. Dieses historische Geb\u00e4ude vereint architektonische Eleganz mit kultureller Bedeutung und ist ein fester Bestandteil des kulturellen Lebens in Schermbeck.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der achteckige Zentralbau, 1786 fertiggestellt, dient heute aufgrund seiner klanglichen Eigenschaften kulturellen Veranstaltungen und wird ebenso f\u00fcr Trauzeremonien genutzt.<\/p>\n","protected":false},"author":0,"featured_media":100498,"template":"","destinations":[171,242],"class_list":["post-133014","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-burgen-schloesser","destination-kirchen-kloester"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ehemalige reformierte Kirche - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehemalige-reformierte-kirche\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ehemalige reformierte Kirche - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Der achteckige Zentralbau, 1786 fertiggestellt, dient heute aufgrund seiner klanglichen Eigenschaften kulturellen Veranstaltungen und wird ebenso f\u00fcr Trauzeremonien genutzt.\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/ehemalige-reformierte-kirche-schermbeck-oberer-bereich.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehemalige-reformierte-kirche\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehemalige-reformierte-kirche\/\",\"name\":\"Ehemalige reformierte Kirche - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-09-02T00:03:07+00:00\",\"dateModified\":\"2026-09-02T00:03:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehemalige-reformierte-kirche\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehemalige-reformierte-kirche\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehemalige-reformierte-kirche\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ehemalige reformierte Kirche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ehemalige reformierte Kirche - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehemalige-reformierte-kirche\/","og_locale":"en_US","og_type":"article","og_title":"Ehemalige reformierte Kirche - Stadt. Land. Niederrhein","og_description":"Der achteckige Zentralbau, 1786 fertiggestellt, dient heute aufgrund seiner klanglichen Eigenschaften kulturellen Veranstaltungen und wird ebenso f\u00fcr Trauzeremonien genutzt.","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":1920,"height":1280,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/ehemalige-reformierte-kirche-schermbeck-oberer-bereich.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehemalige-reformierte-kirche\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehemalige-reformierte-kirche\/","name":"Ehemalige reformierte Kirche - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-09-02T00:03:07+00:00","dateModified":"2026-09-02T00:03:07+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehemalige-reformierte-kirche\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehemalige-reformierte-kirche\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehemalige-reformierte-kirche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culture","item":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/"},{"@type":"ListItem","position":3,"name":"Ehemalige reformierte Kirche"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/133014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/133014\/revisions"}],"predecessor-version":[{"id":133237,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/133014\/revisions\/133237"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/100498"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=133014"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/destinations?post=133014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}