{"id":133021,"date":"2026-09-02T01:37:55","date_gmt":"2026-09-01T23:37:55","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/ehrenmal-altschermbeck\/"},"modified":"2026-09-02T01:37:55","modified_gmt":"2026-09-01T23:37:55","slug":"ehrenmal-altschermbeck","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehrenmal-altschermbeck\/","title":{"rendered":"Ehrenmal Altschermbeck"},"content":{"rendered":"<p>Das Ehrenmal Altschermbeck, ein bedeutendes Denkmal, erinnert an die Gefallenen der Weltkriege. Urspr\u00fcnglich errichtet, um den Opfern des Ersten Weltkriegs zu gedenken, wurde es 1953 durch ein neues Denkmal ersetzt, da das urspr\u00fcngliche stark verwittert war. Die St. Georgsstatue, flankiert von den Namen der Opfer beider Weltkriege, steht im Zentrum. Dieses Ehrenmal dient nicht nur als historisches Zeugnis, sondern auch als mahnendes Symbol f\u00fcr verantwortungsvolles Handeln in der Zukunft.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Ehrenmal Altschermbeck, ein bedeutendes Denkmal, erinnert an die Gefallenen der Weltkriege. Urspr\u00fcnglich errichtet, um den Opfern des Ersten Weltkriegs zu gedenken, wurde es 1953 durch ein neues Denkmal ersetzt, da das urspr\u00fcngliche stark verwittert war. Die St. Georgsstatue, flankiert von den Namen der Opfer beider Weltkriege, steht im Zentrum. Dieses Ehrenmal dient nicht nur [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":125844,"template":"","destinations":[235,170],"class_list":["post-133021","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-historische-orte","destination-museen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ehrenmal Altschermbeck - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehrenmal-altschermbeck\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ehrenmal Altschermbeck - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Das Ehrenmal Altschermbeck, ein bedeutendes Denkmal, erinnert an die Gefallenen der Weltkriege. Urspr\u00fcnglich errichtet, um den Opfern des Ersten Weltkriegs zu gedenken, wurde es 1953 durch ein neues Denkmal ersetzt, da das urspr\u00fcngliche stark verwittert war. Die St. Georgsstatue, flankiert von den Namen der Opfer beider Weltkriege, steht im Zentrum. Dieses Ehrenmal dient nicht nur [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/12\/altschermbeck1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2449\" \/>\n\t<meta property=\"og:image:height\" content=\"1632\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehrenmal-altschermbeck\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehrenmal-altschermbeck\/\",\"name\":\"Ehrenmal Altschermbeck - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-09-01T23:37:55+00:00\",\"dateModified\":\"2026-09-01T23:37:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehrenmal-altschermbeck\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehrenmal-altschermbeck\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehrenmal-altschermbeck\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ehrenmal Altschermbeck\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ehrenmal Altschermbeck - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehrenmal-altschermbeck\/","og_locale":"en_US","og_type":"article","og_title":"Ehrenmal Altschermbeck - Stadt. Land. Niederrhein","og_description":"Das Ehrenmal Altschermbeck, ein bedeutendes Denkmal, erinnert an die Gefallenen der Weltkriege. Urspr\u00fcnglich errichtet, um den Opfern des Ersten Weltkriegs zu gedenken, wurde es 1953 durch ein neues Denkmal ersetzt, da das urspr\u00fcngliche stark verwittert war. Die St. Georgsstatue, flankiert von den Namen der Opfer beider Weltkriege, steht im Zentrum. Dieses Ehrenmal dient nicht nur [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2449,"height":1632,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/12\/altschermbeck1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehrenmal-altschermbeck\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehrenmal-altschermbeck\/","name":"Ehrenmal Altschermbeck - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-09-01T23:37:55+00:00","dateModified":"2026-09-01T23:37:55+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehrenmal-altschermbeck\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehrenmal-altschermbeck\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/ehrenmal-altschermbeck\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culture","item":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/"},{"@type":"ListItem","position":3,"name":"Ehrenmal Altschermbeck"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/133021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/133021\/revisions"}],"predecessor-version":[{"id":133188,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/133021\/revisions\/133188"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/125844"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=133021"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/destinations?post=133021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}