{"id":134780,"date":"2026-09-02T02:03:08","date_gmt":"2026-09-02T00:03:08","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/museum-rund-ums-geld\/"},"modified":"2026-09-02T02:03:08","modified_gmt":"2026-09-02T00:03:08","slug":"museum-rund-ums-geld","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/museum-rund-ums-geld\/","title":{"rendered":"Museum rund ums Geld"},"content":{"rendered":"<p>Das Museum rund ums Geld in Xanten bietet auf 340 Quadratmetern eine umfassende Darstellung der Geldgeschichte. Tr\u00e4ger ist der Geldgeschichtliche Verein Niederrhein, der als gemeinn\u00fctziger Verein die Ausstellung betreibt. Besucher:innen k\u00f6nnen historische Zahlungsmittel und M\u00fcnzgeschichten von der Antike bis zur Gegenwart entdecken. Die Ausstellung umfasst Spargef\u00e4\u00dfe, Schulsparautomaten, Geldtransportwagen und funktionierende Geldverarbeitungsmaschinen. Eine besondere Attraktion ist die Pr\u00e4gewerkstatt, in der eigene M\u00fcnzen geschlagen werden k\u00f6nnen. Die Schulwerkstatt bietet Lernstationen, an denen das Rechnen nach Adam Ries erlernt werden kann. Eine Abteilung ist dem Genossenschaftsgr\u00fcnder Friedrich Wilhelm Raiffeisen gewidmet. Der ehemalige Sparkassenraum zeigt Rechen- und Buchungsmaschinen aus den 1950er Jahren. Seit 2016 ist das Museum in einem d\u00f6rflichen Umfeld angesiedelt und bietet p\u00e4dagogisch betreute Kindergeburtstage sowie au\u00dferschulische Unterrichtstage f\u00fcr Schulen an. Eine Sonderausstellung zum Thema &#8220;100 Jahre Weltspartag&#8221; ist bis 2025 zu sehen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Museum rund ums Geld in Xanten bietet auf 340 Quadratmetern eine umfassende Darstellung der Geldgeschichte. Tr\u00e4ger ist der Geldgeschichtliche Verein Niederrhein, der als gemeinn\u00fctziger Verein die Ausstellung betreibt. Besucher:innen k\u00f6nnen historische Zahlungsmittel und M\u00fcnzgeschichten von der Antike bis zur Gegenwart entdecken. Die Ausstellung umfasst Spargef\u00e4\u00dfe, Schulsparautomaten, Geldtransportwagen und funktionierende Geldverarbeitungsmaschinen. Eine besondere Attraktion ist [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":101428,"template":"","destinations":[235,170],"class_list":["post-134780","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-historische-orte","destination-museen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Museum rund ums Geld - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/museum-rund-ums-geld\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Museum rund ums Geld - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Das Museum rund ums Geld in Xanten bietet auf 340 Quadratmetern eine umfassende Darstellung der Geldgeschichte. Tr\u00e4ger ist der Geldgeschichtliche Verein Niederrhein, der als gemeinn\u00fctziger Verein die Ausstellung betreibt. Besucher:innen k\u00f6nnen historische Zahlungsmittel und M\u00fcnzgeschichten von der Antike bis zur Gegenwart entdecken. Die Ausstellung umfasst Spargef\u00e4\u00dfe, Schulsparautomaten, Geldtransportwagen und funktionierende Geldverarbeitungsmaschinen. Eine besondere Attraktion ist [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/03\/geldmuseum6-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1886\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/museum-rund-ums-geld\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/museum-rund-ums-geld\/\",\"name\":\"Museum rund ums Geld - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-09-02T00:03:08+00:00\",\"dateModified\":\"2026-09-02T00:03:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/museum-rund-ums-geld\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/museum-rund-ums-geld\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/museum-rund-ums-geld\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Museum rund ums Geld\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Museum rund ums Geld - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/museum-rund-ums-geld\/","og_locale":"en_US","og_type":"article","og_title":"Museum rund ums Geld - Stadt. Land. Niederrhein","og_description":"Das Museum rund ums Geld in Xanten bietet auf 340 Quadratmetern eine umfassende Darstellung der Geldgeschichte. Tr\u00e4ger ist der Geldgeschichtliche Verein Niederrhein, der als gemeinn\u00fctziger Verein die Ausstellung betreibt. Besucher:innen k\u00f6nnen historische Zahlungsmittel und M\u00fcnzgeschichten von der Antike bis zur Gegenwart entdecken. Die Ausstellung umfasst Spargef\u00e4\u00dfe, Schulsparautomaten, Geldtransportwagen und funktionierende Geldverarbeitungsmaschinen. Eine besondere Attraktion ist [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2560,"height":1886,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/03\/geldmuseum6-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/museum-rund-ums-geld\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/museum-rund-ums-geld\/","name":"Museum rund ums Geld - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-09-02T00:03:08+00:00","dateModified":"2026-09-02T00:03:08+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/museum-rund-ums-geld\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kultur\/museum-rund-ums-geld\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/museum-rund-ums-geld\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culture","item":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/"},{"@type":"ListItem","position":3,"name":"Museum rund ums Geld"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/134780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/134780\/revisions"}],"predecessor-version":[{"id":135081,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/134780\/revisions\/135081"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/101428"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=134780"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/destinations?post=134780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}