{"id":134783,"date":"2026-09-02T02:03:08","date_gmt":"2026-09-02T00:03:08","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/vinyl-garage\/"},"modified":"2026-09-02T02:03:08","modified_gmt":"2026-09-02T00:03:08","slug":"vinyl-garage","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/vinyl-garage\/","title":{"rendered":"Vinyl Garage"},"content":{"rendered":"<p>Mitten in der Altstadt von M\u00f6nchengladbach bietet die Vinyl Garage einen einzigartigen Raum f\u00fcr Musikliebhaber:innen. Urspr\u00fcnglich als Garage genutzt, pr\u00e4sentiert sich der vordere Verkaufsbereich heute mit gef\u00fcllten Vinylkisten und farbenfrohen Plattencovern, die bis zur Decke reichen. Die sorgf\u00e4ltig kuratierte Plattenauswahl setzt sich in der \u201eDiele\u201c und im \u201eWohnzimmer\u201c fort, wo Sofas, Sessel und Vorh\u00f6rstationen zum Verweilen einladen. In der \u201eK\u00fcche\u201c stehen Kaffee und kalte Getr\u00e4nke zur Selbstbedienung bereit. <\/p>\n<p>Die Vinyl Garage ist jedoch mehr als ein Schallplattenladen. Als gemeinn\u00fctziges Projekt bietet sie Menschen mit Suchterkrankungen die M\u00f6glichkeit zur Teilhabe und Rehabilitation. Durch angeleitete T\u00e4tigkeiten in der Aufbereitung, im Verkauf und im Upcycling von Schallplatten wird eine wertvolle soziale Arbeit geleistet. Dieses Engagement macht die Vinyl Garage zu einem besonderen Ort, der Musik und soziale Verantwortung auf bemerkenswerte Weise verbindet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mitten in der Altstadt von M\u00f6nchengladbach bietet die Vinyl Garage einen einzigartigen Raum f\u00fcr Musikliebhaber:innen. Urspr\u00fcnglich als Garage genutzt, pr\u00e4sentiert sich der vordere Verkaufsbereich heute mit gef\u00fcllten Vinylkisten und farbenfrohen Plattencovern, die bis zur Decke reichen. Die sorgf\u00e4ltig kuratierte Plattenauswahl setzt sich in der \u201eDiele\u201c und im \u201eWohnzimmer\u201c fort, wo Sofas, Sessel und Vorh\u00f6rstationen zum [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":100971,"template":"","destinations":[235,170],"class_list":["post-134783","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-historische-orte","destination-museen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vinyl Garage - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/vinyl-garage\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vinyl Garage - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Mitten in der Altstadt von M\u00f6nchengladbach bietet die Vinyl Garage einen einzigartigen Raum f\u00fcr Musikliebhaber:innen. Urspr\u00fcnglich als Garage genutzt, pr\u00e4sentiert sich der vordere Verkaufsbereich heute mit gef\u00fcllten Vinylkisten und farbenfrohen Plattencovern, die bis zur Decke reichen. Die sorgf\u00e4ltig kuratierte Plattenauswahl setzt sich in der \u201eDiele\u201c und im \u201eWohnzimmer\u201c fort, wo Sofas, Sessel und Vorh\u00f6rstationen zum [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/unnamed-file-31.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/vinyl-garage\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/vinyl-garage\/\",\"name\":\"Vinyl Garage - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-09-02T00:03:08+00:00\",\"dateModified\":\"2026-09-02T00:03:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/vinyl-garage\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/vinyl-garage\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/vinyl-garage\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vinyl Garage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vinyl Garage - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/vinyl-garage\/","og_locale":"en_US","og_type":"article","og_title":"Vinyl Garage - Stadt. Land. Niederrhein","og_description":"Mitten in der Altstadt von M\u00f6nchengladbach bietet die Vinyl Garage einen einzigartigen Raum f\u00fcr Musikliebhaber:innen. Urspr\u00fcnglich als Garage genutzt, pr\u00e4sentiert sich der vordere Verkaufsbereich heute mit gef\u00fcllten Vinylkisten und farbenfrohen Plattencovern, die bis zur Decke reichen. Die sorgf\u00e4ltig kuratierte Plattenauswahl setzt sich in der \u201eDiele\u201c und im \u201eWohnzimmer\u201c fort, wo Sofas, Sessel und Vorh\u00f6rstationen zum [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2048,"height":1365,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/unnamed-file-31.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/vinyl-garage\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/vinyl-garage\/","name":"Vinyl Garage - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-09-02T00:03:08+00:00","dateModified":"2026-09-02T00:03:08+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/vinyl-garage\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kultur\/vinyl-garage\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/vinyl-garage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culture","item":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/"},{"@type":"ListItem","position":3,"name":"Vinyl Garage"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/134783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/134783\/revisions"}],"predecessor-version":[{"id":135066,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/134783\/revisions\/135066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/100971"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=134783"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/destinations?post=134783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}