{"id":134807,"date":"2026-09-02T01:41:45","date_gmt":"2026-09-01T23:41:45","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/schlosskapelle-ossenberg\/"},"modified":"2026-09-02T01:41:45","modified_gmt":"2026-09-01T23:41:45","slug":"schlosskapelle-ossenberg","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/schlosskapelle-ossenberg\/","title":{"rendered":"Schlosskapelle Ossenberg"},"content":{"rendered":"<p>Die Schlosskapelle Ossenberg, s\u00fcdlich der historischen Schlossanlage gelegen, wurde erstmals im 13. Jahrhundert urkundlich erw\u00e4hnt, wobei ihre Urspr\u00fcnge bis ins 11. Jahrhundert zur\u00fcckreichen. Der heutige Bau pr\u00e4sentiert sich als zweischiffiger Backsteinbau aus dem 18. Jahrhundert, ausgestattet mit einem barocken Altar und einem kunstvollen Orgelprospekt. Im 20. Jahrhundert wurde die Kapelle von engagierten B\u00fcrger:innen restauriert und dient heute als Ort f\u00fcr Gottesdienste und Trauungen beider Konfessionen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Schlosskapelle Ossenberg, s\u00fcdlich der historischen Schlossanlage gelegen, wurde erstmals im 13. Jahrhundert urkundlich erw\u00e4hnt, wobei ihre Urspr\u00fcnge bis ins 11. Jahrhundert zur\u00fcckreichen. Der heutige Bau pr\u00e4sentiert sich als zweischiffiger Backsteinbau aus dem 18. Jahrhundert, ausgestattet mit einem barocken Altar und einem kunstvollen Orgelprospekt. Im 20. Jahrhundert wurde die Kapelle von engagierten B\u00fcrger:innen restauriert und [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":110176,"template":"","destinations":[242],"class_list":["post-134807","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-kirchen-kloester"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Schlosskapelle Ossenberg - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/schlosskapelle-ossenberg\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schlosskapelle Ossenberg - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Die Schlosskapelle Ossenberg, s\u00fcdlich der historischen Schlossanlage gelegen, wurde erstmals im 13. Jahrhundert urkundlich erw\u00e4hnt, wobei ihre Urspr\u00fcnge bis ins 11. Jahrhundert zur\u00fcckreichen. Der heutige Bau pr\u00e4sentiert sich als zweischiffiger Backsteinbau aus dem 18. Jahrhundert, ausgestattet mit einem barocken Altar und einem kunstvollen Orgelprospekt. Im 20. Jahrhundert wurde die Kapelle von engagierten B\u00fcrger:innen restauriert und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/06\/schlosskapelle-ossenberg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1618\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/schlosskapelle-ossenberg\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/schlosskapelle-ossenberg\/\",\"name\":\"Schlosskapelle Ossenberg - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-09-01T23:41:45+00:00\",\"dateModified\":\"2026-09-01T23:41:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/schlosskapelle-ossenberg\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/schlosskapelle-ossenberg\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/schlosskapelle-ossenberg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culture\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Schlosskapelle Ossenberg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schlosskapelle Ossenberg - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/schlosskapelle-ossenberg\/","og_locale":"en_US","og_type":"article","og_title":"Schlosskapelle Ossenberg - Stadt. Land. Niederrhein","og_description":"Die Schlosskapelle Ossenberg, s\u00fcdlich der historischen Schlossanlage gelegen, wurde erstmals im 13. Jahrhundert urkundlich erw\u00e4hnt, wobei ihre Urspr\u00fcnge bis ins 11. Jahrhundert zur\u00fcckreichen. Der heutige Bau pr\u00e4sentiert sich als zweischiffiger Backsteinbau aus dem 18. Jahrhundert, ausgestattet mit einem barocken Altar und einem kunstvollen Orgelprospekt. Im 20. Jahrhundert wurde die Kapelle von engagierten B\u00fcrger:innen restauriert und [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":1618,"height":1080,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/06\/schlosskapelle-ossenberg.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/schlosskapelle-ossenberg\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/schlosskapelle-ossenberg\/","name":"Schlosskapelle Ossenberg - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-09-01T23:41:45+00:00","dateModified":"2026-09-01T23:41:45+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/schlosskapelle-ossenberg\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kultur\/schlosskapelle-ossenberg\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/schlosskapelle-ossenberg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culture","item":"https:\/\/stadt-land-niederrhein.de\/en\/kultur\/"},{"@type":"ListItem","position":3,"name":"Schlosskapelle Ossenberg"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/134807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/134807\/revisions"}],"predecessor-version":[{"id":134981,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/pois\/134807\/revisions\/134981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/110176"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=134807"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/destinations?post=134807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}