{"id":107569,"date":"2026-05-13T01:05:17","date_gmt":"2026-05-12T23:05:17","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kulinarik\/vhaus\/"},"modified":"2026-05-13T01:05:17","modified_gmt":"2026-05-12T23:05:17","slug":"vhaus","status":"publish","type":"restaurant","link":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/vhaus\/","title":{"rendered":"VHaus"},"content":{"rendered":"<p>Das VHaus in Dinslaken-Hiesfeld, eingebettet im Naherholungsgebiet Rotbachtal, bietet eine professionelle Umgebung f\u00fcr gesellige Anl\u00e4sse. Der gro\u00dfz\u00fcgige Gastraum und der \u00fcberdachte Biergarten sind ideal f\u00fcr Treffen. Die K\u00fcche vereint klassische und moderne Gerichte, die auch zum Mitnehmen erh\u00e4ltlich sind. Unterhaltung bietet die Kegelbahn und die Sky Sports Bar. Flexible R\u00e4umlichkeiten stehen f\u00fcr Veranstaltungen zur Verf\u00fcgung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das VHaus in Dinslaken-Hiesfeld, eingebettet im Naherholungsgebiet Rotbachtal, bietet eine professionelle Umgebung f\u00fcr gesellige Anl\u00e4sse. Der gro\u00dfz\u00fcgige Gastraum und der \u00fcberdachte Biergarten sind ideal f\u00fcr Treffen. Die K\u00fcche vereint klassische und moderne Gerichte, die auch zum Mitnehmen erh\u00e4ltlich sind. Unterhaltung bietet die Kegelbahn und die Sky Sports Bar. Flexible R\u00e4umlichkeiten stehen f\u00fcr Veranstaltungen zur Verf\u00fcgung.<\/p>\n","protected":false},"author":0,"featured_media":128985,"template":"","cuisines":[],"features":[],"kitchen_offers":[],"operating_modes":[244,92,243],"class_list":["post-107569","restaurant","type-restaurant","status-publish","has-post-thumbnail","hentry","operating_mode-gaststaetten","operating_mode-restaurant","operating_mode-trinkgenuss"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>VHaus - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/vhaus\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VHaus - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Das VHaus in Dinslaken-Hiesfeld, eingebettet im Naherholungsgebiet Rotbachtal, bietet eine professionelle Umgebung f\u00fcr gesellige Anl\u00e4sse. Der gro\u00dfz\u00fcgige Gastraum und der \u00fcberdachte Biergarten sind ideal f\u00fcr Treffen. Die K\u00fcche vereint klassische und moderne Gerichte, die auch zum Mitnehmen erh\u00e4ltlich sind. Unterhaltung bietet die Kegelbahn und die Sky Sports Bar. Flexible R\u00e4umlichkeiten stehen f\u00fcr Veranstaltungen zur Verf\u00fcgung.\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2026\/03\/vhaus_klein.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/vhaus\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/vhaus\/\",\"name\":\"VHaus - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-05-12T23:05:17+00:00\",\"dateModified\":\"2026-05-12T23:05:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/vhaus\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/vhaus\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/vhaus\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culinary\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/culinary\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"VHaus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VHaus - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/vhaus\/","og_locale":"en_US","og_type":"article","og_title":"VHaus - Stadt. Land. Niederrhein","og_description":"Das VHaus in Dinslaken-Hiesfeld, eingebettet im Naherholungsgebiet Rotbachtal, bietet eine professionelle Umgebung f\u00fcr gesellige Anl\u00e4sse. Der gro\u00dfz\u00fcgige Gastraum und der \u00fcberdachte Biergarten sind ideal f\u00fcr Treffen. Die K\u00fcche vereint klassische und moderne Gerichte, die auch zum Mitnehmen erh\u00e4ltlich sind. Unterhaltung bietet die Kegelbahn und die Sky Sports Bar. Flexible R\u00e4umlichkeiten stehen f\u00fcr Veranstaltungen zur Verf\u00fcgung.","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":1440,"height":1080,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2026\/03\/vhaus_klein.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/vhaus\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/vhaus\/","name":"VHaus - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-05-12T23:05:17+00:00","dateModified":"2026-05-12T23:05:17+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/vhaus\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/vhaus\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/vhaus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culinary","item":"https:\/\/stadt-land-niederrhein.de\/en\/culinary\/"},{"@type":"ListItem","position":3,"name":"VHaus"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/107569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/restaurant"}],"version-history":[{"count":3,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/107569\/revisions"}],"predecessor-version":[{"id":124137,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/107569\/revisions\/124137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/128985"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=107569"}],"wp:term":[{"taxonomy":"cuisine","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/cuisines?post=107569"},{"taxonomy":"feature","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/features?post=107569"},{"taxonomy":"kitchen_offer","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/kitchen_offers?post=107569"},{"taxonomy":"operating_mode","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/operating_modes?post=107569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}