{"id":108938,"date":"2026-09-01T02:24:15","date_gmt":"2026-09-01T00:24:15","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kulinarik\/cafe-dams-backwerkstatt\/"},"modified":"2026-09-01T02:24:15","modified_gmt":"2026-09-01T00:24:15","slug":"cafe-dams-backwerkstatt","status":"publish","type":"restaurant","link":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/cafe-dams-backwerkstatt\/","title":{"rendered":"Caf\u00e9 Dams Backwerkstatt"},"content":{"rendered":"<p>Caf\u00e9 Dams Backwerkstatt in Wesel bietet eine breite Auswahl an handgefertigten Backwaren, die mit traditionellen Techniken hergestellt werden. Das Caf\u00e9 ist bekannt f\u00fcr seine frischen Brote und s\u00fc\u00dfen Leckereien, die in einer einladenden Umgebung serviert werden. Ein Besuch lohnt sich f\u00fcr alle, die Qualit\u00e4t und Handwerkskunst sch\u00e4tzen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Caf\u00e9 Dams Backwerkstatt in Wesel bietet eine breite Auswahl an handgefertigten Backwaren, die mit traditionellen Techniken hergestellt werden. Das Caf\u00e9 ist bekannt f\u00fcr seine frischen Brote und s\u00fc\u00dfen Leckereien, die in einer einladenden Umgebung serviert werden. Ein Besuch lohnt sich f\u00fcr alle, die Qualit\u00e4t und Handwerkskunst sch\u00e4tzen.<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","cuisines":[],"features":[],"kitchen_offers":[],"operating_modes":[90],"class_list":["post-108938","restaurant","type-restaurant","status-publish","hentry","operating_mode-cafe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Caf\u00e9 Dams Backwerkstatt - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/cafe-dams-backwerkstatt\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caf\u00e9 Dams Backwerkstatt - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Caf\u00e9 Dams Backwerkstatt in Wesel bietet eine breite Auswahl an handgefertigten Backwaren, die mit traditionellen Techniken hergestellt werden. Das Caf\u00e9 ist bekannt f\u00fcr seine frischen Brote und s\u00fc\u00dfen Leckereien, die in einer einladenden Umgebung serviert werden. Ein Besuch lohnt sich f\u00fcr alle, die Qualit\u00e4t und Handwerkskunst sch\u00e4tzen.\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/cafe-dams-backwerkstatt\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/cafe-dams-backwerkstatt\/\",\"name\":\"Caf\u00e9 Dams Backwerkstatt - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-09-01T00:24:15+00:00\",\"dateModified\":\"2026-09-01T00:24:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/cafe-dams-backwerkstatt\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/cafe-dams-backwerkstatt\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/cafe-dams-backwerkstatt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culinary\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/culinary\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Caf\u00e9 Dams Backwerkstatt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caf\u00e9 Dams Backwerkstatt - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/cafe-dams-backwerkstatt\/","og_locale":"en_US","og_type":"article","og_title":"Caf\u00e9 Dams Backwerkstatt - Stadt. Land. Niederrhein","og_description":"Caf\u00e9 Dams Backwerkstatt in Wesel bietet eine breite Auswahl an handgefertigten Backwaren, die mit traditionellen Techniken hergestellt werden. Das Caf\u00e9 ist bekannt f\u00fcr seine frischen Brote und s\u00fc\u00dfen Leckereien, die in einer einladenden Umgebung serviert werden. Ein Besuch lohnt sich f\u00fcr alle, die Qualit\u00e4t und Handwerkskunst sch\u00e4tzen.","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/cafe-dams-backwerkstatt\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/cafe-dams-backwerkstatt\/","name":"Caf\u00e9 Dams Backwerkstatt - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-09-01T00:24:15+00:00","dateModified":"2026-09-01T00:24:15+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/cafe-dams-backwerkstatt\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/cafe-dams-backwerkstatt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/cafe-dams-backwerkstatt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culinary","item":"https:\/\/stadt-land-niederrhein.de\/en\/culinary\/"},{"@type":"ListItem","position":3,"name":"Caf\u00e9 Dams Backwerkstatt"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/108938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/restaurant"}],"version-history":[{"count":2,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/108938\/revisions"}],"predecessor-version":[{"id":122567,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/108938\/revisions\/122567"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=108938"}],"wp:term":[{"taxonomy":"cuisine","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/cuisines?post=108938"},{"taxonomy":"feature","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/features?post=108938"},{"taxonomy":"kitchen_offer","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/kitchen_offers?post=108938"},{"taxonomy":"operating_mode","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/operating_modes?post=108938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}