{"id":108978,"date":"2026-05-13T01:06:03","date_gmt":"2026-05-12T23:06:03","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kulinarik\/kleinespel-imping-cafe-baeckerei-konditorei-2\/"},"modified":"2026-05-13T01:06:03","modified_gmt":"2026-05-12T23:06:03","slug":"kleinespel-imping-cafe-baeckerei-konditorei-2","status":"publish","type":"restaurant","link":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kleinespel-imping-cafe-baeckerei-konditorei-2\/","title":{"rendered":"Kleinespel &amp; Imping (Caf\u00e9, B\u00e4ckerei, Konditorei)"},"content":{"rendered":"<p>Kleinespel &amp; Imping in Schermbeck vereint die Kunst des traditionellen B\u00e4ckerhandwerks mit der Verwendung hochwertiger regionaler Rohstoffe. Die B\u00e4ckerei und Konditorei setzt auf althergebrachte Rezepte und handwerkliche Produktion. Ein Gro\u00dfteil der Mehle und Schrote wird von einem \u00f6rtlichen M\u00fcller bezogen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kleinespel &amp; Imping in Schermbeck vereint die Kunst des traditionellen B\u00e4ckerhandwerks mit der Verwendung hochwertiger regionaler Rohstoffe. Die B\u00e4ckerei und Konditorei setzt auf althergebrachte Rezepte und handwerkliche Produktion. Ein Gro\u00dfteil der Mehle und Schrote wird von einem \u00f6rtlichen M\u00fcller bezogen.<\/p>\n","protected":false},"author":0,"featured_media":106727,"template":"","cuisines":[],"features":[],"kitchen_offers":[],"operating_modes":[90,92],"class_list":["post-108978","restaurant","type-restaurant","status-publish","has-post-thumbnail","hentry","operating_mode-cafe","operating_mode-restaurant"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kleinespel &amp; Imping (Caf\u00e9, B\u00e4ckerei, Konditorei) - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kleinespel-imping-cafe-baeckerei-konditorei-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kleinespel &amp; Imping (Caf\u00e9, B\u00e4ckerei, Konditorei) - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Kleinespel &amp; Imping in Schermbeck vereint die Kunst des traditionellen B\u00e4ckerhandwerks mit der Verwendung hochwertiger regionaler Rohstoffe. Die B\u00e4ckerei und Konditorei setzt auf althergebrachte Rezepte und handwerkliche Produktion. Ein Gro\u00dfteil der Mehle und Schrote wird von einem \u00f6rtlichen M\u00fcller bezogen.\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/05\/eingang-zum-caf-b-ckerei-imping.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1530\" \/>\n\t<meta property=\"og:image:height\" content=\"2040\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kleinespel-imping-cafe-baeckerei-konditorei-2\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kleinespel-imping-cafe-baeckerei-konditorei-2\/\",\"name\":\"Kleinespel &amp; Imping (Caf\u00e9, B\u00e4ckerei, Konditorei) - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-05-12T23:06:03+00:00\",\"dateModified\":\"2026-05-12T23:06:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kleinespel-imping-cafe-baeckerei-konditorei-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kleinespel-imping-cafe-baeckerei-konditorei-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kleinespel-imping-cafe-baeckerei-konditorei-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culinary\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/culinary\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kleinespel &amp; Imping (Caf\u00e9, B\u00e4ckerei, Konditorei)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kleinespel &amp; Imping (Caf\u00e9, B\u00e4ckerei, Konditorei) - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kleinespel-imping-cafe-baeckerei-konditorei-2\/","og_locale":"en_US","og_type":"article","og_title":"Kleinespel &amp; Imping (Caf\u00e9, B\u00e4ckerei, Konditorei) - Stadt. Land. Niederrhein","og_description":"Kleinespel &amp; Imping in Schermbeck vereint die Kunst des traditionellen B\u00e4ckerhandwerks mit der Verwendung hochwertiger regionaler Rohstoffe. Die B\u00e4ckerei und Konditorei setzt auf althergebrachte Rezepte und handwerkliche Produktion. Ein Gro\u00dfteil der Mehle und Schrote wird von einem \u00f6rtlichen M\u00fcller bezogen.","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":1530,"height":2040,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/05\/eingang-zum-caf-b-ckerei-imping.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kleinespel-imping-cafe-baeckerei-konditorei-2\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kleinespel-imping-cafe-baeckerei-konditorei-2\/","name":"Kleinespel &amp; Imping (Caf\u00e9, B\u00e4ckerei, Konditorei) - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-05-12T23:06:03+00:00","dateModified":"2026-05-12T23:06:03+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kleinespel-imping-cafe-baeckerei-konditorei-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kleinespel-imping-cafe-baeckerei-konditorei-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kleinespel-imping-cafe-baeckerei-konditorei-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culinary","item":"https:\/\/stadt-land-niederrhein.de\/en\/culinary\/"},{"@type":"ListItem","position":3,"name":"Kleinespel &amp; Imping (Caf\u00e9, B\u00e4ckerei, Konditorei)"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/108978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/restaurant"}],"version-history":[{"count":3,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/108978\/revisions"}],"predecessor-version":[{"id":124191,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/108978\/revisions\/124191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/106727"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=108978"}],"wp:term":[{"taxonomy":"cuisine","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/cuisines?post=108978"},{"taxonomy":"feature","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/features?post=108978"},{"taxonomy":"kitchen_offer","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/kitchen_offers?post=108978"},{"taxonomy":"operating_mode","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/operating_modes?post=108978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}