{"id":109112,"date":"2026-09-01T02:24:25","date_gmt":"2026-09-01T00:24:25","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kulinarik\/naturhof-bauernmarkt-und-cafe-beyen-gmbh-2\/"},"modified":"2026-09-01T02:24:25","modified_gmt":"2026-09-01T00:24:25","slug":"naturhof-bauernmarkt-und-cafe-beyen-gmbh-2","status":"publish","type":"restaurant","link":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/naturhof-bauernmarkt-und-cafe-beyen-gmbh-2\/","title":{"rendered":"Naturhof, Bauernmarkt und Cafe Beyen GmbH"},"content":{"rendered":"<p>Der Naturhof, Bauernmarkt und Caf\u00e9 Beyen GmbH in Kerken bietet seit \u00fcber 30 Jahren regionale Produkte wie Kartoffeln, Obst und Gem\u00fcse direkt ab Hof an. Das Sortiment wurde stetig erweitert und umfasst heute auch Rindfleisch aus eigener Aufzucht. Im Jahr 2005 wurde ein Caf\u00e9 im ehemaligen Kuhstall er\u00f6ffnet, das hausgemachte Torten und Kuchen serviert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Naturhof, Bauernmarkt und Caf\u00e9 Beyen GmbH in Kerken bietet seit \u00fcber 30 Jahren regionale Produkte wie Kartoffeln, Obst und Gem\u00fcse direkt ab Hof an. Das Sortiment wurde stetig erweitert und umfasst heute auch Rindfleisch aus eigener Aufzucht. Im Jahr 2005 wurde ein Caf\u00e9 im ehemaligen Kuhstall er\u00f6ffnet, das hausgemachte Torten und Kuchen serviert.<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","cuisines":[],"features":[],"kitchen_offers":[],"operating_modes":[90],"class_list":["post-109112","restaurant","type-restaurant","status-publish","hentry","operating_mode-cafe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Naturhof, Bauernmarkt und Cafe Beyen GmbH - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/naturhof-bauernmarkt-und-cafe-beyen-gmbh-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Naturhof, Bauernmarkt und Cafe Beyen GmbH - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Der Naturhof, Bauernmarkt und Caf\u00e9 Beyen GmbH in Kerken bietet seit \u00fcber 30 Jahren regionale Produkte wie Kartoffeln, Obst und Gem\u00fcse direkt ab Hof an. Das Sortiment wurde stetig erweitert und umfasst heute auch Rindfleisch aus eigener Aufzucht. Im Jahr 2005 wurde ein Caf\u00e9 im ehemaligen Kuhstall er\u00f6ffnet, das hausgemachte Torten und Kuchen serviert.\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/naturhof-bauernmarkt-und-cafe-beyen-gmbh-2\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/naturhof-bauernmarkt-und-cafe-beyen-gmbh-2\/\",\"name\":\"Naturhof, Bauernmarkt und Cafe Beyen GmbH - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-09-01T00:24:25+00:00\",\"dateModified\":\"2026-09-01T00:24:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/naturhof-bauernmarkt-und-cafe-beyen-gmbh-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/naturhof-bauernmarkt-und-cafe-beyen-gmbh-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/naturhof-bauernmarkt-und-cafe-beyen-gmbh-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culinary\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/culinary\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Naturhof, Bauernmarkt und Cafe Beyen GmbH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Naturhof, Bauernmarkt und Cafe Beyen GmbH - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/naturhof-bauernmarkt-und-cafe-beyen-gmbh-2\/","og_locale":"en_US","og_type":"article","og_title":"Naturhof, Bauernmarkt und Cafe Beyen GmbH - Stadt. Land. Niederrhein","og_description":"Der Naturhof, Bauernmarkt und Caf\u00e9 Beyen GmbH in Kerken bietet seit \u00fcber 30 Jahren regionale Produkte wie Kartoffeln, Obst und Gem\u00fcse direkt ab Hof an. Das Sortiment wurde stetig erweitert und umfasst heute auch Rindfleisch aus eigener Aufzucht. Im Jahr 2005 wurde ein Caf\u00e9 im ehemaligen Kuhstall er\u00f6ffnet, das hausgemachte Torten und Kuchen serviert.","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/naturhof-bauernmarkt-und-cafe-beyen-gmbh-2\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/naturhof-bauernmarkt-und-cafe-beyen-gmbh-2\/","name":"Naturhof, Bauernmarkt und Cafe Beyen GmbH - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-09-01T00:24:25+00:00","dateModified":"2026-09-01T00:24:25+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/naturhof-bauernmarkt-und-cafe-beyen-gmbh-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/naturhof-bauernmarkt-und-cafe-beyen-gmbh-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/naturhof-bauernmarkt-und-cafe-beyen-gmbh-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culinary","item":"https:\/\/stadt-land-niederrhein.de\/en\/culinary\/"},{"@type":"ListItem","position":3,"name":"Naturhof, Bauernmarkt und Cafe Beyen GmbH"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/109112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/restaurant"}],"version-history":[{"count":3,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/109112\/revisions"}],"predecessor-version":[{"id":124262,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/109112\/revisions\/124262"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=109112"}],"wp:term":[{"taxonomy":"cuisine","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/cuisines?post=109112"},{"taxonomy":"feature","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/features?post=109112"},{"taxonomy":"kitchen_offer","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/kitchen_offers?post=109112"},{"taxonomy":"operating_mode","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/operating_modes?post=109112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}