{"id":115229,"date":"2026-05-11T03:14:29","date_gmt":"2026-05-11T01:14:29","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kulinarik\/haberstroh-cafe-conditorei-confiserie\/"},"modified":"2026-05-11T03:14:29","modified_gmt":"2026-05-11T01:14:29","slug":"haberstroh-cafe-conditorei-confiserie","status":"publish","type":"restaurant","link":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/haberstroh-cafe-conditorei-confiserie\/","title":{"rendered":"Haberstroh &#8211; Caf\u00e9 Conditorei Confiserie"},"content":{"rendered":"<p>Haberstroh &#8211; Caf\u00e9 Conditorei Confiserie in Krefeld bietet eine exquisite Auswahl an handgefertigten Pralinen, Torten und Geb\u00e4ck. Das Caf\u00e9 besticht durch seine traditionelle Handwerkskunst und l\u00e4dt in einem stilvollen Ambiente zum Verweilen ein. Die Speisekarte umfasst zudem saisonale Spezialit\u00e4ten, die mit viel Liebe zum Detail zubereitet werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Haberstroh &#8211; Caf\u00e9 Conditorei Confiserie in Krefeld bietet eine exquisite Auswahl an handgefertigten Pralinen, Torten und Geb\u00e4ck. Das Caf\u00e9 besticht durch seine traditionelle Handwerkskunst und l\u00e4dt in einem stilvollen Ambiente zum Verweilen ein. Die Speisekarte umfasst zudem saisonale Spezialit\u00e4ten, die mit viel Liebe zum Detail zubereitet werden.<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","cuisines":[],"features":[],"kitchen_offers":[],"operating_modes":[90],"class_list":["post-115229","restaurant","type-restaurant","status-publish","hentry","operating_mode-cafe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Haberstroh - Caf\u00e9 Conditorei Confiserie - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/haberstroh-cafe-conditorei-confiserie\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Haberstroh - Caf\u00e9 Conditorei Confiserie - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Haberstroh &#8211; Caf\u00e9 Conditorei Confiserie in Krefeld bietet eine exquisite Auswahl an handgefertigten Pralinen, Torten und Geb\u00e4ck. Das Caf\u00e9 besticht durch seine traditionelle Handwerkskunst und l\u00e4dt in einem stilvollen Ambiente zum Verweilen ein. Die Speisekarte umfasst zudem saisonale Spezialit\u00e4ten, die mit viel Liebe zum Detail zubereitet werden.\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/haberstroh-cafe-conditorei-confiserie\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/haberstroh-cafe-conditorei-confiserie\/\",\"name\":\"Haberstroh - Caf\u00e9 Conditorei Confiserie - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-05-11T01:14:29+00:00\",\"dateModified\":\"2026-05-11T01:14:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/haberstroh-cafe-conditorei-confiserie\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/haberstroh-cafe-conditorei-confiserie\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/haberstroh-cafe-conditorei-confiserie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culinary\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/culinary\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Haberstroh - Caf\u00e9 Conditorei Confiserie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Haberstroh - Caf\u00e9 Conditorei Confiserie - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/haberstroh-cafe-conditorei-confiserie\/","og_locale":"en_US","og_type":"article","og_title":"Haberstroh - Caf\u00e9 Conditorei Confiserie - Stadt. Land. Niederrhein","og_description":"Haberstroh &#8211; Caf\u00e9 Conditorei Confiserie in Krefeld bietet eine exquisite Auswahl an handgefertigten Pralinen, Torten und Geb\u00e4ck. Das Caf\u00e9 besticht durch seine traditionelle Handwerkskunst und l\u00e4dt in einem stilvollen Ambiente zum Verweilen ein. Die Speisekarte umfasst zudem saisonale Spezialit\u00e4ten, die mit viel Liebe zum Detail zubereitet werden.","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/haberstroh-cafe-conditorei-confiserie\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/haberstroh-cafe-conditorei-confiserie\/","name":"Haberstroh - Caf\u00e9 Conditorei Confiserie - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-05-11T01:14:29+00:00","dateModified":"2026-05-11T01:14:29+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/haberstroh-cafe-conditorei-confiserie\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/haberstroh-cafe-conditorei-confiserie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/haberstroh-cafe-conditorei-confiserie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culinary","item":"https:\/\/stadt-land-niederrhein.de\/en\/culinary\/"},{"@type":"ListItem","position":3,"name":"Haberstroh - Caf\u00e9 Conditorei Confiserie"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/115229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/restaurant"}],"version-history":[{"count":2,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/115229\/revisions"}],"predecessor-version":[{"id":122439,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/115229\/revisions\/122439"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=115229"}],"wp:term":[{"taxonomy":"cuisine","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/cuisines?post=115229"},{"taxonomy":"feature","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/features?post=115229"},{"taxonomy":"kitchen_offer","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/kitchen_offers?post=115229"},{"taxonomy":"operating_mode","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/operating_modes?post=115229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}