{"id":119889,"date":"2026-05-12T02:29:04","date_gmt":"2026-05-12T00:29:04","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kulinarik\/franken-eis-2\/"},"modified":"2026-05-12T02:29:04","modified_gmt":"2026-05-12T00:29:04","slug":"franken-eis-2","status":"publish","type":"restaurant","link":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/franken-eis-2\/","title":{"rendered":"Franken-Eis"},"content":{"rendered":"<p>Franken-Eis in Krefeld ist eine Eisdiele, die mediterrane und italienische Eisspezialit\u00e4ten bietet. Die Lage in der Stadt Krefeld erm\u00f6glicht einen einfachen Zugang f\u00fcr Besucher:innen. Die Speisekarte umfasst eine Vielzahl an Eissorten, die mit hochwertigen Zutaten zubereitet werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Franken-Eis in Krefeld ist eine Eisdiele, die mediterrane und italienische Eisspezialit\u00e4ten bietet. Die Lage in der Stadt Krefeld erm\u00f6glicht einen einfachen Zugang f\u00fcr Besucher:innen. Die Speisekarte umfasst eine Vielzahl an Eissorten, die mit hochwertigen Zutaten zubereitet werden.<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","cuisines":[67,69],"features":[],"kitchen_offers":[],"operating_modes":[90],"class_list":["post-119889","restaurant","type-restaurant","status-publish","hentry","cuisine-italienisch","cuisine-mediterran","operating_mode-cafe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Franken-Eis - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/franken-eis-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Franken-Eis - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Franken-Eis in Krefeld ist eine Eisdiele, die mediterrane und italienische Eisspezialit\u00e4ten bietet. Die Lage in der Stadt Krefeld erm\u00f6glicht einen einfachen Zugang f\u00fcr Besucher:innen. Die Speisekarte umfasst eine Vielzahl an Eissorten, die mit hochwertigen Zutaten zubereitet werden.\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/franken-eis-2\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/franken-eis-2\/\",\"name\":\"Franken-Eis - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-05-12T00:29:04+00:00\",\"dateModified\":\"2026-05-12T00:29:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/franken-eis-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/franken-eis-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/franken-eis-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culinary\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/culinary\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Franken-Eis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Franken-Eis - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/franken-eis-2\/","og_locale":"en_US","og_type":"article","og_title":"Franken-Eis - Stadt. Land. Niederrhein","og_description":"Franken-Eis in Krefeld ist eine Eisdiele, die mediterrane und italienische Eisspezialit\u00e4ten bietet. Die Lage in der Stadt Krefeld erm\u00f6glicht einen einfachen Zugang f\u00fcr Besucher:innen. Die Speisekarte umfasst eine Vielzahl an Eissorten, die mit hochwertigen Zutaten zubereitet werden.","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/franken-eis-2\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/franken-eis-2\/","name":"Franken-Eis - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-05-12T00:29:04+00:00","dateModified":"2026-05-12T00:29:04+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/franken-eis-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/franken-eis-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/franken-eis-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culinary","item":"https:\/\/stadt-land-niederrhein.de\/en\/culinary\/"},{"@type":"ListItem","position":3,"name":"Franken-Eis"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/119889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/restaurant"}],"version-history":[{"count":2,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/119889\/revisions"}],"predecessor-version":[{"id":121887,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/119889\/revisions\/121887"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=119889"}],"wp:term":[{"taxonomy":"cuisine","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/cuisines?post=119889"},{"taxonomy":"feature","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/features?post=119889"},{"taxonomy":"kitchen_offer","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/kitchen_offers?post=119889"},{"taxonomy":"operating_mode","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/operating_modes?post=119889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}