{"id":133749,"date":"2026-09-02T01:08:21","date_gmt":"2026-09-01T23:08:21","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kulinarik\/alt-peddenberg\/"},"modified":"2026-09-02T01:08:21","modified_gmt":"2026-09-01T23:08:21","slug":"alt-peddenberg","status":"publish","type":"restaurant","link":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/alt-peddenberg\/","title":{"rendered":"Alt-Peddenberg"},"content":{"rendered":"<p>Das Haus &#8220;Alt-Peddenberg&#8221; befindet sich zentral in H\u00fcnxe-Drevenack und bietet eine gutb\u00fcrgerliche K\u00fcche. Die Gastst\u00e4tte verf\u00fcgt \u00fcber zwei Kegelbahnen und Gesellschaftsr\u00e4ume f\u00fcr bis zu 150 Personen. Eine gro\u00dfz\u00fcgige Terrasse l\u00e4dt zum Verweilen ein. Die Familie Vennmann bietet zudem Catering-Dienstleistungen an.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Haus &#8220;Alt-Peddenberg&#8221; befindet sich zentral in H\u00fcnxe-Drevenack und bietet eine gutb\u00fcrgerliche K\u00fcche. Die Gastst\u00e4tte verf\u00fcgt \u00fcber zwei Kegelbahnen und Gesellschaftsr\u00e4ume f\u00fcr bis zu 150 Personen. Eine gro\u00dfz\u00fcgige Terrasse l\u00e4dt zum Verweilen ein. Die Familie Vennmann bietet zudem Catering-Dienstleistungen an.<\/p>\n","protected":false},"author":0,"featured_media":99425,"template":"","cuisines":[],"features":[],"kitchen_offers":[],"operating_modes":[244,92,243],"class_list":["post-133749","restaurant","type-restaurant","status-publish","has-post-thumbnail","hentry","operating_mode-gaststaetten","operating_mode-restaurant","operating_mode-trinkgenuss"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alt-Peddenberg - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/alt-peddenberg\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alt-Peddenberg - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Das Haus &#8220;Alt-Peddenberg&#8221; befindet sich zentral in H\u00fcnxe-Drevenack und bietet eine gutb\u00fcrgerliche K\u00fcche. Die Gastst\u00e4tte verf\u00fcgt \u00fcber zwei Kegelbahnen und Gesellschaftsr\u00e4ume f\u00fcr bis zu 150 Personen. Eine gro\u00dfz\u00fcgige Terrasse l\u00e4dt zum Verweilen ein. Die Familie Vennmann bietet zudem Catering-Dienstleistungen an.\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/gastst-tte-alt-peddenberg-in-h-nxe-drevenack.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/alt-peddenberg\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/alt-peddenberg\/\",\"name\":\"Alt-Peddenberg - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-09-01T23:08:21+00:00\",\"dateModified\":\"2026-09-01T23:08:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/alt-peddenberg\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/alt-peddenberg\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/alt-peddenberg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culinary\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/culinary\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alt-Peddenberg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alt-Peddenberg - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/alt-peddenberg\/","og_locale":"en_US","og_type":"article","og_title":"Alt-Peddenberg - Stadt. Land. Niederrhein","og_description":"Das Haus &#8220;Alt-Peddenberg&#8221; befindet sich zentral in H\u00fcnxe-Drevenack und bietet eine gutb\u00fcrgerliche K\u00fcche. Die Gastst\u00e4tte verf\u00fcgt \u00fcber zwei Kegelbahnen und Gesellschaftsr\u00e4ume f\u00fcr bis zu 150 Personen. Eine gro\u00dfz\u00fcgige Terrasse l\u00e4dt zum Verweilen ein. Die Familie Vennmann bietet zudem Catering-Dienstleistungen an.","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":1024,"height":683,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/gastst-tte-alt-peddenberg-in-h-nxe-drevenack.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/alt-peddenberg\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/alt-peddenberg\/","name":"Alt-Peddenberg - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-09-01T23:08:21+00:00","dateModified":"2026-09-01T23:08:21+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/alt-peddenberg\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/alt-peddenberg\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/alt-peddenberg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culinary","item":"https:\/\/stadt-land-niederrhein.de\/en\/culinary\/"},{"@type":"ListItem","position":3,"name":"Alt-Peddenberg"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/133749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/restaurant"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/133749\/revisions"}],"predecessor-version":[{"id":134022,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/133749\/revisions\/134022"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/99425"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=133749"}],"wp:term":[{"taxonomy":"cuisine","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/cuisines?post=133749"},{"taxonomy":"feature","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/features?post=133749"},{"taxonomy":"kitchen_offer","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/kitchen_offers?post=133749"},{"taxonomy":"operating_mode","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/operating_modes?post=133749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}