{"id":135786,"date":"2026-09-02T01:07:20","date_gmt":"2026-09-01T23:07:20","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kulinarik\/hellas-griechisches-restaurant\/"},"modified":"2026-09-02T01:07:20","modified_gmt":"2026-09-01T23:07:20","slug":"hellas-griechisches-restaurant","status":"publish","type":"restaurant","link":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/hellas-griechisches-restaurant\/","title":{"rendered":"Hellas \u2013 Griechisches Restaurant"},"content":{"rendered":"<p>Das griechische Restaurant \u201eHellas\u201c befindet sich seit \u00fcber 30 Jahren am Gro\u00dfen Markt in Wesel, direkt neben dem historischen Rathaus und dem Willibrordi-Dom. Der Familienbetrieb bietet 80 Sitzpl\u00e4tze im Innen- und Au\u00dfenbereich und richtet sich an ein breites Publikum.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das griechische Restaurant \u201eHellas\u201c befindet sich seit \u00fcber 30 Jahren am Gro\u00dfen Markt in Wesel, direkt neben dem historischen Rathaus und dem Willibrordi-Dom. Der Familienbetrieb bietet 80 Sitzpl\u00e4tze im Innen- und Au\u00dfenbereich und richtet sich an ein breites Publikum.<\/p>\n","protected":false},"author":0,"featured_media":99232,"template":"","cuisines":[],"features":[],"kitchen_offers":[],"operating_modes":[244,92],"class_list":["post-135786","restaurant","type-restaurant","status-publish","has-post-thumbnail","hentry","operating_mode-gaststaetten","operating_mode-restaurant"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hellas \u2013 Griechisches Restaurant - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/hellas-griechisches-restaurant\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hellas \u2013 Griechisches Restaurant - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Das griechische Restaurant \u201eHellas\u201c befindet sich seit \u00fcber 30 Jahren am Gro\u00dfen Markt in Wesel, direkt neben dem historischen Rathaus und dem Willibrordi-Dom. Der Familienbetrieb bietet 80 Sitzpl\u00e4tze im Innen- und Au\u00dfenbereich und richtet sich an ein breites Publikum.\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/hellas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/hellas-griechisches-restaurant\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/hellas-griechisches-restaurant\/\",\"name\":\"Hellas \u2013 Griechisches Restaurant - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-09-01T23:07:20+00:00\",\"dateModified\":\"2026-09-01T23:07:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/hellas-griechisches-restaurant\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/hellas-griechisches-restaurant\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/hellas-griechisches-restaurant\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culinary\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/culinary\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hellas \u2013 Griechisches Restaurant\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hellas \u2013 Griechisches Restaurant - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/hellas-griechisches-restaurant\/","og_locale":"en_US","og_type":"article","og_title":"Hellas \u2013 Griechisches Restaurant - Stadt. Land. Niederrhein","og_description":"Das griechische Restaurant \u201eHellas\u201c befindet sich seit \u00fcber 30 Jahren am Gro\u00dfen Markt in Wesel, direkt neben dem historischen Rathaus und dem Willibrordi-Dom. Der Familienbetrieb bietet 80 Sitzpl\u00e4tze im Innen- und Au\u00dfenbereich und richtet sich an ein breites Publikum.","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":640,"height":480,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/hellas.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/hellas-griechisches-restaurant\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/hellas-griechisches-restaurant\/","name":"Hellas \u2013 Griechisches Restaurant - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-09-01T23:07:20+00:00","dateModified":"2026-09-01T23:07:20+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/hellas-griechisches-restaurant\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/hellas-griechisches-restaurant\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/hellas-griechisches-restaurant\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culinary","item":"https:\/\/stadt-land-niederrhein.de\/en\/culinary\/"},{"@type":"ListItem","position":3,"name":"Hellas \u2013 Griechisches Restaurant"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/135786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/restaurant"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/135786\/revisions"}],"predecessor-version":[{"id":136005,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/135786\/revisions\/136005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/99232"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=135786"}],"wp:term":[{"taxonomy":"cuisine","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/cuisines?post=135786"},{"taxonomy":"feature","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/features?post=135786"},{"taxonomy":"kitchen_offer","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/kitchen_offers?post=135786"},{"taxonomy":"operating_mode","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/operating_modes?post=135786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}