{"id":135913,"date":"2026-09-02T01:07:03","date_gmt":"2026-09-01T23:07:03","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kulinarik\/kolkshof-buedchen\/"},"modified":"2026-09-02T01:07:03","modified_gmt":"2026-09-01T23:07:03","slug":"kolkshof-buedchen","status":"publish","type":"restaurant","link":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kolkshof-buedchen\/","title":{"rendered":"Kolkshof B\u00fcdchen"},"content":{"rendered":"<p>Das Kolkshof B\u00fcdchen bietet eine Auswahl an selbstgemachtem Kuchen, frischen Waffeln und regionalem Landeis aus Kevelaer. Erg\u00e4nzt wird das Angebot durch Hei\u00df- und Kaltgetr\u00e4nke. Vor Ort kann das Fleisch der Limousinrinder im \u201eKolkshofs Burger\u201c probiert werden. Auch Grill- und Mettw\u00fcrstchen von der Metzgerei R\u00fchl sind erh\u00e4ltlich. Der Au\u00dfenbereich bietet gem\u00fctliche Sitzpl\u00e4tze, teilweise \u00fcberdacht, sowie Steckdosen f\u00fcr E-Bikes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Kolkshof B\u00fcdchen bietet eine Auswahl an selbstgemachtem Kuchen, frischen Waffeln und regionalem Landeis aus Kevelaer. Erg\u00e4nzt wird das Angebot durch Hei\u00df- und Kaltgetr\u00e4nke. Vor Ort kann das Fleisch der Limousinrinder im \u201eKolkshofs Burger\u201c probiert werden. Auch Grill- und Mettw\u00fcrstchen von der Metzgerei R\u00fchl sind erh\u00e4ltlich. Der Au\u00dfenbereich bietet gem\u00fctliche Sitzpl\u00e4tze, teilweise \u00fcberdacht, sowie Steckdosen [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":107973,"template":"","cuisines":[],"features":[],"kitchen_offers":[],"operating_modes":[244,92],"class_list":["post-135913","restaurant","type-restaurant","status-publish","has-post-thumbnail","hentry","operating_mode-gaststaetten","operating_mode-restaurant"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kolkshof B\u00fcdchen - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kolkshof-buedchen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kolkshof B\u00fcdchen - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Das Kolkshof B\u00fcdchen bietet eine Auswahl an selbstgemachtem Kuchen, frischen Waffeln und regionalem Landeis aus Kevelaer. Erg\u00e4nzt wird das Angebot durch Hei\u00df- und Kaltgetr\u00e4nke. Vor Ort kann das Fleisch der Limousinrinder im \u201eKolkshofs Burger\u201c probiert werden. Auch Grill- und Mettw\u00fcrstchen von der Metzgerei R\u00fchl sind erh\u00e4ltlich. Der Au\u00dfenbereich bietet gem\u00fctliche Sitzpl\u00e4tze, teilweise \u00fcberdacht, sowie Steckdosen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/05\/kolkshof-b-dchen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kolkshof-buedchen\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kolkshof-buedchen\/\",\"name\":\"Kolkshof B\u00fcdchen - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-09-01T23:07:03+00:00\",\"dateModified\":\"2026-09-01T23:07:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kolkshof-buedchen\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kolkshof-buedchen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kolkshof-buedchen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culinary\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/culinary\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kolkshof B\u00fcdchen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kolkshof B\u00fcdchen - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kolkshof-buedchen\/","og_locale":"en_US","og_type":"article","og_title":"Kolkshof B\u00fcdchen - Stadt. Land. Niederrhein","og_description":"Das Kolkshof B\u00fcdchen bietet eine Auswahl an selbstgemachtem Kuchen, frischen Waffeln und regionalem Landeis aus Kevelaer. Erg\u00e4nzt wird das Angebot durch Hei\u00df- und Kaltgetr\u00e4nke. Vor Ort kann das Fleisch der Limousinrinder im \u201eKolkshofs Burger\u201c probiert werden. Auch Grill- und Mettw\u00fcrstchen von der Metzgerei R\u00fchl sind erh\u00e4ltlich. Der Au\u00dfenbereich bietet gem\u00fctliche Sitzpl\u00e4tze, teilweise \u00fcberdacht, sowie Steckdosen [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":1536,"height":2048,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/05\/kolkshof-b-dchen.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kolkshof-buedchen\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kolkshof-buedchen\/","name":"Kolkshof B\u00fcdchen - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-09-01T23:07:03+00:00","dateModified":"2026-09-01T23:07:03+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kolkshof-buedchen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kolkshof-buedchen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/kolkshof-buedchen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culinary","item":"https:\/\/stadt-land-niederrhein.de\/en\/culinary\/"},{"@type":"ListItem","position":3,"name":"Kolkshof B\u00fcdchen"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/135913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/restaurant"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/135913\/revisions"}],"predecessor-version":[{"id":136132,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/135913\/revisions\/136132"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/107973"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=135913"}],"wp:term":[{"taxonomy":"cuisine","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/cuisines?post=135913"},{"taxonomy":"feature","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/features?post=135913"},{"taxonomy":"kitchen_offer","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/kitchen_offers?post=135913"},{"taxonomy":"operating_mode","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/operating_modes?post=135913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}