{"id":135919,"date":"2026-09-02T01:08:49","date_gmt":"2026-09-01T23:08:49","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kulinarik\/gaststaette-dames\/"},"modified":"2026-09-02T01:08:49","modified_gmt":"2026-09-01T23:08:49","slug":"gaststaette-dames","status":"publish","type":"restaurant","link":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/gaststaette-dames\/","title":{"rendered":"Gastst\u00e4tte Dames"},"content":{"rendered":"<p>Gastst\u00e4tte Dames, die \u00e4lteste Dorfgastst\u00e4tte in H\u00fcnxe, bietet eine gutb\u00fcrgerliche K\u00fcche und l\u00e4dt mit ihrem Biergarten zu entspannten Stunden ein. Direkt am Rathaus gelegen, verf\u00fcgt sie \u00fcber Gesellschaftsr\u00e4ume f\u00fcr diverse Anl\u00e4sse. Im Sommer finden regelm\u00e4\u00dfig Grillabende statt, die ein besonderes kulinarisches Erlebnis bieten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gastst\u00e4tte Dames, die \u00e4lteste Dorfgastst\u00e4tte in H\u00fcnxe, bietet eine gutb\u00fcrgerliche K\u00fcche und l\u00e4dt mit ihrem Biergarten zu entspannten Stunden ein. Direkt am Rathaus gelegen, verf\u00fcgt sie \u00fcber Gesellschaftsr\u00e4ume f\u00fcr diverse Anl\u00e4sse. Im Sommer finden regelm\u00e4\u00dfig Grillabende statt, die ein besonderes kulinarisches Erlebnis bieten.<\/p>\n","protected":false},"author":0,"featured_media":99251,"template":"","cuisines":[],"features":[],"kitchen_offers":[],"operating_modes":[244,92,243],"class_list":["post-135919","restaurant","type-restaurant","status-publish","has-post-thumbnail","hentry","operating_mode-gaststaetten","operating_mode-restaurant","operating_mode-trinkgenuss"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gastst\u00e4tte Dames - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/gaststaette-dames\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gastst\u00e4tte Dames - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Gastst\u00e4tte Dames, die \u00e4lteste Dorfgastst\u00e4tte in H\u00fcnxe, bietet eine gutb\u00fcrgerliche K\u00fcche und l\u00e4dt mit ihrem Biergarten zu entspannten Stunden ein. Direkt am Rathaus gelegen, verf\u00fcgt sie \u00fcber Gesellschaftsr\u00e4ume f\u00fcr diverse Anl\u00e4sse. Im Sommer finden regelm\u00e4\u00dfig Grillabende statt, die ein besonderes kulinarisches Erlebnis bieten.\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/gastst-tte-dames.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"613\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/gaststaette-dames\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/gaststaette-dames\/\",\"name\":\"Gastst\u00e4tte Dames - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\"},\"datePublished\":\"2026-09-01T23:08:49+00:00\",\"dateModified\":\"2026-09-01T23:08:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/gaststaette-dames\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/gaststaette-dames\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/gaststaette-dames\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culinary\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/en\/culinary\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gastst\u00e4tte Dames\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gastst\u00e4tte Dames - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/gaststaette-dames\/","og_locale":"en_US","og_type":"article","og_title":"Gastst\u00e4tte Dames - Stadt. Land. Niederrhein","og_description":"Gastst\u00e4tte Dames, die \u00e4lteste Dorfgastst\u00e4tte in H\u00fcnxe, bietet eine gutb\u00fcrgerliche K\u00fcche und l\u00e4dt mit ihrem Biergarten zu entspannten Stunden ein. Direkt am Rathaus gelegen, verf\u00fcgt sie \u00fcber Gesellschaftsr\u00e4ume f\u00fcr diverse Anl\u00e4sse. Im Sommer finden regelm\u00e4\u00dfig Grillabende statt, die ein besonderes kulinarisches Erlebnis bieten.","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":960,"height":613,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/gastst-tte-dames.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/gaststaette-dames\/","url":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/gaststaette-dames\/","name":"Gastst\u00e4tte Dames - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website"},"datePublished":"2026-09-01T23:08:49+00:00","dateModified":"2026-09-01T23:08:49+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/gaststaette-dames\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/gaststaette-dames\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/en\/kulinarik\/gaststaette-dames\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/stadt-land-niederrhein.de\/en\/"},{"@type":"ListItem","position":2,"name":"Culinary","item":"https:\/\/stadt-land-niederrhein.de\/en\/culinary\/"},{"@type":"ListItem","position":3,"name":"Gastst\u00e4tte Dames"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#website","url":"https:\/\/stadt-land-niederrhein.de\/en\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/135919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/types\/restaurant"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/135919\/revisions"}],"predecessor-version":[{"id":136138,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/restaurants\/135919\/revisions\/136138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media\/99251"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/media?parent=135919"}],"wp:term":[{"taxonomy":"cuisine","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/cuisines?post=135919"},{"taxonomy":"feature","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/features?post=135919"},{"taxonomy":"kitchen_offer","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/kitchen_offers?post=135919"},{"taxonomy":"operating_mode","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/en\/wp-json\/wp\/v2\/operating_modes?post=135919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}