{"id":106100,"date":"2026-05-12T01:50:14","date_gmt":"2026-05-11T23:50:14","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/gastgeber\/schermbecker-waldhuette\/"},"modified":"2026-05-12T01:50:14","modified_gmt":"2026-05-11T23:50:14","slug":"schermbecker-waldhuette","status":"publish","type":"host","link":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/schermbecker-waldhuette\/","title":{"rendered":"Schermbecker Waldh\u00fctte"},"content":{"rendered":"<p>Die Schermbecker Waldh\u00fctte pr\u00e4sentiert sich als erstklassige Location f\u00fcr private und gesch\u00e4ftliche Veranstaltungen. Sie erm\u00f6glicht es, inmitten der Natur erholsame Wochenenden oder festliche Anl\u00e4sse zu genie\u00dfen. Die gem\u00fctliche Unterkunft bietet Platz f\u00fcr bis zu 21 G\u00e4ste, verteilt auf Zimmer mit jeweils 3 bis 6 Betten. Die vollst\u00e4ndig m\u00f6blierte Ausstattung gew\u00e4hrleistet Komfort und Flexibilit\u00e4t, ideal f\u00fcr Gruppen, die sowohl unter der Woche als auch am Wochenende an diesem idyllischen Ort verweilen m\u00f6chten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Schermbecker Waldh\u00fctte pr\u00e4sentiert sich als erstklassige Location f\u00fcr private und gesch\u00e4ftliche Veranstaltungen. Sie erm\u00f6glicht es, inmitten der Natur erholsame Wochenenden oder festliche Anl\u00e4sse zu genie\u00dfen. Die gem\u00fctliche Unterkunft bietet Platz f\u00fcr bis zu 21 G\u00e4ste, verteilt auf Zimmer mit jeweils 3 bis 6 Betten. Die vollst\u00e4ndig m\u00f6blierte Ausstattung gew\u00e4hrleistet Komfort und Flexibilit\u00e4t, ideal f\u00fcr [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":106101,"template":"","accommodation_types":[148],"class_list":["post-106100","host","type-host","status-publish","has-post-thumbnail","hentry","accommodation_type-besondere-unterkunft"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Schermbecker Waldh\u00fctte - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/schermbecker-waldhuette\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schermbecker Waldh\u00fctte - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Die Schermbecker Waldh\u00fctte pr\u00e4sentiert sich als erstklassige Location f\u00fcr private und gesch\u00e4ftliche Veranstaltungen. Sie erm\u00f6glicht es, inmitten der Natur erholsame Wochenenden oder festliche Anl\u00e4sse zu genie\u00dfen. Die gem\u00fctliche Unterkunft bietet Platz f\u00fcr bis zu 21 G\u00e4ste, verteilt auf Zimmer mit jeweils 3 bis 6 Betten. Die vollst\u00e4ndig m\u00f6blierte Ausstattung gew\u00e4hrleistet Komfort und Flexibilit\u00e4t, ideal f\u00fcr [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/04\/au-enansicht-waldh-tte.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2040\" \/>\n\t<meta property=\"og:image:height\" content=\"1530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/schermbecker-waldhuette\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/schermbecker-waldhuette\/\",\"name\":\"Schermbecker Waldh\u00fctte - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-05-11T23:50:14+00:00\",\"dateModified\":\"2026-05-11T23:50:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/schermbecker-waldhuette\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/schermbecker-waldhuette\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/schermbecker-waldhuette\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gastgeber\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Schermbecker Waldh\u00fctte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schermbecker Waldh\u00fctte - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/schermbecker-waldhuette\/","og_locale":"nl_NL","og_type":"article","og_title":"Schermbecker Waldh\u00fctte - Stadt. Land. Niederrhein","og_description":"Die Schermbecker Waldh\u00fctte pr\u00e4sentiert sich als erstklassige Location f\u00fcr private und gesch\u00e4ftliche Veranstaltungen. Sie erm\u00f6glicht es, inmitten der Natur erholsame Wochenenden oder festliche Anl\u00e4sse zu genie\u00dfen. Die gem\u00fctliche Unterkunft bietet Platz f\u00fcr bis zu 21 G\u00e4ste, verteilt auf Zimmer mit jeweils 3 bis 6 Betten. Die vollst\u00e4ndig m\u00f6blierte Ausstattung gew\u00e4hrleistet Komfort und Flexibilit\u00e4t, ideal f\u00fcr [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2040,"height":1530,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/04\/au-enansicht-waldh-tte.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/schermbecker-waldhuette\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/schermbecker-waldhuette\/","name":"Schermbecker Waldh\u00fctte - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-05-11T23:50:14+00:00","dateModified":"2026-05-11T23:50:14+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/schermbecker-waldhuette\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/schermbecker-waldhuette\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/schermbecker-waldhuette\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Gastgeber","item":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/"},{"@type":"ListItem","position":3,"name":"Schermbecker Waldh\u00fctte"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts\/106100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/host"}],"version-history":[{"count":3,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts\/106100\/revisions"}],"predecessor-version":[{"id":123463,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts\/106100\/revisions\/123463"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media\/106101"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=106100"}],"wp:term":[{"taxonomy":"accommodation_type","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/accommodation_types?post=106100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}