{"id":108691,"date":"2026-05-12T01:51:20","date_gmt":"2026-05-11T23:51:20","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/gastgeber\/ferienhaus-villa-klara-2\/"},"modified":"2026-05-12T01:51:20","modified_gmt":"2026-05-11T23:51:20","slug":"ferienhaus-villa-klara-2","status":"publish","type":"host","link":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-villa-klara-2\/","title":{"rendered":"Ferienhaus Villa Klara"},"content":{"rendered":"<p>Das Ferienhaus Villa Klara pr\u00e4sentiert sich als gem\u00fctliches Blockbohlenhaus mit gehobener Ausstattung auf 45 qm. Im charmanten Ortsteil Krudenburg gelegen, bietet die Unterkunft einen gro\u00dfen Garten mit Pavillon, ideal zum Entspannen. Nahe am renaturierten &#8220;Alten Lippehafen&#8221; verspricht die Lage Ruhe und Erholung. Die Einrichtung ist komplett und individuell gestaltet, was eine behagliche Atmosph\u00e4re schafft. Perfekt f\u00fcr einen erholsamen Aufenthalt in nat\u00fcrlicher Umgebung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Ferienhaus Villa Klara pr\u00e4sentiert sich als gem\u00fctliches Blockbohlenhaus mit gehobener Ausstattung auf 45 qm. Im charmanten Ortsteil Krudenburg gelegen, bietet die Unterkunft einen gro\u00dfen Garten mit Pavillon, ideal zum Entspannen. Nahe am renaturierten &#8220;Alten Lippehafen&#8221; verspricht die Lage Ruhe und Erholung. Die Einrichtung ist komplett und individuell gestaltet, was eine behagliche Atmosph\u00e4re schafft. Perfekt [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":119138,"template":"","accommodation_types":[139,138],"class_list":["post-108691","host","type-host","status-publish","has-post-thumbnail","hentry","accommodation_type-ferienhaus","accommodation_type-ferienwohnung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ferienhaus Villa Klara - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-villa-klara-2\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferienhaus Villa Klara - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Das Ferienhaus Villa Klara pr\u00e4sentiert sich als gem\u00fctliches Blockbohlenhaus mit gehobener Ausstattung auf 45 qm. Im charmanten Ortsteil Krudenburg gelegen, bietet die Unterkunft einen gro\u00dfen Garten mit Pavillon, ideal zum Entspannen. Nahe am renaturierten &#8220;Alten Lippehafen&#8221; verspricht die Lage Ruhe und Erholung. Die Einrichtung ist komplett und individuell gestaltet, was eine behagliche Atmosph\u00e4re schafft. Perfekt [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/10\/ferienhaus-krudenburg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-villa-klara-2\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-villa-klara-2\/\",\"name\":\"Ferienhaus Villa Klara - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-05-11T23:51:20+00:00\",\"dateModified\":\"2026-05-11T23:51:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-villa-klara-2\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-villa-klara-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-villa-klara-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gastgeber\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ferienhaus Villa Klara\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ferienhaus Villa Klara - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-villa-klara-2\/","og_locale":"nl_NL","og_type":"article","og_title":"Ferienhaus Villa Klara - Stadt. Land. Niederrhein","og_description":"Das Ferienhaus Villa Klara pr\u00e4sentiert sich als gem\u00fctliches Blockbohlenhaus mit gehobener Ausstattung auf 45 qm. Im charmanten Ortsteil Krudenburg gelegen, bietet die Unterkunft einen gro\u00dfen Garten mit Pavillon, ideal zum Entspannen. Nahe am renaturierten &#8220;Alten Lippehafen&#8221; verspricht die Lage Ruhe und Erholung. Die Einrichtung ist komplett und individuell gestaltet, was eine behagliche Atmosph\u00e4re schafft. Perfekt [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":1024,"height":768,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/10\/ferienhaus-krudenburg.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-villa-klara-2\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-villa-klara-2\/","name":"Ferienhaus Villa Klara - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-05-11T23:51:20+00:00","dateModified":"2026-05-11T23:51:20+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-villa-klara-2\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-villa-klara-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-villa-klara-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Gastgeber","item":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/"},{"@type":"ListItem","position":3,"name":"Ferienhaus Villa Klara"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts\/108691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/host"}],"version-history":[{"count":5,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts\/108691\/revisions"}],"predecessor-version":[{"id":123460,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts\/108691\/revisions\/123460"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media\/119138"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=108691"}],"wp:term":[{"taxonomy":"accommodation_type","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/accommodation_types?post=108691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}