{"id":108720,"date":"2026-05-12T01:46:51","date_gmt":"2026-05-11T23:46:51","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/gastgeber\/erholungszentrum-grav-insel-2\/"},"modified":"2026-05-12T01:46:51","modified_gmt":"2026-05-11T23:46:51","slug":"erholungszentrum-grav-insel-2","status":"publish","type":"host","link":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/erholungszentrum-grav-insel-2\/","title":{"rendered":"Erholungszentrum Grav-Insel"},"content":{"rendered":"<p>Das Erholungszentrum Grav-Insel bietet ein Campingvergn\u00fcgen am Niederrhein, ideal f\u00fcr Familien. Unweit von Wesel gelegen, besticht der Campingplatz durch seine Lage am Wasser, eingebettet in eine malerische Auen- und Wiesenlandschaft. Von Saisonstellpl\u00e4tzen direkt am Ufer bis hin zu ganzj\u00e4hrigen Dauerpl\u00e4tzen, hier finden Naturliebhaber:innen den perfekten R\u00fcckzugsort. Die Umgebung lockt mit weitl\u00e4ufigen Landschaften, historischen St\u00e4dten und kulturellen Sch\u00e4tzen, die das Zusammenspiel von Natur und Geschichte widerspiegeln.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Erholungszentrum Grav-Insel bietet ein Campingvergn\u00fcgen am Niederrhein, ideal f\u00fcr Familien. Unweit von Wesel gelegen, besticht der Campingplatz durch seine Lage am Wasser, eingebettet in eine malerische Auen- und Wiesenlandschaft. Von Saisonstellpl\u00e4tzen direkt am Ufer bis hin zu ganzj\u00e4hrigen Dauerpl\u00e4tzen, hier finden Naturliebhaber:innen den perfekten R\u00fcckzugsort. Die Umgebung lockt mit weitl\u00e4ufigen Landschaften, historischen St\u00e4dten und [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":103739,"template":"","accommodation_types":[142],"class_list":["post-108720","host","type-host","status-publish","has-post-thumbnail","hentry","accommodation_type-campingplatz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Erholungszentrum Grav-Insel - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/erholungszentrum-grav-insel-2\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erholungszentrum Grav-Insel - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Das Erholungszentrum Grav-Insel bietet ein Campingvergn\u00fcgen am Niederrhein, ideal f\u00fcr Familien. Unweit von Wesel gelegen, besticht der Campingplatz durch seine Lage am Wasser, eingebettet in eine malerische Auen- und Wiesenlandschaft. Von Saisonstellpl\u00e4tzen direkt am Ufer bis hin zu ganzj\u00e4hrigen Dauerpl\u00e4tzen, hier finden Naturliebhaber:innen den perfekten R\u00fcckzugsort. Die Umgebung lockt mit weitl\u00e4ufigen Landschaften, historischen St\u00e4dten und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/03\/campingplatz-gravinsel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/erholungszentrum-grav-insel-2\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/erholungszentrum-grav-insel-2\/\",\"name\":\"Erholungszentrum Grav-Insel - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-05-11T23:46:51+00:00\",\"dateModified\":\"2026-05-11T23:46:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/erholungszentrum-grav-insel-2\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/erholungszentrum-grav-insel-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/erholungszentrum-grav-insel-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gastgeber\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Erholungszentrum Grav-Insel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erholungszentrum Grav-Insel - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/erholungszentrum-grav-insel-2\/","og_locale":"nl_NL","og_type":"article","og_title":"Erholungszentrum Grav-Insel - Stadt. Land. Niederrhein","og_description":"Das Erholungszentrum Grav-Insel bietet ein Campingvergn\u00fcgen am Niederrhein, ideal f\u00fcr Familien. Unweit von Wesel gelegen, besticht der Campingplatz durch seine Lage am Wasser, eingebettet in eine malerische Auen- und Wiesenlandschaft. Von Saisonstellpl\u00e4tzen direkt am Ufer bis hin zu ganzj\u00e4hrigen Dauerpl\u00e4tzen, hier finden Naturliebhaber:innen den perfekten R\u00fcckzugsort. Die Umgebung lockt mit weitl\u00e4ufigen Landschaften, historischen St\u00e4dten und [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2048,"height":1152,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/03\/campingplatz-gravinsel.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/erholungszentrum-grav-insel-2\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/erholungszentrum-grav-insel-2\/","name":"Erholungszentrum Grav-Insel - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-05-11T23:46:51+00:00","dateModified":"2026-05-11T23:46:51+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/erholungszentrum-grav-insel-2\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/erholungszentrum-grav-insel-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/erholungszentrum-grav-insel-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Gastgeber","item":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/"},{"@type":"ListItem","position":3,"name":"Erholungszentrum Grav-Insel"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts\/108720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/host"}],"version-history":[{"count":2,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts\/108720\/revisions"}],"predecessor-version":[{"id":123739,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts\/108720\/revisions\/123739"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media\/103739"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=108720"}],"wp:term":[{"taxonomy":"accommodation_type","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/accommodation_types?post=108720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}