{"id":108757,"date":"2026-05-12T01:49:40","date_gmt":"2026-05-11T23:49:40","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/gastgeber\/hotel-zur-aue-2\/"},"modified":"2026-05-12T01:49:40","modified_gmt":"2026-05-11T23:49:40","slug":"hotel-zur-aue-2","status":"publish","type":"host","link":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/hotel-zur-aue-2\/","title":{"rendered":"Hotel Zur Aue"},"content":{"rendered":"<p>Hotel Zur Aue in Wesel bietet eine einladende Unterkunft f\u00fcr preisbewusste Reisende, die Wert auf zentrale Erreichbarkeit legen. In nur wenigen Gehminuten befindet sich die lebendige Stadtmitte, die zur Erkundung zahlreicher kultureller und gastronomischer Angebote einl\u00e4dt. Das Hotel zeichnet sich durch seinen freundlichen Service und die komfortable Ausstattung aus, die einen angenehmen Aufenthalt sicherstellen. Gesch\u00e4ftsreisende und Urlauber finden hier gleicherma\u00dfen ideale Voraussetzungen f\u00fcr ihre Anspr\u00fcche.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hotel Zur Aue in Wesel bietet eine einladende Unterkunft f\u00fcr preisbewusste Reisende, die Wert auf zentrale Erreichbarkeit legen. In nur wenigen Gehminuten befindet sich die lebendige Stadtmitte, die zur Erkundung zahlreicher kultureller und gastronomischer Angebote einl\u00e4dt. Das Hotel zeichnet sich durch seinen freundlichen Service und die komfortable Ausstattung aus, die einen angenehmen Aufenthalt sicherstellen. Gesch\u00e4ftsreisende [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":103339,"template":"","accommodation_types":[132],"class_list":["post-108757","host","type-host","status-publish","has-post-thumbnail","hentry","accommodation_type-hotel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hotel Zur Aue - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/hotel-zur-aue-2\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hotel Zur Aue - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Hotel Zur Aue in Wesel bietet eine einladende Unterkunft f\u00fcr preisbewusste Reisende, die Wert auf zentrale Erreichbarkeit legen. In nur wenigen Gehminuten befindet sich die lebendige Stadtmitte, die zur Erkundung zahlreicher kultureller und gastronomischer Angebote einl\u00e4dt. Das Hotel zeichnet sich durch seinen freundlichen Service und die komfortable Ausstattung aus, die einen angenehmen Aufenthalt sicherstellen. Gesch\u00e4ftsreisende [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/03\/hotel-in-der-aue_au-enansicht.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/hotel-zur-aue-2\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/hotel-zur-aue-2\/\",\"name\":\"Hotel Zur Aue - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-05-11T23:49:40+00:00\",\"dateModified\":\"2026-05-11T23:49:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/hotel-zur-aue-2\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/hotel-zur-aue-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/hotel-zur-aue-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gastgeber\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hotel Zur Aue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hotel Zur Aue - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/hotel-zur-aue-2\/","og_locale":"nl_NL","og_type":"article","og_title":"Hotel Zur Aue - Stadt. Land. Niederrhein","og_description":"Hotel Zur Aue in Wesel bietet eine einladende Unterkunft f\u00fcr preisbewusste Reisende, die Wert auf zentrale Erreichbarkeit legen. In nur wenigen Gehminuten befindet sich die lebendige Stadtmitte, die zur Erkundung zahlreicher kultureller und gastronomischer Angebote einl\u00e4dt. Das Hotel zeichnet sich durch seinen freundlichen Service und die komfortable Ausstattung aus, die einen angenehmen Aufenthalt sicherstellen. Gesch\u00e4ftsreisende [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":800,"height":533,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/03\/hotel-in-der-aue_au-enansicht.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/hotel-zur-aue-2\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/hotel-zur-aue-2\/","name":"Hotel Zur Aue - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-05-11T23:49:40+00:00","dateModified":"2026-05-11T23:49:40+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/hotel-zur-aue-2\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/hotel-zur-aue-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/hotel-zur-aue-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Gastgeber","item":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/"},{"@type":"ListItem","position":3,"name":"Hotel Zur Aue"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts\/108757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/host"}],"version-history":[{"count":2,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts\/108757\/revisions"}],"predecessor-version":[{"id":123974,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts\/108757\/revisions\/123974"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media\/103339"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=108757"}],"wp:term":[{"taxonomy":"accommodation_type","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/accommodation_types?post=108757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}