{"id":130200,"date":"2026-05-11T03:25:19","date_gmt":"2026-05-11T01:25:19","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/gastgeber\/ferienhaus-craemer\/"},"modified":"2026-05-11T03:25:19","modified_gmt":"2026-05-11T01:25:19","slug":"ferienhaus-craemer","status":"publish","type":"host","link":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-craemer\/","title":{"rendered":"Ferienhaus Cr\u00e4mer"},"content":{"rendered":"<p>Das Ferienhaus Cr\u00e4mer in Wassenberg bietet eine komfortable Unterkunft, die sich durch ihre idyllische Lage und modernen Annehmlichkeiten auszeichnet. Gelegen im Landkreis Heinsberg, l\u00e4dt das Ferienhaus dazu ein, die umliegende Natur zu entdecken und zahlreiche Freizeitm\u00f6glichkeiten zu nutzen. Die stilvoll eingerichteten R\u00e4ume sorgen f\u00fcr eine erholsame Atmosph\u00e4re, w\u00e4hrend die Ausstattung hohen Anspr\u00fcchen gerecht wird. Ideal f\u00fcr Familien oder Paare, die eine Pause vom Alltag suchen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Ferienhaus Cr\u00e4mer in Wassenberg bietet eine komfortable Unterkunft, die sich durch ihre idyllische Lage und modernen Annehmlichkeiten auszeichnet. Gelegen im Landkreis Heinsberg, l\u00e4dt das Ferienhaus dazu ein, die umliegende Natur zu entdecken und zahlreiche Freizeitm\u00f6glichkeiten zu nutzen. Die stilvoll eingerichteten R\u00e4ume sorgen f\u00fcr eine erholsame Atmosph\u00e4re, w\u00e4hrend die Ausstattung hohen Anspr\u00fcchen gerecht wird. Ideal [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","accommodation_types":[139],"class_list":["post-130200","host","type-host","status-publish","hentry","accommodation_type-ferienhaus"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ferienhaus Cr\u00e4mer - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-craemer\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ferienhaus Cr\u00e4mer - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Das Ferienhaus Cr\u00e4mer in Wassenberg bietet eine komfortable Unterkunft, die sich durch ihre idyllische Lage und modernen Annehmlichkeiten auszeichnet. Gelegen im Landkreis Heinsberg, l\u00e4dt das Ferienhaus dazu ein, die umliegende Natur zu entdecken und zahlreiche Freizeitm\u00f6glichkeiten zu nutzen. Die stilvoll eingerichteten R\u00e4ume sorgen f\u00fcr eine erholsame Atmosph\u00e4re, w\u00e4hrend die Ausstattung hohen Anspr\u00fcchen gerecht wird. Ideal [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-craemer\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-craemer\/\",\"name\":\"Ferienhaus Cr\u00e4mer - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-05-11T01:25:19+00:00\",\"dateModified\":\"2026-05-11T01:25:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-craemer\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-craemer\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-craemer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gastgeber\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ferienhaus Cr\u00e4mer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ferienhaus Cr\u00e4mer - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-craemer\/","og_locale":"nl_NL","og_type":"article","og_title":"Ferienhaus Cr\u00e4mer - Stadt. Land. Niederrhein","og_description":"Das Ferienhaus Cr\u00e4mer in Wassenberg bietet eine komfortable Unterkunft, die sich durch ihre idyllische Lage und modernen Annehmlichkeiten auszeichnet. Gelegen im Landkreis Heinsberg, l\u00e4dt das Ferienhaus dazu ein, die umliegende Natur zu entdecken und zahlreiche Freizeitm\u00f6glichkeiten zu nutzen. Die stilvoll eingerichteten R\u00e4ume sorgen f\u00fcr eine erholsame Atmosph\u00e4re, w\u00e4hrend die Ausstattung hohen Anspr\u00fcchen gerecht wird. Ideal [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-craemer\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-craemer\/","name":"Ferienhaus Cr\u00e4mer - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-05-11T01:25:19+00:00","dateModified":"2026-05-11T01:25:19+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-craemer\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-craemer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/ferienhaus-craemer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Gastgeber","item":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/"},{"@type":"ListItem","position":3,"name":"Ferienhaus Cr\u00e4mer"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts\/130200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/host"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts\/130200\/revisions"}],"predecessor-version":[{"id":130642,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts\/130200\/revisions\/130642"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=130200"}],"wp:term":[{"taxonomy":"accommodation_type","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/accommodation_types?post=130200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}