{"id":136531,"date":"2026-08-29T03:55:19","date_gmt":"2026-08-29T01:55:19","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/gastgeber\/luxury-residence-duesseldorf-meerbusch-fuer-1-6-personen-10-minuten-zum-airport-oder-messe-15-minuten-zur-koenigsallee\/"},"modified":"2026-08-29T03:55:19","modified_gmt":"2026-08-29T01:55:19","slug":"luxury-residence-duesseldorf-meerbusch-fuer-1-6-personen-10-minuten-zum-airport-oder-messe-15-minuten-zur-koenigsallee","status":"publish","type":"host","link":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/luxury-residence-duesseldorf-meerbusch-fuer-1-6-personen-10-minuten-zum-airport-oder-messe-15-minuten-zur-koenigsallee\/","title":{"rendered":"Luxury Residence D\u00fcsseldorf-Meerbusch f\u00fcr 1-6 Personen, 10 Minuten zum Airport oder Messe, 15 Minuten zur K\u00f6nigsallee"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":0,"template":"","accommodation_types":[138],"class_list":["post-136531","host","type-host","status-publish","hentry","accommodation_type-ferienwohnung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Luxury Residence D\u00fcsseldorf-Meerbusch f\u00fcr 1-6 Personen, 10 Minuten zum Airport oder Messe, 15 Minuten zur K\u00f6nigsallee - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/luxury-residence-duesseldorf-meerbusch-fuer-1-6-personen-10-minuten-zum-airport-oder-messe-15-minuten-zur-koenigsallee\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luxury Residence D\u00fcsseldorf-Meerbusch f\u00fcr 1-6 Personen, 10 Minuten zum Airport oder Messe, 15 Minuten zur K\u00f6nigsallee - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/luxury-residence-duesseldorf-meerbusch-fuer-1-6-personen-10-minuten-zum-airport-oder-messe-15-minuten-zur-koenigsallee\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/luxury-residence-duesseldorf-meerbusch-fuer-1-6-personen-10-minuten-zum-airport-oder-messe-15-minuten-zur-koenigsallee\/\",\"name\":\"Luxury Residence D\u00fcsseldorf-Meerbusch f\u00fcr 1-6 Personen, 10 Minuten zum Airport oder Messe, 15 Minuten zur K\u00f6nigsallee - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-08-29T01:55:19+00:00\",\"dateModified\":\"2026-08-29T01:55:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/luxury-residence-duesseldorf-meerbusch-fuer-1-6-personen-10-minuten-zum-airport-oder-messe-15-minuten-zur-koenigsallee\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/luxury-residence-duesseldorf-meerbusch-fuer-1-6-personen-10-minuten-zum-airport-oder-messe-15-minuten-zur-koenigsallee\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/luxury-residence-duesseldorf-meerbusch-fuer-1-6-personen-10-minuten-zum-airport-oder-messe-15-minuten-zur-koenigsallee\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gastgeber\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Luxury Residence D\u00fcsseldorf-Meerbusch f\u00fcr 1-6 Personen, 10 Minuten zum Airport oder Messe, 15 Minuten zur K\u00f6nigsallee\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luxury Residence D\u00fcsseldorf-Meerbusch f\u00fcr 1-6 Personen, 10 Minuten zum Airport oder Messe, 15 Minuten zur K\u00f6nigsallee - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/luxury-residence-duesseldorf-meerbusch-fuer-1-6-personen-10-minuten-zum-airport-oder-messe-15-minuten-zur-koenigsallee\/","og_locale":"nl_NL","og_type":"article","og_title":"Luxury Residence D\u00fcsseldorf-Meerbusch f\u00fcr 1-6 Personen, 10 Minuten zum Airport oder Messe, 15 Minuten zur K\u00f6nigsallee - Stadt. Land. Niederrhein","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/luxury-residence-duesseldorf-meerbusch-fuer-1-6-personen-10-minuten-zum-airport-oder-messe-15-minuten-zur-koenigsallee\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/luxury-residence-duesseldorf-meerbusch-fuer-1-6-personen-10-minuten-zum-airport-oder-messe-15-minuten-zur-koenigsallee\/","name":"Luxury Residence D\u00fcsseldorf-Meerbusch f\u00fcr 1-6 Personen, 10 Minuten zum Airport oder Messe, 15 Minuten zur K\u00f6nigsallee - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-08-29T01:55:19+00:00","dateModified":"2026-08-29T01:55:19+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/luxury-residence-duesseldorf-meerbusch-fuer-1-6-personen-10-minuten-zum-airport-oder-messe-15-minuten-zur-koenigsallee\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/luxury-residence-duesseldorf-meerbusch-fuer-1-6-personen-10-minuten-zum-airport-oder-messe-15-minuten-zur-koenigsallee\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/luxury-residence-duesseldorf-meerbusch-fuer-1-6-personen-10-minuten-zum-airport-oder-messe-15-minuten-zur-koenigsallee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Gastgeber","item":"https:\/\/stadt-land-niederrhein.de\/nl\/gastgeber\/"},{"@type":"ListItem","position":3,"name":"Luxury Residence D\u00fcsseldorf-Meerbusch f\u00fcr 1-6 Personen, 10 Minuten zum Airport oder Messe, 15 Minuten zur K\u00f6nigsallee"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts\/136531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/host"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts\/136531\/revisions"}],"predecessor-version":[{"id":138722,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/hosts\/136531\/revisions\/138722"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=136531"}],"wp:term":[{"taxonomy":"accommodation_type","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/accommodation_types?post=136531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}