{"id":127564,"date":"2026-05-11T03:22:23","date_gmt":"2026-05-11T01:22:23","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/steintor\/"},"modified":"2026-05-11T03:22:23","modified_gmt":"2026-05-11T01:22:23","slug":"steintor","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/steintor\/","title":{"rendered":"Steintor"},"content":{"rendered":"<p>Das Steintor in Goch, erstmals 1458 erw\u00e4hnt, ist ein bedeutendes historisches Bauwerk, das vermutlich noch zur Befestigung des 14. Jahrhunderts geh\u00f6rt. Nach einem teilweisen Einsturz 1919 wurde es umfassend restauriert. Im Zweiten Weltkrieg erlitten die D\u00e4cher des Mittelbaus und des westlichen Turms schwere Sch\u00e4den, ebenso wie die Torgew\u00e4nde und das Mauerwerk. Heute dient das Steintor als Heimatmuseum und beeindruckt durch seine architektonischen Merkmale. Der l\u00e4ngsrechteckige Mittelteil umfasst drei Geschosse, die \u00fcber eine spitzbogige, tonnengew\u00f6lbte Durchfahrt zug\u00e4nglich sind. An der Feldseite flankieren zwei Rundt\u00fcrme das Bauwerk, deren Obergeschosse \u00fcber Pendentifs ins Zehneck \u00fcbergehen. Die spitzen Schieferd\u00e4cher und der erneuerte Zinnenkranz verleihen dem Bauwerk seine markante Silhouette. An der Standseite des Mittelbaus befinden sich sechseckige Eckwarten. \u00dcber der feldw\u00e4rts gelegenen Tor\u00f6ffnung sind drei nasenbesetzte Spitzbogenblenden aus Haustein zu sehen, die die Sandsteinfigur des heiligen Georg zwischen dem Gocher und dem preu\u00dfischen Wappen beherbergen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Steintor in Goch, erstmals 1458 erw\u00e4hnt, ist ein bedeutendes historisches Bauwerk, das vermutlich noch zur Befestigung des 14. Jahrhunderts geh\u00f6rt. Nach einem teilweisen Einsturz 1919 wurde es umfassend restauriert. Im Zweiten Weltkrieg erlitten die D\u00e4cher des Mittelbaus und des westlichen Turms schwere Sch\u00e4den, ebenso wie die Torgew\u00e4nde und das Mauerwerk. Heute dient das Steintor [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","destinations":[235,170],"class_list":["post-127564","poi","type-poi","status-publish","hentry","destination-historische-orte","destination-museen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Steintor - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/steintor\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Steintor - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Das Steintor in Goch, erstmals 1458 erw\u00e4hnt, ist ein bedeutendes historisches Bauwerk, das vermutlich noch zur Befestigung des 14. Jahrhunderts geh\u00f6rt. Nach einem teilweisen Einsturz 1919 wurde es umfassend restauriert. Im Zweiten Weltkrieg erlitten die D\u00e4cher des Mittelbaus und des westlichen Turms schwere Sch\u00e4den, ebenso wie die Torgew\u00e4nde und das Mauerwerk. Heute dient das Steintor [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/steintor\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/steintor\/\",\"name\":\"Steintor - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-05-11T01:22:23+00:00\",\"dateModified\":\"2026-05-11T01:22:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/steintor\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/steintor\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/steintor\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cultuur\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Steintor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Steintor - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/steintor\/","og_locale":"nl_NL","og_type":"article","og_title":"Steintor - Stadt. Land. Niederrhein","og_description":"Das Steintor in Goch, erstmals 1458 erw\u00e4hnt, ist ein bedeutendes historisches Bauwerk, das vermutlich noch zur Befestigung des 14. Jahrhunderts geh\u00f6rt. Nach einem teilweisen Einsturz 1919 wurde es umfassend restauriert. Im Zweiten Weltkrieg erlitten die D\u00e4cher des Mittelbaus und des westlichen Turms schwere Sch\u00e4den, ebenso wie die Torgew\u00e4nde und das Mauerwerk. Heute dient das Steintor [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/steintor\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/steintor\/","name":"Steintor - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-05-11T01:22:23+00:00","dateModified":"2026-05-11T01:22:23+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/steintor\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/steintor\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/steintor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Cultuur","item":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/"},{"@type":"ListItem","position":3,"name":"Steintor"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/127564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/127564\/revisions"}],"predecessor-version":[{"id":127579,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/127564\/revisions\/127579"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=127564"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/destinations?post=127564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}