{"id":130881,"date":"2026-05-13T01:10:12","date_gmt":"2026-05-12T23:10:12","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/auf-den-spuren-der-boxteler-bahn\/"},"modified":"2026-05-13T01:10:12","modified_gmt":"2026-05-12T23:10:12","slug":"auf-den-spuren-der-boxteler-bahn","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/auf-den-spuren-der-boxteler-bahn\/","title":{"rendered":"Auf den Spuren der Boxteler Bahn"},"content":{"rendered":"<p>Die Tour \u201eAuf den Spuren der Boxteler Bahn\u201c bietet eine faszinierende Reise in die Eisenbahngeschichte des Niederrheins. Diese Radroute, bekannt als \u201eDuits Lijntje\u201c, erstreckt sich \u00fcber fast 160 Kilometer von Wesel bis ins niederl\u00e4ndische Boxtel. Zwischen 1873 und dem 20. Jahrhundert war die Strecke ein bedeutender Teil der schnellsten Ost-West-Verbindung von London \u00fcber Berlin bis nach St. Petersburg. Ihre Bedeutung wurde durch die Nutzung durch europ\u00e4ische K\u00f6nigsh\u00e4user und die russische Zarenfamilie unterstrichen. Entlang der Route informieren Tafeln \u00fcber die bewegte Geschichte dieser legend\u00e4ren Bahnverbindung und machen die Tour zu einem lehrreichen Erlebnis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Route &#8220;Auf den Spuren der Boxteler Bahn&#8221; am Niederrhein erm\u00f6glicht eine detaillierte Auseinandersetzung mit der ehemaligen Eisenbahnstrecke, die einst London mit St. Petersburg verband. Dieser historische Radweg, auch als &#8220;Duits Lijntje&#8221; bekannt, stellt eine pr\u00e4gnante Darstellung regionaler Infrastrukturgeschichte dar, die durch Informationstafeln lebendig vermittelt wird.<\/p>\n","protected":false},"author":0,"featured_media":100442,"template":"","destinations":[235],"class_list":["post-130881","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-historische-orte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Auf den Spuren der Boxteler Bahn - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/auf-den-spuren-der-boxteler-bahn\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auf den Spuren der Boxteler Bahn - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Die Route &quot;Auf den Spuren der Boxteler Bahn&quot; am Niederrhein erm\u00f6glicht eine detaillierte Auseinandersetzung mit der ehemaligen Eisenbahnstrecke, die einst London mit St. Petersburg verband. Dieser historische Radweg, auch als &quot;Duits Lijntje&quot; bekannt, stellt eine pr\u00e4gnante Darstellung regionaler Infrastrukturgeschichte dar, die durch Informationstafeln lebendig vermittelt wird.\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/wesel-eaw-boxtelerbahn-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/auf-den-spuren-der-boxteler-bahn\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/auf-den-spuren-der-boxteler-bahn\/\",\"name\":\"Auf den Spuren der Boxteler Bahn - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-05-12T23:10:12+00:00\",\"dateModified\":\"2026-05-12T23:10:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/auf-den-spuren-der-boxteler-bahn\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/auf-den-spuren-der-boxteler-bahn\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/auf-den-spuren-der-boxteler-bahn\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cultuur\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Auf den Spuren der Boxteler Bahn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Auf den Spuren der Boxteler Bahn - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/auf-den-spuren-der-boxteler-bahn\/","og_locale":"nl_NL","og_type":"article","og_title":"Auf den Spuren der Boxteler Bahn - Stadt. Land. Niederrhein","og_description":"Die Route \"Auf den Spuren der Boxteler Bahn\" am Niederrhein erm\u00f6glicht eine detaillierte Auseinandersetzung mit der ehemaligen Eisenbahnstrecke, die einst London mit St. Petersburg verband. Dieser historische Radweg, auch als \"Duits Lijntje\" bekannt, stellt eine pr\u00e4gnante Darstellung regionaler Infrastrukturgeschichte dar, die durch Informationstafeln lebendig vermittelt wird.","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":800,"height":600,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/wesel-eaw-boxtelerbahn-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/auf-den-spuren-der-boxteler-bahn\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/auf-den-spuren-der-boxteler-bahn\/","name":"Auf den Spuren der Boxteler Bahn - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-05-12T23:10:12+00:00","dateModified":"2026-05-12T23:10:12+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/auf-den-spuren-der-boxteler-bahn\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/auf-den-spuren-der-boxteler-bahn\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/auf-den-spuren-der-boxteler-bahn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Cultuur","item":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/"},{"@type":"ListItem","position":3,"name":"Auf den Spuren der Boxteler Bahn"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/130881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/130881\/revisions"}],"predecessor-version":[{"id":131078,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/130881\/revisions\/131078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media\/100442"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=130881"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/destinations?post=130881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}