{"id":131038,"date":"2026-05-12T02:18:38","date_gmt":"2026-05-12T00:18:38","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/skulptur-der-sonnenfaenger\/"},"modified":"2026-05-12T02:18:38","modified_gmt":"2026-05-12T00:18:38","slug":"skulptur-der-sonnenfaenger","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/skulptur-der-sonnenfaenger\/","title":{"rendered":"Skulptur &#8220;Der Sonnenf\u00e4nger&#8221;"},"content":{"rendered":"<p>Riesige alpine Granitfindlinge aus dem \u00d6tztal schaffen eine Verbindung zwischen der Erftm\u00fcndung im Neusser Stadtteil Gnadental und dem Museum Insel Hombroich. Der Bildhauer Anatol Herzfeld, der viele Jahre in seinem Atelier auf der Insel Hombroich t\u00e4tig war und 2019 in Moers verstarb, gestaltete aus diesen Steinen archaisch anmutende Gesichter, die in Form und Material an arch\u00e4ologische Funde erinnern. Diese Skulpturen sind Teil des EUROGA-Projekts \u201eKunstwege nach D\u00fcsseldorf\u201c. Die EUROGA 2002plus, die zweite Regionale des Landes Nordrhein-Westfalen, bietet ein umfassendes Kultur- und Naturerlebnis entlang von Rhein und Maas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Riesige alpine Granitfindlinge aus dem \u00d6tztal schaffen eine Verbindung zwischen der Erftm\u00fcndung im Neusser Stadtteil Gnadental und dem Museum Insel Hombroich. Der Bildhauer Anatol Herzfeld, der viele Jahre in seinem Atelier auf der Insel Hombroich t\u00e4tig war und 2019 in Moers verstarb, gestaltete aus diesen Steinen archaisch anmutende Gesichter, die in Form und Material an [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":100022,"template":"","destinations":[235],"class_list":["post-131038","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-historische-orte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Skulptur &quot;Der Sonnenf\u00e4nger&quot; - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/skulptur-der-sonnenfaenger\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Skulptur &quot;Der Sonnenf\u00e4nger&quot; - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Riesige alpine Granitfindlinge aus dem \u00d6tztal schaffen eine Verbindung zwischen der Erftm\u00fcndung im Neusser Stadtteil Gnadental und dem Museum Insel Hombroich. Der Bildhauer Anatol Herzfeld, der viele Jahre in seinem Atelier auf der Insel Hombroich t\u00e4tig war und 2019 in Moers verstarb, gestaltete aus diesen Steinen archaisch anmutende Gesichter, die in Form und Material an [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/skulptur-der-sonnenf-nger-von-anatol-herzfeld.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1363\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/skulptur-der-sonnenfaenger\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/skulptur-der-sonnenfaenger\/\",\"name\":\"Skulptur \\\"Der Sonnenf\u00e4nger\\\" - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-05-12T00:18:38+00:00\",\"dateModified\":\"2026-05-12T00:18:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/skulptur-der-sonnenfaenger\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/skulptur-der-sonnenfaenger\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/skulptur-der-sonnenfaenger\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cultuur\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Skulptur \\\"Der Sonnenf\u00e4nger\\\"\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Skulptur \"Der Sonnenf\u00e4nger\" - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/skulptur-der-sonnenfaenger\/","og_locale":"nl_NL","og_type":"article","og_title":"Skulptur \"Der Sonnenf\u00e4nger\" - Stadt. Land. Niederrhein","og_description":"Riesige alpine Granitfindlinge aus dem \u00d6tztal schaffen eine Verbindung zwischen der Erftm\u00fcndung im Neusser Stadtteil Gnadental und dem Museum Insel Hombroich. Der Bildhauer Anatol Herzfeld, der viele Jahre in seinem Atelier auf der Insel Hombroich t\u00e4tig war und 2019 in Moers verstarb, gestaltete aus diesen Steinen archaisch anmutende Gesichter, die in Form und Material an [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2048,"height":1363,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2025\/02\/skulptur-der-sonnenf-nger-von-anatol-herzfeld.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/skulptur-der-sonnenfaenger\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/skulptur-der-sonnenfaenger\/","name":"Skulptur \"Der Sonnenf\u00e4nger\" - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-05-12T00:18:38+00:00","dateModified":"2026-05-12T00:18:38+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/skulptur-der-sonnenfaenger\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/skulptur-der-sonnenfaenger\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/skulptur-der-sonnenfaenger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Cultuur","item":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/"},{"@type":"ListItem","position":3,"name":"Skulptur \"Der Sonnenf\u00e4nger\""}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/131038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/131038\/revisions"}],"predecessor-version":[{"id":131231,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/131038\/revisions\/131231"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media\/100022"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=131038"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/destinations?post=131038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}