{"id":131677,"date":"2026-09-02T01:47:02","date_gmt":"2026-09-01T23:47:02","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/theater-am-schlachthof\/"},"modified":"2026-09-02T01:47:02","modified_gmt":"2026-09-01T23:47:02","slug":"theater-am-schlachthof","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/theater-am-schlachthof\/","title":{"rendered":"Theater am Schlachthof"},"content":{"rendered":"<p>Das Theater am Schlachthof ist das gr\u00f6\u00dfte freie Theater der Region und befindet sich im zentral gelegenen Barbaraviertel von Neuss. Seit seiner Gr\u00fcndung im Jahr 1994 bietet es auf zwei B\u00fchnen mit 70 und 100 Sitzpl\u00e4tzen ein breites Spektrum an Eigenproduktionen und Gastspielen. Die freie Platzwahl in den S\u00e4len garantiert eine gute Sicht auf die B\u00fchne. Das vielf\u00e4ltige Programm umfasst Kindertheater, Schauspiel und Kabarett. Besonders hervorzuheben ist die j\u00e4hrliche Kabarettshow STUNK zur Karnevalszeit. Mit rund 25.000 Besucher:innen j\u00e4hrlich und fast 200 Veranstaltungen ist das Theater weit \u00fcber die Stadtgrenzen hinaus bekannt. Es bietet nicht nur hochwertige Unterhaltung, sondern fungiert auch als soziokulturelles Zentrum mit theaterp\u00e4dagogischen Angeboten f\u00fcr Kinder, Jugendliche und Senior:innen. Das einladende Theaterfoyer \u00f6ffnet vor den Veranstaltungen und bietet die M\u00f6glichkeit, sich bei einem Getr\u00e4nk auf die Auff\u00fchrung einzustimmen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Theater am Schlachthof ist das gr\u00f6\u00dfte freie Theater der Region und befindet sich im zentral gelegenen Barbaraviertel von Neuss. Seit seiner Gr\u00fcndung im Jahr 1994 bietet es auf zwei B\u00fchnen mit 70 und 100 Sitzpl\u00e4tzen ein breites Spektrum an Eigenproduktionen und Gastspielen. Die freie Platzwahl in den S\u00e4len garantiert eine gute Sicht auf die [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":47628,"template":"","destinations":[246],"class_list":["post-131677","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-theater-co"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Theater am Schlachthof - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/theater-am-schlachthof\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Theater am Schlachthof - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Das Theater am Schlachthof ist das gr\u00f6\u00dfte freie Theater der Region und befindet sich im zentral gelegenen Barbaraviertel von Neuss. Seit seiner Gr\u00fcndung im Jahr 1994 bietet es auf zwei B\u00fchnen mit 70 und 100 Sitzpl\u00e4tzen ein breites Spektrum an Eigenproduktionen und Gastspielen. Die freie Platzwahl in den S\u00e4len garantiert eine gute Sicht auf die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2023\/03\/theater-am-schlachthof-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/theater-am-schlachthof\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/theater-am-schlachthof\/\",\"name\":\"Theater am Schlachthof - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-09-01T23:47:02+00:00\",\"dateModified\":\"2026-09-01T23:47:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/theater-am-schlachthof\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/theater-am-schlachthof\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/theater-am-schlachthof\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cultuur\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Theater am Schlachthof\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Theater am Schlachthof - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/theater-am-schlachthof\/","og_locale":"nl_NL","og_type":"article","og_title":"Theater am Schlachthof - Stadt. Land. Niederrhein","og_description":"Das Theater am Schlachthof ist das gr\u00f6\u00dfte freie Theater der Region und befindet sich im zentral gelegenen Barbaraviertel von Neuss. Seit seiner Gr\u00fcndung im Jahr 1994 bietet es auf zwei B\u00fchnen mit 70 und 100 Sitzpl\u00e4tzen ein breites Spektrum an Eigenproduktionen und Gastspielen. Die freie Platzwahl in den S\u00e4len garantiert eine gute Sicht auf die [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2560,"height":1707,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2023\/03\/theater-am-schlachthof-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/theater-am-schlachthof\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/theater-am-schlachthof\/","name":"Theater am Schlachthof - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-09-01T23:47:02+00:00","dateModified":"2026-09-01T23:47:02+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/theater-am-schlachthof\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/theater-am-schlachthof\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/theater-am-schlachthof\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Cultuur","item":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/"},{"@type":"ListItem","position":3,"name":"Theater am Schlachthof"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/131677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/131677\/revisions"}],"predecessor-version":[{"id":131756,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/131677\/revisions\/131756"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media\/47628"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=131677"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/destinations?post=131677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}