{"id":131678,"date":"2026-09-02T01:29:57","date_gmt":"2026-09-01T23:29:57","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/romaneum\/"},"modified":"2026-09-02T01:29:57","modified_gmt":"2026-09-01T23:29:57","slug":"romaneum","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/romaneum\/","title":{"rendered":"RomaNEum"},"content":{"rendered":"<p>Um die Mitte des 1. Jahrhunderts nach Christus entstand entlang der r\u00f6mischen Fernstra\u00dfe von K\u00f6ln nach Xanten eine r\u00f6mische Zivilsiedlung, bekannt als Vicus. Diese Siedlung lag zwischen dem heutigen Obertor und dem B\u00fcchel auf einer hochwassergesch\u00fctzten Sandd\u00fcne. Hier lebten H\u00e4ndler, Handwerker und die Familien von Soldaten, die im nahegelegenen Legionslager stationiert waren. Bei Ausgrabungen zwischen 2002 und 2010 wurden Spuren dieser fr\u00fchen Siedlung entdeckt, darunter Wandlehmfragmente und Fundamentreste aus Rheinkieseln und Tuffsteinen. Ein massives r\u00f6misches Geb\u00e4ude, dessen Eckfundamente bis knapp f\u00fcnf Meter unter die heutige Oberfl\u00e4che reichen, ist teilweise im Innern des Romaneums sichtbar. Im 3. Jahrhundert wurde dieses Geb\u00e4ude abgerissen und durch ein repr\u00e4sentatives Gro\u00dfgeb\u00e4ude ersetzt, das vermutlich als Stra\u00dfenstation f\u00fcr reisende Amtspersonen diente. Diese Mansio lag direkt am r\u00f6mischen Rheinufer und bot auch Schiffsreisenden Unterkunft. Unter der Geb\u00e4udesohle fanden sich Reste einer Kanalheizung, die sowohl Fu\u00dfb\u00f6den als auch W\u00e4nde beheizte. Ende des 4. Jahrhunderts wurden der Vicus und die Mansio aufgegeben, ihre Mauern verfielen und wurden von der Vegetation \u00fcberwuchert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um die Mitte des 1. Jahrhunderts nach Christus entstand entlang der r\u00f6mischen Fernstra\u00dfe von K\u00f6ln nach Xanten eine r\u00f6mische Zivilsiedlung, bekannt als Vicus. Diese Siedlung lag zwischen dem heutigen Obertor und dem B\u00fcchel auf einer hochwassergesch\u00fctzten Sandd\u00fcne. Hier lebten H\u00e4ndler, Handwerker und die Familien von Soldaten, die im nahegelegenen Legionslager stationiert waren. Bei Ausgrabungen zwischen [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":7874,"template":"","destinations":[170],"class_list":["post-131678","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-museen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>RomaNEum - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/romaneum\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RomaNEum - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Um die Mitte des 1. Jahrhunderts nach Christus entstand entlang der r\u00f6mischen Fernstra\u00dfe von K\u00f6ln nach Xanten eine r\u00f6mische Zivilsiedlung, bekannt als Vicus. Diese Siedlung lag zwischen dem heutigen Obertor und dem B\u00fcchel auf einer hochwassergesch\u00fctzten Sandd\u00fcne. Hier lebten H\u00e4ndler, Handwerker und die Familien von Soldaten, die im nahegelegenen Legionslager stationiert waren. Bei Ausgrabungen zwischen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/08\/ausgrabungen-im-romaneum-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/romaneum\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/romaneum\/\",\"name\":\"RomaNEum - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-09-01T23:29:57+00:00\",\"dateModified\":\"2026-09-01T23:29:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/romaneum\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/romaneum\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/romaneum\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cultuur\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"RomaNEum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RomaNEum - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/romaneum\/","og_locale":"nl_NL","og_type":"article","og_title":"RomaNEum - Stadt. Land. Niederrhein","og_description":"Um die Mitte des 1. Jahrhunderts nach Christus entstand entlang der r\u00f6mischen Fernstra\u00dfe von K\u00f6ln nach Xanten eine r\u00f6mische Zivilsiedlung, bekannt als Vicus. Diese Siedlung lag zwischen dem heutigen Obertor und dem B\u00fcchel auf einer hochwassergesch\u00fctzten Sandd\u00fcne. Hier lebten H\u00e4ndler, Handwerker und die Familien von Soldaten, die im nahegelegenen Legionslager stationiert waren. Bei Ausgrabungen zwischen [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":1707,"height":2560,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/08\/ausgrabungen-im-romaneum-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/romaneum\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/romaneum\/","name":"RomaNEum - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-09-01T23:29:57+00:00","dateModified":"2026-09-01T23:29:57+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/romaneum\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/romaneum\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/romaneum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Cultuur","item":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/"},{"@type":"ListItem","position":3,"name":"RomaNEum"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/131678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/131678\/revisions"}],"predecessor-version":[{"id":131757,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/131678\/revisions\/131757"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media\/7874"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=131678"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/destinations?post=131678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}