{"id":131683,"date":"2026-05-13T01:07:01","date_gmt":"2026-05-12T23:07:01","guid":{"rendered":"https:\/\/stadt-land-niederrhein.de\/kultur\/kloster-knechtsteden\/"},"modified":"2026-05-13T01:07:01","modified_gmt":"2026-05-12T23:07:01","slug":"kloster-knechtsteden","status":"publish","type":"poi","link":"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/kloster-knechtsteden\/","title":{"rendered":"Kloster Knechtsteden"},"content":{"rendered":"<p>Die weitl\u00e4ufige Anlage des Klosters Knechtsteden hat sich zu einem modernen Bildungs-, Kultur- und Veranstaltungszentrum entwickelt. In den \u00fcber 100 Jahre alten Werkst\u00e4tten und der imposanten Bibliothek er\u00f6ffnen sich beeindruckende Einblicke in die kl\u00f6sterliche Vergangenheit. Das Kloster, eine ehemalige Pr\u00e4monstratenserabtei aus dem fr\u00fchen 12. Jahrhundert, befindet sich heute im Besitz des Spiritanerordens. Auf dem Gel\u00e4nde steht eine romanische Gew\u00f6lbebasilika, erbaut zwischen 1138 und 1162 aus Tuffstein. In der Westapsis der Basilika ist ein monumentales Fresko aus dem Jahr 1160 zu sehen, das Christus als Weltenherrscher darstellt. Nach Besch\u00e4digungen w\u00e4hrend der Neusser Fehde 1474 wurde die Ostapsis 1477 im gotischen Stil erneuert. Die heutige Innengestalt erhielt die Basilika durch Restaurierungen in den Jahren 1962 bis 1964. Aufgrund ihrer kunstgeschichtlichen Bedeutung und Tradition als Wallfahrtsort erhielt die Basilika 1974 den p\u00e4pstlichen Titel \u201eBasilika minor\u201c. Die Klosteranlage beherbergt das Norbert-Gymnasium, ein katholisches Internat, sowie den Kulturhof Knechtsteden, der f\u00fcr Trauungen, Galaabende und klassische Musikveranstaltungen genutzt wird. Auf drei Wanderrouten lassen sich \u00fcber 300 Obstb\u00e4ume und 120 Obstsorten entdecken, w\u00e4hrend die Biologische Station im Haus der Natur Wissen zu Natur-, Arten- und Umweltschutz vermittelt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die weitl\u00e4ufige Anlage des Klosters Knechtsteden hat sich zu einem modernen Bildungs-, Kultur- und Veranstaltungszentrum entwickelt. In den \u00fcber 100 Jahre alten Werkst\u00e4tten und der imposanten Bibliothek er\u00f6ffnen sich beeindruckende Einblicke in die kl\u00f6sterliche Vergangenheit. Das Kloster, eine ehemalige Pr\u00e4monstratenserabtei aus dem fr\u00fchen 12. Jahrhundert, befindet sich heute im Besitz des Spiritanerordens. Auf dem Gel\u00e4nde [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":8015,"template":"","destinations":[242],"class_list":["post-131683","poi","type-poi","status-publish","has-post-thumbnail","hentry","destination-kirchen-kloester"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kloster Knechtsteden - Stadt. Land. Niederrhein<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/kloster-knechtsteden\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kloster Knechtsteden - Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:description\" content=\"Die weitl\u00e4ufige Anlage des Klosters Knechtsteden hat sich zu einem modernen Bildungs-, Kultur- und Veranstaltungszentrum entwickelt. In den \u00fcber 100 Jahre alten Werkst\u00e4tten und der imposanten Bibliothek er\u00f6ffnen sich beeindruckende Einblicke in die kl\u00f6sterliche Vergangenheit. Das Kloster, eine ehemalige Pr\u00e4monstratenserabtei aus dem fr\u00fchen 12. Jahrhundert, befindet sich heute im Besitz des Spiritanerordens. Auf dem Gel\u00e4nde [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"\/\" \/>\n<meta property=\"og:site_name\" content=\"Stadt. Land. Niederrhein\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/08\/p-rchen-an-der-basilika-des-kloster-knechtsteden-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/kloster-knechtsteden\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/kloster-knechtsteden\/\",\"name\":\"Kloster Knechtsteden - Stadt. Land. Niederrhein\",\"isPartOf\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\"},\"datePublished\":\"2026-05-12T23:07:01+00:00\",\"dateModified\":\"2026-05-12T23:07:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/kloster-knechtsteden\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/kloster-knechtsteden\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/kloster-knechtsteden\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cultuur\",\"item\":\"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kloster Knechtsteden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#website\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"name\":\"Stadt. Land. Niederrhein\",\"description\":\"Niederrhein f\u00fcr alle Sinne\",\"publisher\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\"},\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#organization\",\"name\":\"Stadt. Land. Niederrhein\",\"alternateName\":\"Niederrhein f\u00fcr alle Sinne\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"contentUrl\":\"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png\",\"width\":400,\"height\":133,\"caption\":\"Stadt. Land. Niederrhein\"},\"image\":{\"@id\":\"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/niederrheintourismus_\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kloster Knechtsteden - Stadt. Land. Niederrhein","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/kloster-knechtsteden\/","og_locale":"nl_NL","og_type":"article","og_title":"Kloster Knechtsteden - Stadt. Land. Niederrhein","og_description":"Die weitl\u00e4ufige Anlage des Klosters Knechtsteden hat sich zu einem modernen Bildungs-, Kultur- und Veranstaltungszentrum entwickelt. In den \u00fcber 100 Jahre alten Werkst\u00e4tten und der imposanten Bibliothek er\u00f6ffnen sich beeindruckende Einblicke in die kl\u00f6sterliche Vergangenheit. Das Kloster, eine ehemalige Pr\u00e4monstratenserabtei aus dem fr\u00fchen 12. Jahrhundert, befindet sich heute im Besitz des Spiritanerordens. Auf dem Gel\u00e4nde [&hellip;]","og_url":"\/","og_site_name":"Stadt. Land. Niederrhein","og_image":[{"width":2560,"height":1707,"url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/08\/p-rchen-an-der-basilika-des-kloster-knechtsteden-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/kloster-knechtsteden\/","url":"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/kloster-knechtsteden\/","name":"Kloster Knechtsteden - Stadt. Land. Niederrhein","isPartOf":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website"},"datePublished":"2026-05-12T23:07:01+00:00","dateModified":"2026-05-12T23:07:01+00:00","breadcrumb":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/kloster-knechtsteden\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/kloster-knechtsteden\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/cultuur\/kloster-knechtsteden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/stadt-land-niederrhein.de\/nl\/"},{"@type":"ListItem","position":2,"name":"Cultuur","item":"https:\/\/stadt-land-niederrhein.de\/nl\/kultur\/"},{"@type":"ListItem","position":3,"name":"Kloster Knechtsteden"}]},{"@type":"WebSite","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#website","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","name":"Stadt. Land. Niederrhein","description":"Niederrhein f\u00fcr alle Sinne","publisher":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization"},"alternateName":"Niederrhein f\u00fcr alle Sinne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stadt-land-niederrhein.de\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#organization","name":"Stadt. Land. Niederrhein","alternateName":"Niederrhein f\u00fcr alle Sinne","url":"https:\/\/stadt-land-niederrhein.de\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","contentUrl":"https:\/\/stadt-land-niederrhein.de\/wp-content\/uploads\/2022\/09\/stadt-land-niederrhein_logo_block_400px.png","width":400,"height":133,"caption":"Stadt. Land. Niederrhein"},"image":{"@id":"https:\/\/stadt-land-niederrhein.de\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/niederrheintourismus_\/"]}]}},"_links":{"self":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/131683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois"}],"about":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/types\/poi"}],"version-history":[{"count":1,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/131683\/revisions"}],"predecessor-version":[{"id":131761,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/pois\/131683\/revisions\/131761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media\/8015"}],"wp:attachment":[{"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/media?parent=131683"}],"wp:term":[{"taxonomy":"destination","embeddable":true,"href":"https:\/\/stadt-land-niederrhein.de\/nl\/wp-json\/wp\/v2\/destinations?post=131683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}